{"id":1426,"date":"2023-10-16T08:05:54","date_gmt":"2023-10-16T08:05:54","guid":{"rendered":"https:\/\/dev.improof.lu\/?p=1426"},"modified":"2024-01-31T15:15:31","modified_gmt":"2024-01-31T15:15:31","slug":"extreme-ungleichheit-des-reichtums","status":"publish","type":"post","link":"https:\/\/dev.improof.lu\/de\/articles\/extreme-ungleichheit-des-reichtums\/","title":{"rendered":"Die extreme Ungleichheit der Verm\u00f6gen: Sprengstoff f\u00fcr unsere Gesellschaft"},"content":{"rendered":"<p>Sei es die wachsende Schere zwischen Arm und Reich, die Klimakrise oder die Wohnungsnot \u2013 viele der gesellschaftlichen Probleme, die uns besch\u00e4ftigen, lassen sich nicht in ihrer G\u00e4nze verstehen und l\u00f6sen, ohne sich mit Ungleichheiten zu befassen.<\/p>\n<p>Besondere Aufmerksamkeit m\u00fcsste dabei der Ungleichheit der Verm\u00f6gen und des Reichtums gewidmet werden, da sie andere Formen der Ungleichheit, einschlie\u00dflich der Einkommensungleichheit, verst\u00e4rkt.<\/p>\n<p>In sozialen Analysen ist sie allerdings viel seltener anzutreffen als etwa die ungleiche Verteilung der Einkommen. Zudem wird sie <a href=\"https:\/\/www.progressives-zentrum.org\/en\/wp-content\/uploads\/sites\/2\/2021\/05\/210521_UKZ_Policy_Paper_06_Bledow-Bellani_EN_web_RZ.pdf\" target=\"_blank\" rel=\"noopener\"><span style=\"text-decoration: underline;\"><em>von der Bev\u00f6lkerung untersch\u00e4tzt und gegen\u00fcber Einkommensungleichheit als kleiner empfunden<\/em><\/span><\/a>, obwohl sie in den meisten L\u00e4ndern deutlich ausgepr\u00e4gter ist.<\/p>\n<p>Auch in Luxemburg sind die Privatverm\u00f6gen sehr ungleich verteilt und bei wenigen Reichen konzentriert.<\/p>\n<p>Zur Veranschaulichung: Das durchschnittliche Jahreseinkommen der 10 % der einkommensst\u00e4rksten Haushalte ist fast 10-mal so hoch wie das der 10 % der Einkommensschw\u00e4chsten.<\/p>\n<p>Bei Verm\u00f6gen sieht das etwas anders aus. Die 10 % der Haushalte mit dem h\u00f6chsten Verm\u00f6gen besitzen durchschnittlich 1945-mal so viel wie die 10 % der \u00e4rmsten Haushalte, und immer noch 29-mal so viel wie insgesamt 50 % der Bev\u00f6lkerung am unteren Rand der Verm\u00f6gensverteilung.*<\/p>\n<p>Die reichsten 10 % der Haushalte besitzen 50 % des gesamten Privatverm\u00f6gens. Sie verf\u00fcgen somit \u00fcber das gleiche Verm\u00f6gen wie die \u00fcbrigen 90 % der Haushalte. Allein das oberste 1 % konzentriert 21 % des Gesamtverm\u00f6gens.<\/p>\n<p>In Geld ausgedr\u00fcckt, verf\u00fcgten im Jahr 2018 die 10 % der reichsten Haushalte durchschnittlich knapp 4,5 Millionen Euro, das reichste 1 % der Haushalte \u00fcber 180 Millionen Euro.<\/p>\n<p>Dar\u00fcber hinaus sind auch die verschiedenen Kategorien von Verm\u00f6gen und Reichtum, also Immobilien, Unternehmen, Finanzanlagen, usw., innerhalb der Bev\u00f6lkerung sehr ungleich verteilt.<\/p>\n<p>Mit Ausnahme des Hauptwohnsitzes <a href=\"https:\/\/www.csl.lu\/app\/uploads\/2023\/04\/csl_panorama_social_2023.pdf?fbclid=IwAR0RPCL3Y52NHC6BPe3sOcmxeeeckA9YL4n5RWYBoNHYNB8cHpQff7-s28E#page=26\" target=\"_blank\" rel=\"noopener\"><span style=\"text-decoration: underline;\"><em>befindet sich mehr als die H\u00e4lfte jeder Verm\u00f6genskategorie im Besitz von weniger als 10 % der Haushalte in Luxemburg<\/em><\/span><\/a>. Beispielsweise besitzen innerhalb der Gesamtbev\u00f6lkerung allein 10 % der Haushalte 84 % der Immobilien, die nicht als Hauptwohnsitz dienen. 10 % der Haushalte besitzen 97,8 % der Finanzanlagen.<\/p>\n<p>Die aktuelle Steuerpolitik tr\u00e4gt stark zu dieser extremen Ungleichheit bei: Im Jahr 2006 wurde die Verm\u00f6genssteuer abgeschafft. Die Besteuerung von Erbschaften in direkter Linie existiert nicht.<\/p>\n<p>Hinzu kommt, dass die Einnahmen, die durch Verm\u00f6gen\/Kapital generiert werden (beispielsweise Dividenden), gegen\u00fcber Arbeitseinkommen steuerlich beg\u00fcnstigt werden.<\/p>\n<p>Wir befinden uns also in folgender Situation: Wenn zwei Personen die gleiche H\u00f6he an Einkommen beziehen, aber ein Einkommen durch Arbeit und das andere durch Kapital erzielt wird, zahlt die Person, die ihr Einkommen aus Kapital bezieht, weniger Steuern als die Andere. Im Gegensatz zu Arbeitseinkommen flie\u00dfen diese Einnahmen zudem gr\u00f6\u00dftenteils in die H\u00e4nde der Reichsten, also einer winzigen Minderheit der Bev\u00f6lkerung.<\/p>\n<p>Das luxemburgische Steuersystem privilegiert somit ohnehin schon Verm\u00f6gende. Steuerbefreites Verm\u00f6gen generiert steuerbeg\u00fcnstigte Eink\u00fcnfte, die in neuen Verm\u00f6genserwerb reinvestiert werden k\u00f6nnen. Die Folge ist eine zunehmende Polarisierung der Gesellschaft.<\/p>\n<p>Dazu gesellen sich Erbschaften \u2013 sie verst\u00e4rken die bestehende Verm\u00f6gensungleichheit.<\/p>\n<p>Manche Politiker benutzen die Erbschaftssteuer als Kampfbegriff, um materielle \u00c4ngste der breiten Bev\u00f6lkerung zu befeuern: Die nette Oma von nebenan ackert ihr Leben lang und darf dann ihren Enkeln nichts weitergeben.<\/p>\n<p>Schaut man sich aber die reale Verteilung der Erbschaften an, erweckt sich der Eindruck, dass hier ein ideologischer Trick genutzt wird, der das Interesse einer wohlhabenden Minderheit zum Allgemeininteresse erkl\u00e4rt.<\/p>\n<p>Es w\u00e4re problemlos m\u00f6glich, einen Freibetrag zu finden, der garantiert, dass sich eine Erbschaftssteuer nicht auf kleinere und mittlere Erbschaften, also den \u201eDurchschnittsb\u00fcrger\u201c, auswirkt, sondern nur hohe bis sehr hohe Erbschaften besteuert werden. Problemlos deswegen, weil auch Erbschaften sehr ungleich verteilt sind.<\/p>\n<p>Im Jahr 2018 (letzte verf\u00fcgbare Daten) haben nur knapp 30 % der Bev\u00f6lkerung in Luxemburg tats\u00e4chlich geerbt. Dabei konzentrierten allein 10 % der ans\u00e4ssigen Haushalte fast 83 % des gesamten geerbten Verm\u00f6gens, inklusive Schenkungen. Und nur etwa 3 % der Gesamtbev\u00f6lkerung konzentrierten 53 % des gesamten Erbes in Luxemburg.<\/p>\n<p>Chancengleichheit und Leistungsgesellschaft sind in diesem Zusammenhang eher Mythos als Realit\u00e4t.<\/p>\n<p>Diese Tatsachen zeigen, dass politischer Handlungsbedarf bei der Bek\u00e4mpfung von Ungleichheiten besteht, nicht nur aus Gr\u00fcnden der Gerechtigkeit, sondern auch, weil sie, wie sogar schon <a href=\"https:\/\/www.oecd.org\/social\/Focus-Inequality-and-Growth-2014.pdf\" target=\"_blank\" rel=\"noopener\"><span style=\"text-decoration: underline;\"><em>die OECD<\/em><\/span><\/a> und <a href=\"https:\/\/www.imf.org\/en\/Blogs\/Articles\/2017\/02\/22\/the-imfs-work-on-inequality-bridging-research-and-reality\" target=\"_blank\" rel=\"noopener\"><span style=\"text-decoration: underline;\"><em>der IWF<\/em><\/span><\/a> feststellen mussten, <a href=\"https:\/\/www.sciencedirect.com\/science\/article\/abs\/pii\/S0264999318315967\" target=\"_blank\" rel=\"noopener\"><span style=\"text-decoration: underline;\"><em>sch\u00e4dlich f\u00fcr die Wirtschaft sind<\/em><\/span><\/a>. Eine gerechtere Verteilung des Reichtums <a href=\"https:\/\/www.oecd.org\/social\/in-it-together-why-less-inequality-benefits-all-9789264235120-en.htm\" target=\"_blank\" rel=\"noopener\"><span style=\"text-decoration: underline;\"><em>nutzt im Prinzip allen<\/em><\/span><\/a>.<\/p>\n<p>Und tats\u00e4chlich spricht sich <a href=\"https:\/\/infos.rtl.lu\/actu\/luxembourg\/a\/1995515.html\" target=\"_blank\" rel=\"noopener\"><span style=\"text-decoration: underline;\"><em>laut Politmonitor 2022<\/em><\/span><\/a> eine Mehrheit der Bev\u00f6lkerung f\u00fcr Ma\u00dfnahmen aus, damit weniger Wohlhabende mehr Geld behalten k\u00f6nnen und damit diejenigen, denen es finanziell besser geht, mehr zum Allgemeinwohl beitragen. Generell also f\u00fcr Ma\u00dfnahmen, die f\u00fcr mehr Steuergerechtigkeit sorgen sollen.<\/p>\n<p>Die Zeit ist reif f\u00fcr eine progressive Steuerpolitik, die auch die Besteuerung von Verm\u00f6gen beinhalten muss.<\/p>\n<p>Eine progressive Verm\u00f6gensteuer h\u00e4tte ein enormes soziales und wirtschaftliches Potenzial, gerade jetzt, da sich das Land zahlreichen Herausforderungen stellen muss (Immobilienkrise, \u00f6kologischer und demografischer Wandel, usw.).<\/p>\n<p>Sie w\u00e4re nicht nur n\u00fctzlich, um die Ungleichheit des Reichtums zu verringern, sie k\u00f6nnte auch einen erheblichen Teil der \u00f6ffentlichen Mittel generieren, die f\u00fcr die enormen Investitionen zur Bew\u00e4ltigung der vorher genannten Probleme erforderlich sind.<\/p>\n<p><a href=\"https:\/\/dev.improof.lu\/fr\/articles\/oculos-habent-et-non-vident\/\" target=\"_blank\" rel=\"noopener\"><span style=\"text-decoration: underline;\"><em>Laut einer 2021 ver\u00f6ffentlichten Studie der \u00d6konomen Kapeller, Leitch und Wildauer<\/em><\/span><\/a> h\u00e4tte eine progressive Verm\u00f6genssteuer, mit einer Progression von 2 bis 10 %, im Jahr 2018 dem Staat zus\u00e4tzlich etwa 3,9 Milliarden Euro einbringen k\u00f6nnen. Dieses Beispiel einer Verm\u00f6genssteuer setzt erst ab 2 Millionen Euro Privatverm\u00f6gen an. Mit diesem Freibetrag w\u00fcrde die Steuer nur 9 %, also weniger als 10 % der reichsten Haushalte in Luxemburg betreffen.<\/p>\n<p>Materielle und soziale Sicherheit f\u00fcr einen Gro\u00dfteil der Bev\u00f6lkerung, sowie f\u00fcr zuk\u00fcnftige Generationen, sind keine Utopie. Die jetzigen wirtschaftlichen und gesellschaftlichen Verh\u00e4ltnisse sind kein Naturgesetz, sondern sehr wohl zugunsten einer Mehrheit der Bev\u00f6lkerung ver\u00e4nderbar.<\/p>\n<p>Die Politik muss dann aber auch handeln und nicht weiterhin ihren Kopf im Sand vergraben.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die Verm\u00f6gensungleichheit in Luxemburg birgt die Gefahr, unsere Gesellschaft zu spalten und unserer Wirtschaft zu schaden.<\/p>\n","protected":false},"author":23,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[3],"tags":[],"class_list":["post-1426","post","type-post","status-publish","format-standard","hentry","category-unkategorisiert","topic-besteuerung","topic-ungleichheiten","format-text-de"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Die extreme Ungleichheit der Verm\u00f6gen: Sprengstoff f\u00fcr unsere Gesellschaft - Improof<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dev.improof.lu\/de\/articles\/extreme-ungleichheit-des-reichtums\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Die extreme Ungleichheit der Verm\u00f6gen: Sprengstoff f\u00fcr unsere Gesellschaft\" \/>\n<meta property=\"og:description\" content=\"Die Verm\u00f6gensungleichheit in Luxemburg birgt die Gefahr, unsere Gesellschaft zu spalten und unserer Wirtschaft zu schaden.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dev.improof.lu\/de\/articles\/extreme-ungleichheit-des-reichtums\/\" \/>\n<meta property=\"og:site_name\" content=\"Improof\" \/>\n<meta property=\"article:published_time\" content=\"2023-10-16T08:05:54+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-01-31T15:15:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dev.improof.lu\/app\/uploads\/2023\/10\/Jet.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1076\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Nermin Plavsic\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Die extreme Ungleichheit der Verm\u00f6gen: Sprengstoff f\u00fcr unsere Gesellschaft\" \/>\n<meta name=\"twitter:description\" content=\"Die Verm\u00f6gensungleichheit in Luxemburg birgt die Gefahr, unsere Gesellschaft zu spalten und unserer Wirtschaft zu schaden.\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/dev.improof.lu\/app\/uploads\/2023\/10\/Jet.jpg\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Nermin Plavsic\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/dev.improof.lu\/de\/articles\/extreme-ungleichheit-des-reichtums\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dev.improof.lu\/de\/articles\/extreme-ungleichheit-des-reichtums\/\"},\"author\":{\"name\":\"Nermin Plavsic\",\"@id\":\"https:\/\/dev.improof.lu\/de\/#\/schema\/person\/f08e949be075daa3df30515dca76bc50\"},\"headline\":\"Die extreme Ungleichheit der Verm\u00f6gen: Sprengstoff f\u00fcr unsere Gesellschaft\",\"datePublished\":\"2023-10-16T08:05:54+00:00\",\"dateModified\":\"2024-01-31T15:15:31+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dev.improof.lu\/de\/articles\/extreme-ungleichheit-des-reichtums\/\"},\"wordCount\":953,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dev.improof.lu\/de\/#organization\"},\"articleSection\":[\"Unkategorisiert\"],\"inLanguage\":\"de-DE\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dev.improof.lu\/de\/articles\/extreme-ungleichheit-des-reichtums\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dev.improof.lu\/de\/articles\/extreme-ungleichheit-des-reichtums\/\",\"url\":\"https:\/\/dev.improof.lu\/de\/articles\/extreme-ungleichheit-des-reichtums\/\",\"name\":\"Die extreme Ungleichheit der Verm\u00f6gen: Sprengstoff f\u00fcr unsere Gesellschaft - Improof\",\"isPartOf\":{\"@id\":\"https:\/\/dev.improof.lu\/de\/#website\"},\"datePublished\":\"2023-10-16T08:05:54+00:00\",\"dateModified\":\"2024-01-31T15:15:31+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/dev.improof.lu\/de\/articles\/extreme-ungleichheit-des-reichtums\/#breadcrumb\"},\"inLanguage\":\"de-DE\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dev.improof.lu\/de\/articles\/extreme-ungleichheit-des-reichtums\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dev.improof.lu\/de\/articles\/extreme-ungleichheit-des-reichtums\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/dev.improof.lu\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Die extreme Ungleichheit der Verm\u00f6gen: Sprengstoff f\u00fcr unsere Gesellschaft\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dev.improof.lu\/de\/#website\",\"url\":\"https:\/\/dev.improof.lu\/de\/\",\"name\":\"Improof\",\"description\":\"Tagline goes here\",\"publisher\":{\"@id\":\"https:\/\/dev.improof.lu\/de\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dev.improof.lu\/de\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de-DE\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/dev.improof.lu\/de\/#organization\",\"name\":\"Improof\",\"url\":\"https:\/\/dev.improof.lu\/de\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\/\/dev.improof.lu\/de\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dev.improof.lu\/app\/uploads\/2022\/10\/improof-logo-svg.png\",\"contentUrl\":\"https:\/\/dev.improof.lu\/app\/uploads\/2022\/10\/improof-logo-svg.png\",\"width\":652,\"height\":209,\"caption\":\"Improof\"},\"image\":{\"@id\":\"https:\/\/dev.improof.lu\/de\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dev.improof.lu\/de\/#\/schema\/person\/f08e949be075daa3df30515dca76bc50\",\"name\":\"Nermin Plavsic\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\/\/dev.improof.lu\/de\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/afc36a91be839793e88b896ff1fffd59?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/afc36a91be839793e88b896ff1fffd59?s=96&d=mm&r=g\",\"caption\":\"Nermin Plavsic\"},\"sameAs\":[\"http:\/\/dev.improof.lu\"],\"url\":\"https:\/\/dev.improof.lu\/de\/articles\/author\/plavsic-nermin\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Die extreme Ungleichheit der Verm\u00f6gen: Sprengstoff f\u00fcr unsere Gesellschaft - Improof","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dev.improof.lu\/de\/articles\/extreme-ungleichheit-des-reichtums\/","og_locale":"de_DE","og_type":"article","og_title":"Die extreme Ungleichheit der Verm\u00f6gen: Sprengstoff f\u00fcr unsere Gesellschaft","og_description":"Die Verm\u00f6gensungleichheit in Luxemburg birgt die Gefahr, unsere Gesellschaft zu spalten und unserer Wirtschaft zu schaden.","og_url":"https:\/\/dev.improof.lu\/de\/articles\/extreme-ungleichheit-des-reichtums\/","og_site_name":"Improof","article_published_time":"2023-10-16T08:05:54+00:00","article_modified_time":"2024-01-31T15:15:31+00:00","og_image":[{"width":1920,"height":1076,"url":"https:\/\/dev.improof.lu\/app\/uploads\/2023\/10\/Jet.jpg","type":"image\/jpeg"}],"author":"Nermin Plavsic","twitter_card":"summary_large_image","twitter_title":"Die extreme Ungleichheit der Verm\u00f6gen: Sprengstoff f\u00fcr unsere Gesellschaft","twitter_description":"Die Verm\u00f6gensungleichheit in Luxemburg birgt die Gefahr, unsere Gesellschaft zu spalten und unserer Wirtschaft zu schaden.","twitter_image":"https:\/\/dev.improof.lu\/app\/uploads\/2023\/10\/Jet.jpg","twitter_misc":{"Written by":"Nermin Plavsic","Est. reading time":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/dev.improof.lu\/de\/articles\/extreme-ungleichheit-des-reichtums\/#article","isPartOf":{"@id":"https:\/\/dev.improof.lu\/de\/articles\/extreme-ungleichheit-des-reichtums\/"},"author":{"name":"Nermin Plavsic","@id":"https:\/\/dev.improof.lu\/de\/#\/schema\/person\/f08e949be075daa3df30515dca76bc50"},"headline":"Die extreme Ungleichheit der Verm\u00f6gen: Sprengstoff f\u00fcr unsere Gesellschaft","datePublished":"2023-10-16T08:05:54+00:00","dateModified":"2024-01-31T15:15:31+00:00","mainEntityOfPage":{"@id":"https:\/\/dev.improof.lu\/de\/articles\/extreme-ungleichheit-des-reichtums\/"},"wordCount":953,"commentCount":0,"publisher":{"@id":"https:\/\/dev.improof.lu\/de\/#organization"},"articleSection":["Unkategorisiert"],"inLanguage":"de-DE","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dev.improof.lu\/de\/articles\/extreme-ungleichheit-des-reichtums\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/dev.improof.lu\/de\/articles\/extreme-ungleichheit-des-reichtums\/","url":"https:\/\/dev.improof.lu\/de\/articles\/extreme-ungleichheit-des-reichtums\/","name":"Die extreme Ungleichheit der Verm\u00f6gen: Sprengstoff f\u00fcr unsere Gesellschaft - Improof","isPartOf":{"@id":"https:\/\/dev.improof.lu\/de\/#website"},"datePublished":"2023-10-16T08:05:54+00:00","dateModified":"2024-01-31T15:15:31+00:00","breadcrumb":{"@id":"https:\/\/dev.improof.lu\/de\/articles\/extreme-ungleichheit-des-reichtums\/#breadcrumb"},"inLanguage":"de-DE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dev.improof.lu\/de\/articles\/extreme-ungleichheit-des-reichtums\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/dev.improof.lu\/de\/articles\/extreme-ungleichheit-des-reichtums\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/dev.improof.lu\/de\/"},{"@type":"ListItem","position":2,"name":"Die extreme Ungleichheit der Verm\u00f6gen: Sprengstoff f\u00fcr unsere Gesellschaft"}]},{"@type":"WebSite","@id":"https:\/\/dev.improof.lu\/de\/#website","url":"https:\/\/dev.improof.lu\/de\/","name":"Improof","description":"Tagline goes here","publisher":{"@id":"https:\/\/dev.improof.lu\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dev.improof.lu\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de-DE"},{"@type":"Organization","@id":"https:\/\/dev.improof.lu\/de\/#organization","name":"Improof","url":"https:\/\/dev.improof.lu\/de\/","logo":{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/dev.improof.lu\/de\/#\/schema\/logo\/image\/","url":"https:\/\/dev.improof.lu\/app\/uploads\/2022\/10\/improof-logo-svg.png","contentUrl":"https:\/\/dev.improof.lu\/app\/uploads\/2022\/10\/improof-logo-svg.png","width":652,"height":209,"caption":"Improof"},"image":{"@id":"https:\/\/dev.improof.lu\/de\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/dev.improof.lu\/de\/#\/schema\/person\/f08e949be075daa3df30515dca76bc50","name":"Nermin Plavsic","image":{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/dev.improof.lu\/de\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/afc36a91be839793e88b896ff1fffd59?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/afc36a91be839793e88b896ff1fffd59?s=96&d=mm&r=g","caption":"Nermin Plavsic"},"sameAs":["http:\/\/dev.improof.lu"],"url":"https:\/\/dev.improof.lu\/de\/articles\/author\/plavsic-nermin\/"}]}},"_links":{"self":[{"href":"https:\/\/dev.improof.lu\/de\/wp-json\/wp\/v2\/posts\/1426","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.improof.lu\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dev.improof.lu\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dev.improof.lu\/de\/wp-json\/wp\/v2\/users\/23"}],"replies":[{"embeddable":true,"href":"https:\/\/dev.improof.lu\/de\/wp-json\/wp\/v2\/comments?post=1426"}],"version-history":[{"count":6,"href":"https:\/\/dev.improof.lu\/de\/wp-json\/wp\/v2\/posts\/1426\/revisions"}],"predecessor-version":[{"id":1720,"href":"https:\/\/dev.improof.lu\/de\/wp-json\/wp\/v2\/posts\/1426\/revisions\/1720"}],"wp:attachment":[{"href":"https:\/\/dev.improof.lu\/de\/wp-json\/wp\/v2\/media?parent=1426"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dev.improof.lu\/de\/wp-json\/wp\/v2\/categories?post=1426"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dev.improof.lu\/de\/wp-json\/wp\/v2\/tags?post=1426"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}