{"id":2091,"date":"2024-07-25T12:50:26","date_gmt":"2024-07-25T12:50:26","guid":{"rendered":"https:\/\/dev.improof.lu\/?p=2091"},"modified":"2024-07-25T12:50:27","modified_gmt":"2024-07-25T12:50:27","slug":"intelligence-artificielle","status":"publish","type":"post","link":"https:\/\/dev.improof.lu\/de\/articles\/intelligence-artificielle\/","title":{"rendered":"L\u2019intelligence artificielle : quelles ambitions pour quels r\u00e9sultats ?"},"content":{"rendered":"<p>Dans un article rest\u00e9 c\u00e9l\u00e8bre, le math\u00e9maticien, Alan M. Turing (1912-1954), a imagin\u00e9 un dispositif pour une machine \u00ab de se faire passer pour un \u00eatre humain \u00bb. Ce proc\u00e9d\u00e9, d\u00e9nomm\u00e9 \u00ab computing machinery and intelligence[1] \u00bb, est devenu, quelques d\u00e9cennies plus tard, l\u2019intelligence artificielle.<\/p>\n<p>Depuis lors, dans l&#8217;histoire des r\u00e9volutions industrielles, jamais l&#8217;intelligence de l&#8217;homme n&#8217;a \u00e9t\u00e9 \u00e0 ce point \u00e0 la port\u00e9e des avanc\u00e9es technologiques ou techniques. Depuis le d\u00e9but du XXe si\u00e8cle, \u00ab l\u2019intelligence machine \u00bb est devenue une r\u00e9alit\u00e9 avec l\u2019apparition des premiers ordinateurs.<\/p>\n<p>Loin de s\u2019arr\u00eater l\u00e0, dans une soif de progr\u00e8s inextinguible n\u2019ayant pour autre vis\u00e9e que la cr\u00e9ation d\u2019un cerveau artificiel \u2013 sorte de reflet dans lequel le narcissisme peut se complaire \u00e0 loisir \u2013 de nombreux chercheurs \u00ab placent \u00e0 l\u2019horizon de leurs travaux, la r\u00e9alisation d\u2019une intelligence artificielle pleinement intelligente, c\u2019est-\u00e0-dire intelligente au sens humain \u00bb (2023, Andler[2], p.199).<\/p>\n<p>La chose semble plausible puisque \u00ab s\u2019appuyant sur une grande puissance de calcul, des r\u00e9seaux neuronaux artificiels et des grands mod\u00e8les de langage, la technologie de l\u2019IA r\u00e9ussit \u00e0 imiter avec une impressionnante habilet\u00e9, \u00e0 d\u00e9faut de l\u2019acqu\u00e9rir r\u00e9ellement, le \u00ab pivot \u00bb de la civilisation humaine : le langage \u00bb (UNESCO, Giannini, 2023).<\/p>\n<p>Qu\u2019il s\u2019agisse de ChatGPT d\u2019Open AI, de Bard de Google, de Sydney de Microsoft, ou des r\u00e9cents mod\u00e8les de l\u2019entreprise fran\u00e7aise Mistral AI, ces machines dites \u00ab intelligentes \u00bb g\u00e9n\u00e8rent en un clin d\u2019\u0153il des textes et des images, au point \u00ab d\u2019approcher, d\u2019\u00e9galer, voire surpasser l\u2019intelligence de l\u2019humain \u00bb (2023, Andler, p. 200). Pour autant, dans la pratique, ces robots continuent d&#8217;\u00eatre dirig\u00e9s par l&#8217;homme, raison pour laquelle \u00ab l\u2019intelligence au sens humain ne peut s\u2019attacher qu\u2019\u00e0 un \u00eatre humain. L\u2019intelligence artificielle, sous quelque forme et \u00e0 quelque degr\u00e9 de d\u00e9veloppement qu\u2019elle soit, a pour vocation de r\u00e9soudre des probl\u00e8mes, ce qui n\u2019est pour l\u2019intelligence humaine qu\u2019une mission secondaire \u00bb (ibid., p.17).<\/p>\n<p>Au niveau s\u00e9miologique, les processus mis en place par les technologies d&#8217;intelligence artificielle (IA) sont souvent associ\u00e9s \u00e0 l\u2019image de milliards de neurones \u2013 soit l\u2019\u00ab unit\u00e9 de travail de base du cerveau \u00bb[3] humain. En d\u2019autres termes, les progr\u00e8s technologiques d\u2019intelligence artificielle s\u2019inspirent donc de mani\u00e8re litt\u00e9rale des travaux scientifiques sur le fonctionnement du cerveau, en tant que support de l&#8217;intelligence humaine. Mais, pour autant, est-ce \u00e0 dire que l\u2019intelligence artificielle deviendra, dans un proche avenir, une reproduction fid\u00e8le de l\u2019intelligence humaine ?<\/p>\n<p>Partant de ces quelques consid\u00e9rations, le pr\u00e9sent article se donne pour objectif de cerner les ambitions, mais aussi les dangers que repr\u00e9sente l\u2019IA dans le secteur sp\u00e9cifique de l\u2019\u00e9ducation. Nous verrons, en d\u00e9pit de la r\u00e9cente adoption de l\u2019<em>Artifical Intelligence Act<\/em> par l\u2019ensemble des \u00c9tats membres de l\u2019Europe, que l\u2019IA est partout pr\u00e9sente et que les dangers qu\u2019elle pr\u00e9sente pour l\u2019\u00e9ducation et, au-del\u00e0, pour l\u2019intelligence humaine sont aussi r\u00e9els que savamment d\u00e9ni\u00e9s. Enfin, \u00e0 quoi doit servir et \u00e0 quoi doit se limiter l\u2019IA, sp\u00e9cifiquement dans le domaine de l\u2019\u00e9ducation, un d\u00e9bat plus que jamais ouvert.<\/p>\n<h2>1. Des avanc\u00e9es et des dangers de l\u2019IA<\/h2>\n<p>Des chercheurs d\u2019horizons divers (sciences de l\u2019\u00e9ducation, philosophie, sociologies &#8230;) ont entrepris d\u2019analyser les interactions homme-machine dans le cadre de l\u2019intelligence artificielle. Le CNRS[4] (Centre national fran\u00e7ais de la recherche scientifique) estime qu\u2019un \u00ab saut technologique \u00bb des plus saisissants a \u00e9t\u00e9 rendu possible \u00ab par les grands mod\u00e8les de langue dont ChatGPT est aujourd\u2019hui le plus connu \u00bb. Et le CNRS ajoute que ces mod\u00e8les :<\/p>\n<blockquote><p>\u00ab Permettent d\u2019encoder toute la langue et, \u00e0 travers la langue, des textes qui donnent beaucoup d\u2019informations sur le monde (\u2026). [Ce faisant, ils] ne sont pas seulement linguistiques : ils cr\u00e9ent des textes coh\u00e9rents parce qu\u2019ils sont capables de faire le lien entre diff\u00e9rents domaines. Ces mod\u00e8les n\u2019ont \u00e9videmment pas de rapport physique au monde, mais parce qu\u2019ils sont mis au point \u00e0 partir de milliards de textes, ils peuvent, par exemple, fournir des traductions tr\u00e8s fines, tenant compte du contexte, ce qu\u2019on ne savait pas faire il y a peu encore (CNRS, Poibeau, 2023 ).[5]<\/p><\/blockquote>\n<p>Compos\u00e9s d\u2019algorithmes associ\u00e9s aux processus du <em>machine learning<\/em>[6], ces mod\u00e8les, toujours selon le CNRS, reposent sur trois facteurs : une masse de donn\u00e9es que ces machines peuvent ingurgiter ; une capacit\u00e9 de calcul qui a explos\u00e9 ces derni\u00e8res ann\u00e9es gr\u00e2ce \u00e0 de nouvelles puces (les GPU) ; des algorithmes dits d\u2019apprentissage profond permettant de g\u00e9n\u00e9rer des textes.<\/p>\n<p>En plus, ces technologies impliquent des cons\u00e9quences allant au-del\u00e0 du cadre de leur utilisation, autrement dit, au-del\u00e0 du rapport de l\u2019utilisateur \u00e0 la machine. Concernant les avantages des technologies de l\u2019IA, l\u2019on peut citer leur dimension \u00e9conomique. En effet, tout comme ce fut le cas en 1992, lorsque nous avons assist\u00e9 \u00e0 la g\u00e9n\u00e9ralisation des r\u00e9seaux num\u00e9riques, le d\u00e9veloppement et l\u2019impact transformateur de ces \u00ab merveilles automatiques \u00bb et leur utilisation suscitent un engouement \u00e9conomique et social majeur.<\/p>\n<p>De m\u00eame, \u00ab de l\u2019intelligence collective peuvent \u00e9merger des configurations sociales in\u00e9dites, adapt\u00e9es aux conditions nouvelles, qu\u2019aucun savant calcul ne pourrait produire \u00bb (2020, Andler). Au-del\u00e0, les retomb\u00e9es sociales posent un d\u00e9fi social majeur suscitant \u00e0 la fois optimisme et scepticisme dans le monde de la recherche. Au point que certains chercheurs recommandent \u00ab de bannir la recherche en IA avanc\u00e9e, comme l\u2019est la recherche sur les armes bact\u00e9riologiques \u00bb (Andler, p. 331).<\/p>\n<p>Pour autant, la r\u00e9alit\u00e9 contre laquelle on ne peut aller, est que l\u2019utilisation de ces syst\u00e8mes dans notre vie quotidienne est d\u2019ores et d\u00e9j\u00e0 largement accept\u00e9e comme en attestent les syst\u00e8mes de d\u00e9verrouillage de l&#8217;iPhone par reconnaissance faciale ou de navigation par GPS, pour ne citer que quelques exemples. Quant aux moteurs de recherche Internet, ces derniers ne peuvent d\u00e9sormais plus parcourir l&#8217;ensemble du Web \u00e0 la recherche des termes de recherche saisis, sans \u00eatre \u00e9quip\u00e9s de ces logiciels artificiels.<\/p>\n<p>M\u00eame si nous sommes conscients des biais id\u00e9ologiques, \u00e9conomiques, politiques, environnementaux[7] induits par ces technologies, m\u00eame si nous doutons de la pr\u00e9sence en leur sein de dangers potentiels, qu\u2019ils soient visibles ou invisibles, force est de constater que la facilit\u00e9 d\u2019utilisation de ces technologies les rend de plus en plus omnipr\u00e9sentes.<\/p>\n<p>De l\u00e0, se pose la question de savoir ce que l\u2019homme a le plus \u00e0 craindre de la mainmise de l\u2019IA sur son activit\u00e9 num\u00e9rique.<\/p>\n<h2>2. La l\u00e9gislation europ\u00e9enne peut-elle encadrer le d\u00e9veloppement de l\u2019IA ?<\/h2>\n<p>Sur le plan politique, le Parlement Europ\u00e9en s\u2019est empar\u00e9 de la question et a adopt\u00e9 le 13 mars dernier, en s\u00e9ance pl\u00e9ni\u00e8re, une l\u00e9gislation portant sur l\u2019intelligence artificielle. Le but de cet assentiment europ\u00e9en \u00e9tant de \u00ab prot\u00e9ger les droits fondamentaux, la d\u00e9mocratie, l\u2019\u00c9tat de droit et la durabilit\u00e9 environnementale contre les risques li\u00e9s \u00e0 l\u2019intelligence artificielle (IA), tout en encourageant l\u2019innovation et en faisant de l\u2019Europe un acteur de premier plan dans ce domaine[8] \u00bb.<\/p>\n<p>Cette l\u00e9gislation pionni\u00e8re en mati\u00e8re de r\u00e9glementation de l\u2019IA a pris la forme de <em>l\u2019Artifical Intelligence Act<\/em>[9] dont l\u2019application est d\u2019ordre g\u00e9n\u00e9ral \u00e0 l\u2019ensemble de l\u2019Union europ\u00e9enne. Plus pr\u00e9cis\u00e9ment, cet acte d\u00e9finit les obligations permettant une utilisation fiable des \u00ab syst\u00e8mes d\u2019IA \u00bb, en fonction de leurs risques sp\u00e9cifiques et de leur ampleur respective. Pour ce faire, ont \u00e9t\u00e9 attribu\u00e9s \u00e0 ces syst\u00e8mes, diff\u00e9rentes cat\u00e9gories de risques. L\u2019on trouve ainsi : les syst\u00e8mes d\u2019IA \u00e0 usage g\u00e9n\u00e9ral et les syst\u00e8mes d\u2019IA \u00e0 haut risques, voire inacceptables \u00ab en raison de leur pr\u00e9judice potentiel important pour la sant\u00e9, la s\u00e9curit\u00e9, les droits fondamentaux, l\u2019environnement, la d\u00e9mocratie et l\u2019\u00c9tat de droit \u00bb (2024, Parlement europ\u00e9en).<\/p>\n<p>Cet <em>Artifical Intelligence Act<\/em> qui se donne pour finalit\u00e9 de s\u00e9curiser l&#8217;avenir des interactions homme-machine et de prot\u00e9ger les citoyens, met en lumi\u00e8re les risques potentiels engendr\u00e9s par ces syst\u00e8mes artificiels. Or, ces risques ne sont pas neutres au point que certains syst\u00e8mes d\u2019IA sont d\u00e9sormais interdits.<\/p>\n<p>En effet, il a \u00e9t\u00e9 admis que<\/p>\n<blockquote><p>\u00ab ces applications fond\u00e9es sur l\u2019IA [\u2026] menacent les droits des citoyens, y compris les syst\u00e8mes de cat\u00e9gorisation biom\u00e9trique utilisant des caract\u00e9ristiques sensibles et l\u2019extraction non cibl\u00e9e d\u2019images faciales sur Internet ou par vid\u00e9osurveillance pour cr\u00e9er des bases de donn\u00e9es de reconnaissance faciale. La reconnaissance des \u00e9motions sur le lieu de travail et dans les \u00e9tablissements d\u2019enseignement, la notation sociale, la police pr\u00e9dictive (lorsqu\u2019elle est bas\u00e9e uniquement sur le profilage d\u2019une personne ou sur l\u2019\u00e9valuation de ses caract\u00e9ristiques) et l\u2019IA qui manipule le comportement humain ou exploite les vuln\u00e9rabilit\u00e9s des personnes seront \u00e9galement interdites \u00bb (2024, Parlement europ\u00e9en).<\/p><\/blockquote>\n<p>Ces applications class\u00e9es comme \u00e9tant \u00ab \u00e0 haut risque \u00bb doivent \u00ab atteindre un niveau appropri\u00e9 de pr\u00e9cision, de robustesse et de cybers\u00e9curit\u00e9. Les concepteurs devront aussi s\u2019assurer qu\u2019une intervention humaine est toujours possible afin d\u2019\u00e9viter les d\u00e9rives permises par l\u2019automatisation \u00bb (2024, Touteleurope.eu).<\/p>\n<p>Avec cette r\u00e9gulation, \u00ab l\u2019Europe dispose d\u2019une r\u00e9f\u00e9rence mondiale en mati\u00e8re d\u2019IA \u00bb, comme le souligne le commissaire europ\u00e9en au march\u00e9 int\u00e9rieur, Thierry Breton. Une d\u00e9claration qui n\u2019est pas sans rappeler les annonces touchant la strat\u00e9gie de Lisbonne[10]. Selon le discours politique tenu \u00e0 l\u2019\u00e9poque, l\u2019Union europ\u00e9enne devait \u00ab devenir l&#8217;\u00e9conomie de la connaissance la plus comp\u00e9titive et la plus dynamique du monde, capable d&#8217;une croissance \u00e9conomique durable accompagn\u00e9e d&#8217;une am\u00e9lioration quantitative et qualitative de l&#8217;emploi et d&#8217;une plus grande coh\u00e9sion sociale \u00bb (Journal officiel n\u00b0 C 104 du 30\/04\/2004 p.0001\u20130019).<\/p>\n<p>Aujourd\u2019hui, il est ais\u00e9 de reconna\u00eetre que le secteur de l\u2019\u00e9conomie de la \u00ab connaissance \u00bb s\u2019est fortement d\u00e9velopp\u00e9 et qu\u2019il poss\u00e8de une rh\u00e9torique d\u2019adaptation particuli\u00e8rement efficace aux exigences des puissances \u00e9conomiques mondiales.<\/p>\n<p>Pour le dire autrement, nous pouvons penser que les entrepreneurs de l\u2019IA n\u2019auront cure des r\u00e8glements europ\u00e9ens, et cela pour deux raisons principales : la premi\u00e8re est que l\u2019Europe n\u2019est pas le monde. Et que ce qui peut \u00eatre r\u00e9alis\u00e9 dans d\u2019autres continents finira forc\u00e9ment par se r\u00e9pandre et s\u2019imposer en Europe par le biais d\u2019autres moyens que la vente directe de logiciels. Concr\u00e8tement, telle est d\u2019ores et d\u00e9j\u00e0 la logique des entreprises de l\u2019IA qui ont pour projet de d\u00e9velopper leurs technologies \u00e0 l\u2019\u00e9tranger, notamment aux \u00c9tats-Unis ou en Asie, loin de presque toute contrainte, puis de rendre ces derni\u00e8res indispensables dans l\u2019utilisation de certaines machines ou dans l\u2019analyse de certaines donn\u00e9es, rendant ainsi le recours \u00e0 leur technologie incontournable.<\/p>\n<p>La seconde raison pour laquelle la l\u00e9gislation europ\u00e9enne risque de ne pas \u00eatre en mesure de nous prot\u00e9ger contre les dangers de l\u2019IA, est que cette derni\u00e8re r\u00e9pond d\u2019un d\u00e9sir. Un d\u00e9sir \u00e0 la fois narcissique et prom\u00e9th\u00e9en. Or, comme le rappelle Lacan, rien ne peut contraindre un d\u00e9sir, car son objet est fantasmatique. Or, comme la loi, pourrait-elle emp\u00eacher, limiter ou sanctionner un fantasme ?<\/p>\n<p>Reste \u00e0 d\u00e9terminer si, concr\u00e8tement, les technologies de l\u2019IA sont, \u00e0 ce jour, efficaces en mati\u00e8re d\u2019am\u00e9lioration de l\u2019\u00e9ducation. Mani\u00e8re de d\u00e9terminer si l\u2019attention actuellement port\u00e9e \u00e0 cet axe de recherche est ou non m\u00e9rit\u00e9e.<\/p>\n<h2>3. Les limites de l\u2019IA dans le secteur de l\u2019\u00e9ducation<\/h2>\n<p>Il convient de noter que le \u00ab programme ambitieux en vue de moderniser les syst\u00e8mes de s\u00e9curit\u00e9 sociale et d&#8217;\u00e9ducation \u00bb (Journal officiel n\u00b0 C 104 du 30\/04\/2004 p.0001\u20130019) n\u2019a pas atteint ses objectifs.<\/p>\n<p>L\u2019intelligence artificielle n\u2019est certes pas une solution en kit, pr\u00eate \u00e0 r\u00e9soudre toutes les questions en lien avec l\u2019\u00e9ducation et la formation. La question se pose de savoir si les attentes touchant les \u00ab marvels of machine learning \u00bb (soit les merveilles de l\u2019apprentissage automatique) dans le secteur de l\u2019\u00e9ducation, ne risquent pas d\u2019\u00eatre profond\u00e9ment d\u00e9\u00e7ues, engendrant le risque de voir l\u2019\u00e9cole plonger dans un \u00ab processus de d\u00e9sapprentissage et de \u00ab prol\u00e9tarisation des esprits \u00bb comme le soulignait Bernard Stiegler d\u00e8s 2012.<\/p>\n<p>Pour saisir l\u2019importance de cette interrogation, il convient de citer plus longuement ce philosophe pour qui : \u00ab cette \u00e9conomie n\u2019est pas du tout virtuelle ni fumeuse : elle est bien r\u00e9elle, c\u2019est bien une \u00e9conomie de <em>l\u2019exploitation \u00e0 la fois de l\u2019information et de la connaissance<\/em>, mais elle fonctionne au prix d\u2019une destruction de la connaissance et des savoirs, car elle repose sur un processus de perte de savoir et de prol\u00e9tarisation dans les plus hautes sph\u00e8res de la d\u00e9cision, et donc de la pens\u00e9e en tant qu\u2019elle agit. Tel est le sens profond de la notion de \u00ab soci\u00e9t\u00e9 de connaissance \u00bb (2012, Stiegler).<\/p>\n<p>Dans cet \u00e9tat d\u2019esprit, \u00ab l\u2019immense processus de d\u00e9sapprentissage \u00bb (ibid.) a de quoi \u00e0 nous inqui\u00e9ter. D\u2019autant que, dans le m\u00eame temps, l\u2019IA est utilis\u00e9e et m\u00eame impos\u00e9e par ce fait m\u00eame par les entreprises multinationales, sans que les \u00c9tats semblent r\u00e9agir, si ce n\u2019est avec l\u2019<em>Artifical Intelligence Act<\/em> dont la port\u00e9e est d\u2019ores et d\u00e9j\u00e0 limit\u00e9e.<\/p>\n<p>Sommes-nous confront\u00e9s \u00e0 un d\u00e9ni ou \u00e0 d\u00e9n\u00e9gation de cet \u00e9tat de fait ? Et, dans l\u2019un ou l\u2019autre cas, que peut cacher ce type de r\u00e9action ?<\/p>\n<p>Pour r\u00e9pondre \u00e0 cette question, les chercheurs en linguistique, Noam Chomsky et Ian Roberts, accompagn\u00e9s de Jeffrey Watumull, directeur d\u2019une soci\u00e9t\u00e9 dans le domaine de l\u2019IA, ont analys\u00e9 diff\u00e9rents aspects de ChatGPT, dont certains peu connus du grand public.<\/p>\n<p>Dans un article intitul\u00e9 <em>\u00ab The false promise of ChatGPT \u00bb<\/em> (2023), ils montrent que, quelle que soit l&#8217;utilit\u00e9 de ces programmes dans certains domaines, ils sont fondamentalement diff\u00e9rents de la mani\u00e8re dont les humains raisonnent et utilisent le langage au vu des principes de la linguistique et de la philosophie de la connaissance.<\/p>\n<p>Pour \u00e9tayer ce constat, les chercheurs ont compar\u00e9 l\u2019apprentissage automatique ChatGPT et de ses concurrents et mis en lumi\u00e8re le fait que ces programmes, de par leur conception, poss\u00e8dent une m\u00e9morisation illimit\u00e9e, mais qu\u2019ils ne sont pas capables de faire la diff\u00e9rence entre le possible et l&#8217;impossible. En cela, ces machines sont d\u00e9nou\u00e9es de raisonnement et abstraction. Elles donnent ainsi \u00e0 l\u2019utilisateur l\u2019impression d\u2019\u00eatre capables de comprendre, mais recrachent \u00e0 la fois que la terre est plate et qu&#8217;elle est ronde.<\/p>\n<p>Partant de l\u00e0, ces chercheurs mettent en garde contre l\u2019omnipr\u00e9sence de ces processus qui p\u00e9n\u00e8trent dans toutes les sph\u00e8res de la soci\u00e9t\u00e9 et qui touchent m\u00eame les comportements les plus \u00e9l\u00e9mentaires, en prenant l&#8217;apparence de la science sans en respecter les principes scientifiques.<\/p>\n<p>En effet, ces syst\u00e8mes d\u2019IA \u00e9changent simplement des probabilit\u00e9s qui \u00e9voluent avec le temps. Leurs pr\u00e9dictions sont donc, par essence, superficielles et douteuses. Ils donnent le sentiment de faire face \u00e0 une science, qui, en r\u00e9alit\u00e9,\u00a0 n\u2019en est pas une puisque l\u2019intelligence artificielle ne fournit aucun d\u00e9veloppement scientifique. De plus, ces syst\u00e8mes ne poss\u00e8dent pas la capacit\u00e9 de penser, d\u2019expliquer ou de d\u00e9limiter un ensemble de principes \u00e9thiques et moraux d\u00e9terminant ce qui doit \u00eatre et ce qui ne peut \u00eatre.<\/p>\n<p>Ainsi, le verdict de Chomsky et al. est-il sans appel : malgr\u00e9 la sophistication apparente de la pens\u00e9e et du langage produit par ces mod\u00e8les, l&#8217;indiff\u00e9rence morale qu\u2019ils g\u00e9n\u00e8rent na\u00eet de l&#8217;inintelligence. Ce faisant, ChatGPT est un outil sur\u00e9valu\u00e9 qui d\u00e9voile le recours au plagiat, g\u00e9n\u00e8re l\u2019apathie, l\u2019\u00e9viction et l\u2019irresponsabilit\u00e9.<\/p>\n<p>En effet, en r\u00e9sumant des textes issus de la litt\u00e9rature par une sorte de super-autocompl\u00e9tion tout en refusant de prendre position sur quoi que ce soit, ChatGPT plaide non seulement pour l&#8217;ignorance, mais aussi le manque d&#8217;intelligence. En outre, ChatGPT repose sur une logique de d\u00e9fense qui consiste \u00e0 dire : \u00ab\u00a0je ne fais que suivre les ordres\u00a0\u00bb, mani\u00e8re de rejeter toute responsabilit\u00e9 sur ses cr\u00e9ateurs du programme et aussi sur ses utilisateurs.<\/p>\n<p>Au final, les auteurs d\u00e9noncent le fait que ChatGPT et d\u2019autres programmes similaires produisent autant des v\u00e9rit\u00e9s que des mensonges, approuvant des d\u00e9cisions \u00e9thiques et non \u00e9thiques, sans jamais s\u2019engager dans aucune d\u00e9cision et sans jamais se montrer regardant quant aux cons\u00e9quences. Compte tenu du caract\u00e8re immoral de la fausse science ainsi \u00e9tal\u00e9e, et de l\u2019incomp\u00e9tence linguistique qui caract\u00e9rise ces syst\u00e8mes, l\u2019on ne sait pas s\u2019il faut en rire ou pleurer de leur popularit\u00e9 (Chomsky &amp; al, 2023).<\/p>\n<p>Pour Andler (2020), c\u2019est avant tout \u00ab la num\u00e9risph\u00e8re qui place le d\u00e9sastre dans toute son \u00e9tendue sous les yeux de tous, informant chacun \u00e0 chaque instant et par mille canaux. Elle devient ainsi connaissance commune, par laquelle chacun sait que tous savent (tout en entretenant un doute permanent sur ce qui est confirm\u00e9, probable ou faux) \u00bb. De ce point de vue, on peut s\u2019accorder pour dire que l&#8217;opinion de chacun ne retient seulement ce qui la flatte dans ses illusions.<\/p>\n<p>La question est alors de comprendre pourquoi certaines personnes sont incapables ou ne sont plus en mesure de faire cette diff\u00e9rence sur le plan moral ? En d\u2019autres termes, le bon sens et la raison, choses que Descartes estimait les mieux partag\u00e9es du monde, auraient-ils \u00e9t\u00e9 sacrifi\u00e9s sur l\u2019autel de la technologie de l\u2019\u00e9conomie mondiale ?<\/p>\n<p>Pour notre part, nous aurions tendance \u00e0 affirmer que nous ne sommes pas tant dans le cadre d\u2019une immoralit\u00e9 (puisque la moralit\u00e9 semble n\u2019avoir aucun sens, aucune place ici), mais bien dans ce que Chomsky et al (2023) nomment une forme d\u2019amoralit\u00e9. De m\u00eame, nous ne sommes pas dans le cadre de l\u2019insens\u00e9, donc de la folie puisqu\u2019il n\u2019y a pas de normalit\u00e9 au monde de l\u2019intelligence artificielle. En r\u00e9alit\u00e9, nous cultivons avec l\u2019IA le r\u00e8gne de l\u2019amoralit\u00e9 et de ce qui fait sens, \u00e0 un moment donn\u00e9, en un lieu donn\u00e9, dans un hic et nunc sans cesse renouvel\u00e9. En notant que ce constat permet de garder espoir au sens o\u00f9 il ne revient pas aux technosciences ou aux entreprises d\u2019IA de dire ce qui est moral ou pas. C\u2019est \u00e0 l\u2019humain, en activant son intelligence, de s\u00e9parer le bon grain de l\u2019ivraie et, ce faisant, de se d\u00e9marquer de la machine.<\/p>\n<p>C\u2019est \u00e0 cette r\u00e9flexion qu\u2019entend \u00e9galement contribuer l\u2019UNESCO (2023) qui a lanc\u00e9 un appel \u00e0 \u00ab la bonne gouvernance de l\u2019Intelligence artificielle \u00bb \u00e0 ses \u00c9tats membres. Un d\u00e9fi qu\u2019elle qualifie comme \u00e9tant \u00ab l\u2019un des plus importants de notre \u00e9poque \u00bb (UNESCO, 2023).<\/p>\n<h2>4. Quel doit \u00eatre le r\u00f4le de l\u2019IA dans le secteur de l\u2019\u00c9ducation ?<\/h2>\n<p>Pour l\u2019UNESCO, \u00ab s\u2019agissant d\u2019\u00e9valuer et de valider les applications nouvelles et complexes de l\u2019IA en vue de leur utilisation formelle dans les \u00e9tablissements scolaires, l\u2019UNESCO recommande aux minist\u00e8res de l\u2019\u00c9ducation de renforcer leurs capacit\u00e9s, en coordination avec d\u2019autres services du gouvernement charg\u00e9s de la r\u00e9glementation, en particulier de la r\u00e9glementation des technologies \u00bb (UNESCO, 2024).<\/p>\n<p>Mais, que signifie \u00ab renforcer ses capacit\u00e9s \u00bb ? L\u2019expression est si vague qu\u2019elle peut vouloir tout et rien dire \u00e0 la fois. D\u2019une part, le droit de l\u2019Union europ\u00e9en prime sur le droit national, ce qui veut dire qu\u2019un \u00c9tat europ\u00e9en est soumis, quant aux lois qu\u2019il adopte, au droit europ\u00e9en[11]. En cela, le renforcement des services d\u2019un gouvernement ne peut aller que dans la limite de ce qui, en aval, a \u00e9t\u00e9 adopt\u00e9 par l\u2019Union europ\u00e9enne. D\u2019autre part, l\u00e9gif\u00e9rer au fur et \u00e0 mesure que de nouvelles technologies sont mises sur le march\u00e9 est une mesure capillotract\u00e9e, car la force des entreprises de l\u2019IA : leur r\u00e9activit\u00e9, leur facult\u00e9 \u00e0 se glisser dans tous les secteurs sans oublier leur usage rendu n\u00e9cessaire, voire obligatoire, dans maintes applications.<\/p>\n<p>En somme, la lutte des \u00c9tats contre le d\u00e9veloppement de l\u2019IA \u2013 que ce soit, comme ici, dans le secteur de l\u2019\u00e9ducation ou dans tout autre secteur \u2013 ressemble fort \u00e0 la lutte du pot de terre contre le pot de fer. Ou pire encore, \u00e0 la lutte contre une technologie qui se d\u00e9veloppe en contaminant tout et tout le monde sur son passage, soit \u00e0 la fa\u00e7on d\u2019un virus. Faut-il alors accepter tranquillement les grandes d\u00e9ficiences cognitives auxquelles tout le monde est expos\u00e9 ? Ou poursuivre sans rel\u00e2che les efforts de limitation ?<\/p>\n<p>D\u00e8s lors, bien qu\u2019il nous soit impossible, dans le cadre de la pr\u00e9sente contribution, de traiter dans son enti\u00e8ret\u00e9 de la question de l\u2019\u00e9cole face au num\u00e9rique, la \u00ab d\u00e9termination de transmettre nos savoirs aux g\u00e9n\u00e9rations futurs pour leur \u00e9mancipation \u00bb n\u2019est pas une ambition d\u00e9mesur\u00e9e. Il convient d\u2019admettre que \u00ab ces nouvelles technologies cr\u00e9ent les conditions d\u2019une d\u00e9mocratisation inesp\u00e9r\u00e9e de l\u2019acc\u00e8s au savoir \u00bb (2012, Kambouchner &amp; al.).<\/p>\n<p>Allant plus loin, Kambouchner[12] et al. affirment que ces m\u00eames technologies sont \u00ab associ\u00e9es \u00e0 un consum\u00e9risme effr\u00e9n\u00e9 et \u00e0 un marketing intrusif \u00bb auxquels il conviendrait de compl\u00e9ter qu\u2019entre-temps, ces intelligences artificielles sont en m\u00eame temps tr\u00e8s \u00e9nergivores et contribuent \u00e0 \u00e9mettre de grandes quantit\u00e9s de gaz \u00e0 effet de serre. Et d\u2019ajouter : \u00ab Elles apparaissent comme les vecteurs d\u2019un syst\u00e8me toujours plus perfectionn\u00e9 de captations des esprits \u00bb (ibid.)<\/p>\n<p>Dans le m\u00eame temps, cette remarque est tr\u00e8s int\u00e9ressante puisque le cerveau humain, cet objet vivant que l\u2019on tente de cr\u00e9er de toute pi\u00e8ce, est ici remis au centre du d\u00e9bat. Ce faisant, en partant du principe qu\u2019un <em>cerveau artificiel et m\u00e9canique<\/em> ne peut occuper pleinement l\u2019espace du <em>cerveau vivant et naturel<\/em>, de la pens\u00e9e humaine et du langage, la vis\u00e9e premi\u00e8re de toute politique scolaire ne peut donc consister qu\u2019\u00e0 \u00e9viter toute forme de pauvret\u00e9 \u00e9ducative manifeste et qu\u2019\u00e0 garantir une vis\u00e9e \u00e9mancipatrice de l\u2019\u00e9cole.<\/p>\n<p>En outre, attendu que \u00ab cette r\u00e9volution technologique entra\u00eene des nouveaux d\u00e9s\u00e9quilibres \u00bb sur le plan de l\u2019\u00e9ducation et de la formation (comme le pr\u00e9cise la directrice g\u00e9n\u00e9rale de l\u2019UNESCO, Audrey Azoulay), la question se pose de savoir comment prot\u00e9ger les \u00e9l\u00e8ves contre ces d\u00e9rives qui affectent les m\u00e9canismes cl\u00e9s \u00ab d\u2019abstraction r\u00e9fl\u00e9chissante \u00bb au sens o\u00f9 l\u2019entendait Jean Piaget[13].<\/p>\n<p>Allant plus loin, le professeur de l\u2019\u00e9ducation et de la p\u00e9dagogie, Philippe Meirieu[14] (2012) affirme que :<\/p>\n<blockquote><p>\u00ab Le num\u00e9rique est une question politique \u00e0 construire comme telle : sert-il au contr\u00f4le technocratique d\u2019individus assign\u00e9s \u00e0 l\u2019individualisme ou pourrait-il servir \u00e0 l\u2019\u00e9mancipation collective pour l\u2019\u00e9mergence possible d\u2019une d\u00e9mocratie \u00e0 hauteur d\u2019homme ? Le num\u00e9rique \u00e0 l\u2019\u00e9cole est, simultan\u00e9ment, une question p\u00e9dagogique et, donc anthropologique : que transmettons-nous, \u00e0 travers lui, de \u00ab l\u2019humaine condition \u00bb ? Comment nous articulons-nous, \u00e0 travers lui, \u00e0 notre jeunesse et comment lui garantissons-nous les conditions de d\u00e9veloppement ? \u00bb (p.176).<\/p><\/blockquote>\n<h2>5. Conclusion<\/h2>\n<p>\u00c0 rebours d\u2019une \u00ab Europe de la connaissance \u00bb consid\u00e9rant l\u2019innovation, la recherche, l\u2019\u00e9ducation et la formation comme des axes fondamentaux du d\u00e9veloppement de l\u2019Union europ\u00e9enne, la direction oppos\u00e9e est en train d\u2019\u00e9clipser lentement \u00ab le plaisir d\u2019apprendre \u00bb qui est tout sauf une d\u00e9marche qui se fait de soi-m\u00eame, m\u00eame si \u00ab savoir sans apprendre \u00bb, est un imaginaire de l\u2019efficacit\u00e9 imm\u00e9diate de l\u2019IA.<\/p>\n<p>Que ce mouvement soit devenu le quotidien dans notre soci\u00e9t\u00e9 moderne semble, par essence, incontr\u00f4l\u00e9 et incontr\u00f4lable. Pas s\u00fbr si ces vives inqui\u00e9tudes d\u00e9rangent outre mesure ceux qui d\u00e9veloppent les technologies, ni ceux qui encouragent l\u2019acc\u00e8s aux financements pour les entreprises et autres organismes innovants en Europe.<\/p>\n<p>Loin de s\u2019alarmer, les politiques luxembourgeois semblent se f\u00e9liciter de la situation : \u00ab l\u2019\u00e9conomie luxembourgeoise reste une \u00e9conomie de la connaissance \u00bb[15]. Et d\u2019ajouter avec fiert\u00e9 que les solutions politiques sont principalement ax\u00e9es sur les \u00ab technologies de pointe [qui] ont b\u00e9n\u00e9fici\u00e9 d&#8217;un appui consid\u00e9rable ces derni\u00e8res ann\u00e9es, ce qui a donn\u00e9 naissance \u00e0 un \u00e9cosyst\u00e8me florissant d&#8217;entreprises, d&#8217;investisseurs et de parties prenantes publiques \u00bb (ibid).<\/p>\n<p>Il est difficile de rester impassible devant cet indice le plus patent. Qu\u2019en est-il alors de l\u2019investissement scolaire dans cette configuration ?<\/p>\n<p>Il importe certes de nous confronter \u00e0 l\u2019intelligence artificielle, \u00e0 travailler sur ses usages, ses utilit\u00e9s, mais aussi ses risques et d\u00e9faillances, afin d\u2019\u00eatre en mesure de transmettre correctement la port\u00e9e de ces \u00ab intelligences artificielles \u00bb \u00e0 nos enfants, \u00e0 nos \u00e9l\u00e8ves, \u00e0 nos \u00e9tudiants condamn\u00e9s aux dangers de ces \u00ab technologies de pointe \u00bb. Mais, tel discours impassible, et en d\u00e9pit des \u00e9tudes scientifiques en la mati\u00e8re, condamnent l\u2019\u00e9cole \u00e0 la superficialit\u00e9 et contribuent largement, de par son indiff\u00e9rence, que \u00ab la fabrique du cr\u00e9tin digitale \u00bb (2023, Desmurget[16]), continue \u00e0 tourner \u00e0 plein r\u00e9gime.<\/p>\n<p>Malheureusement, proclamer aujourd\u2019hui toutes ces mesures dissone fortement avec les r\u00e9sultats des \u00e9tudes scientifiques. La pertinence sur la transmission du savoir, le plaisir d\u2019apprendre, n\u2019est gu\u00e8re discut\u00e9e. Le sens \u00e0 donner \u00e0 l\u2019\u00e9ducation non plus.<\/p>\n<p>Or, dans le champ de l\u2019\u00e9ducation, ce dernier est un axe pivot car il d\u00e9termine, en partie, la base de r\u00e9flexion sur laquelle \u00ab la g\u00e9n\u00e9ration qui vient sur le chemin des apprentissages \u00bb s\u2019appuieront. Nous ne pouvons qu\u2019approuver que :<\/p>\n<blockquote><p>\u00ab L\u2019intelligence artificielle satisfait sans nul doute, le d\u00e9sir de savoir, ou du moins, le d\u00e9sir d\u2019obtenir une r\u00e9ponse rapide. Ainsi le triomphe du \u00ab savoir sans apprendre \u00bb ne se traduit-il pas seulement par le culte de l\u2019outil technique dernier cri : il encourage aussi, et simultan\u00e9ment, les croyances les plus irrationnelles, celles qui se donnent comme des \u00e9vidences faciles, et renvoient au sentiment du tout ma\u00eetriser, sans avoir eu \u00e0 travailler, sans avoir eu \u00e0 comprendre \u00bb (Meirieu, 2014).<\/p><\/blockquote>\n<p>Disons donc tr\u00e8s clairement que \u00ab dans un monde qui est destitu\u00e9 par le pr\u00eat-\u00e0-porter technologique \u00bb (Meirieu, 2014) l\u2019intelligence artificielle nuit au d\u00e9sir et au plaisir d\u2019apprendre. Partant de l\u00e0, c\u2019est \u00e0 l\u2019\u00e9cole d\u2019enseigner une \u00ab culture lettr\u00e9e \u00bb et de s\u2019emparer activement de ces technologies num\u00e9riques \u00ab pour en conjurer les effets toxiques \u00bb et les mettre au service du projet d\u2019une \u00ab soci\u00e9t\u00e9 savante \u00bb.<\/p>\n<p>Pour le formuler autrement, nous devons faire un choix clair et d\u00e9lib\u00e9r\u00e9 entre une \u00e9ducation de bas niveau (<em>Niedrigbildung<\/em>) et des r\u00e9ponses de remplacement g\u00e9n\u00e9r\u00e9es par l\u2019intelligence artificielle !<\/p>\n<p>Or, pour ce faire, il convient de lutter r\u00e9solument contre ce qui s\u2019annonce, pour le moment, plut\u00f4t comme \u00ab le r\u00e8gne de la b\u00eatise \u00bb (Gauthier &amp; Vergne, 2012).<\/p>\n<h2>Bibliographie<\/h2>\n<p>Andler, D. (2020) Une pand\u00e9mie \u00e0 l\u2019\u00e8re des technologies \u00e9mergentes. <a href=\"https:\/\/academiesciencesmoralesetpolitiques.fr\/wp-content\/uploads\/2020\/05\/DA_unepandemie_12052020.pdf\">https:\/\/academiesciencesmoralesetpolitiques.fr\/wp-content\/uploads\/2020\/05\/DA_unepandemie_12052020.pdf<\/a><\/p>\n<p>Andler, D. (2023). Intelligence artificielle, intelligence humaine : la double \u00e9nigme. Gallimard. <a href=\"https:\/\/doi.org\/10.3917\/gall.andle.2023.01\">https:\/\/doi.org\/10.3917\/gall.andle.2023.01<\/a><\/p>\n<p>Chomsky, N. ; Roberts I. &amp; Watumull J. (2023). The false Promise of ChatGPT. Guest essay in The New York Times. <a href=\"https:\/\/www.nytimes.com\/2023\/03\/08\/opinion\/noam-chomsky-chatgpt-ai.html\">https:\/\/www.nytimes.com\/2023\/03\/08\/opinion\/noam-chomsky-chatgpt-ai.html<\/a><\/p>\n<p>CNRS Le Journal. (2023). La cr\u00e9ativit\u00e9 peut-elle \u00eatre artificielle ? <a href=\"https:\/\/lejournal.cnrs.fr\/articles\/la-creativite-peut-elle-etre-artificielle\">https:\/\/lejournal.cnrs.fr\/articles\/la-creativite-peut-elle-etre-artificielle<\/a><\/p>\n<p>Kambouchner, D., Meirieu, P. ;&amp; Stiegler, B.\u00a0 (2012). L\u2019\u00e9cole, le num\u00e9rique et la soci\u00e9t\u00e9 qui vient. \u00c9ditions mille et une nuits.<\/p>\n<p>L\u2019intelligence artificielle en Europe : \u00e9volution technologique ou r\u00e9volution humaine. <a href=\"https:\/\/www.forumeuropeendebioethique.eu\/emissions\/lintelligence-artificielle-en-europe-evolution-technologique-ou-revolution-humaine\">https:\/\/www.forumeuropeendebioethique.eu\/emissions\/lintelligence-artificielle-en-europe-evolution-technologique-ou-revolution-humaine<\/a><\/p>\n<p>Meirieu, P. (2016). Peut-on susciter le d\u00e9sir d\u2019apprendre ?. Dans : Martine Fournier \u00e9d., \u00c9duquer et Former: Connaissances et d\u00e9bats en \u00c9ducation et Formation (pp. 152-158). Auxerre: \u00c9ditions Sciences Humaines. <a href=\"https:\/\/doi.org\/10.3917\/sh.fourn.2016.01.0152\">https:\/\/doi.org\/10.3917\/sh.fourn.2016.01.0152<\/a><\/p>\n<p>Parlement Europ\u00e9en. (2024). Communiqu\u00e9 de presse 20240308IPR19015. Intelligence artificielle: les d\u00e9put\u00e9s adoptent une l\u00e9gislation historique. <a href=\"https:\/\/www.touteleurope.eu\/economie-et-social\/les-deputes-europeens-adoptent-une-loi-historique-sur-l-intelligence-artificielle\/\">https:\/\/www.touteleurope.eu\/economie-et-social\/les-deputes-europeens-adoptent-une-loi-historique-sur-l-intelligence-artificielle\/<\/a><\/p>\n<p>Parlement Europ\u00e9en. (2024). Intelligence artificielle: les d\u00e9put\u00e9s adoptent une l\u00e9gislation historique. <a href=\"https:\/\/www.europarl.europa.eu\/news\/fr\/press-room\/20240308IPR19015\/intelligence-artificielle-les-deputes-adoptent-une-legislation-historique\">https:\/\/www.europarl.europa.eu\/news\/fr\/press-room\/20240308IPR19015\/intelligence-artificielle-les-deputes-adoptent-une-legislation-historique<\/a><\/p>\n<p>Toute l\u2019Europe. Comprendre l\u2019Europe. <a href=\"https:\/\/www.touteleurope.eu\/economie-et-social\/les-deputes-europeens-adoptent-une-loi-historique-sur-l-intelligence-artificielle\">https:\/\/www.touteleurope.eu\/economie-et-social\/les-deputes-europeens-adoptent-une-loi-historique-sur-l-intelligence-artificielle<\/a><\/p>\n<p>UNESCO. (2018). Discours de la Directrice g\u00e9n\u00e9rale de l&#8217;UNESCO, Audrey Azoulay, \u00e0 l&#8217;occasion du s\u00e9minaire: R\u00e9flexion sur l&#8217;intelligence artificielle; <a href=\"https:\/\/unesdoc.unesco.org\/ark:\/48223\/pf0000264365\">https:\/\/unesdoc.unesco.org\/ark:\/48223\/pf0000264365<\/a><\/p>\n<p>UNESCO. (2023). Global AI Ethics and Governance Observatory. <a href=\"https:\/\/www.unesco.org\/ethics-ai\/en?hub=32618\">https:\/\/www.unesco.org\/ethics-ai\/en?hub=32618<\/a><\/p>\n<p>UNESCO. (2024). L\u2019IA g\u00e9n\u00e9rative et le futur de l\u2019\u00e9ducation <a href=\"https:\/\/unesdoc.unesco.org\/ark:\/48223\/pf0000385877_fre\">https:\/\/unesdoc.unesco.org\/ark:\/48223\/pf0000385877_fre<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le pr\u00e9sent article se donne pour objectif de cerner les ambitions, mais aussi les dangers que repr\u00e9sente l\u2019IA dans le secteur sp\u00e9cifique de l\u2019\u00e9ducation. Nous verrons, en d\u00e9pit de la r\u00e9cente adoption de l\u2019Artifical Intelligence Act par l\u2019ensemble des \u00c9tats membres de l\u2019Europe, que l\u2019IA est partout pr\u00e9sente et que les dangers qu\u2019elle pr\u00e9sente pour l\u2019\u00e9ducation et, au-del\u00e0, pour l\u2019intelligence humaine sont aussi r\u00e9els que savamment d\u00e9ni\u00e9s. Enfin, \u00e0 quoi doit servir et \u00e0 quoi doit se limiter l\u2019IA, sp\u00e9cifiquement dans le domaine de l\u2019\u00e9ducation, un d\u00e9bat plus que jamais ouvert.<\/p>\n","protected":false},"author":20,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[3],"tags":[],"class_list":["post-2091","post","type-post","status-publish","format-standard","hentry","category-unkategorisiert","topic-bildung","format-text-de"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>L\u2019intelligence artificielle : quelles ambitions pour quels r\u00e9sultats ? - Improof<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dev.improof.lu\/de\/articles\/intelligence-artificielle\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"L\u2019intelligence artificielle : quelles ambitions pour quels r\u00e9sultats ?\" \/>\n<meta property=\"og:description\" content=\"Le pr\u00e9sent article se donne pour objectif de cerner les ambitions, mais aussi les dangers que repr\u00e9sente l\u2019IA dans le secteur sp\u00e9cifique de l\u2019\u00e9ducation. Nous verrons, en d\u00e9pit de la r\u00e9cente adoption de l\u2019Artifical Intelligence Act par l\u2019ensemble des \u00c9tats membres de l\u2019Europe, que l\u2019IA est partout pr\u00e9sente et que les dangers qu\u2019elle pr\u00e9sente pour l\u2019\u00e9ducation et, au-del\u00e0, pour l\u2019intelligence humaine sont aussi r\u00e9els que savamment d\u00e9ni\u00e9s. Enfin, \u00e0 quoi doit servir et \u00e0 quoi doit se limiter l\u2019IA, sp\u00e9cifiquement dans le domaine de l\u2019\u00e9ducation, un d\u00e9bat plus que jamais ouvert.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dev.improof.lu\/de\/articles\/intelligence-artificielle\/\" \/>\n<meta property=\"og:site_name\" content=\"Improof\" \/>\n<meta property=\"article:published_time\" content=\"2024-07-25T12:50:26+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-07-25T12:50:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dev.improof.lu\/app\/uploads\/2024\/07\/Sans-titre.jpg\" \/>\n<meta name=\"author\" content=\"Renata Santini\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"L\u2019intelligence artificielle : quelles ambitions pour quels r\u00e9sultats ?\" \/>\n<meta name=\"twitter:description\" content=\"Le pr\u00e9sent article se donne pour objectif de cerner les ambitions, mais aussi les dangers que repr\u00e9sente l\u2019IA dans le secteur sp\u00e9cifique de l\u2019\u00e9ducation. Nous verrons, en d\u00e9pit de la r\u00e9cente adoption de l\u2019Artifical Intelligence Act par l\u2019ensemble des \u00c9tats membres de l\u2019Europe, que l\u2019IA est partout pr\u00e9sente et que les dangers qu\u2019elle pr\u00e9sente pour l\u2019\u00e9ducation et, au-del\u00e0, pour l\u2019intelligence humaine sont aussi r\u00e9els que savamment d\u00e9ni\u00e9s. Enfin, \u00e0 quoi doit servir et \u00e0 quoi doit se limiter l\u2019IA, sp\u00e9cifiquement dans le domaine de l\u2019\u00e9ducation, un d\u00e9bat plus que jamais ouvert.\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/dev.improof.lu\/app\/uploads\/2024\/07\/Sans-titre.jpg\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Renata Santini\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"25 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/dev.improof.lu\/de\/articles\/intelligence-artificielle\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dev.improof.lu\/de\/articles\/intelligence-artificielle\/\"},\"author\":{\"name\":\"Renata Santini\",\"@id\":\"https:\/\/dev.improof.lu\/de\/#\/schema\/person\/6063d9406f45fcc1dcb5892220ca0f23\"},\"headline\":\"L\u2019intelligence artificielle : quelles ambitions pour quels r\u00e9sultats ?\",\"datePublished\":\"2024-07-25T12:50:26+00:00\",\"dateModified\":\"2024-07-25T12:50:27+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dev.improof.lu\/de\/articles\/intelligence-artificielle\/\"},\"wordCount\":4952,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dev.improof.lu\/de\/#organization\"},\"articleSection\":[\"Unkategorisiert\"],\"inLanguage\":\"de-DE\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dev.improof.lu\/de\/articles\/intelligence-artificielle\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dev.improof.lu\/de\/articles\/intelligence-artificielle\/\",\"url\":\"https:\/\/dev.improof.lu\/de\/articles\/intelligence-artificielle\/\",\"name\":\"L\u2019intelligence artificielle : quelles ambitions pour quels r\u00e9sultats ? - Improof\",\"isPartOf\":{\"@id\":\"https:\/\/dev.improof.lu\/de\/#website\"},\"datePublished\":\"2024-07-25T12:50:26+00:00\",\"dateModified\":\"2024-07-25T12:50:27+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/dev.improof.lu\/de\/articles\/intelligence-artificielle\/#breadcrumb\"},\"inLanguage\":\"de-DE\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dev.improof.lu\/de\/articles\/intelligence-artificielle\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dev.improof.lu\/de\/articles\/intelligence-artificielle\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/dev.improof.lu\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"L\u2019intelligence artificielle : quelles ambitions pour quels r\u00e9sultats ?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dev.improof.lu\/de\/#website\",\"url\":\"https:\/\/dev.improof.lu\/de\/\",\"name\":\"Improof\",\"description\":\"Tagline goes here\",\"publisher\":{\"@id\":\"https:\/\/dev.improof.lu\/de\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dev.improof.lu\/de\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de-DE\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/dev.improof.lu\/de\/#organization\",\"name\":\"Improof\",\"url\":\"https:\/\/dev.improof.lu\/de\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\/\/dev.improof.lu\/de\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dev.improof.lu\/app\/uploads\/2022\/10\/improof-logo-svg.png\",\"contentUrl\":\"https:\/\/dev.improof.lu\/app\/uploads\/2022\/10\/improof-logo-svg.png\",\"width\":652,\"height\":209,\"caption\":\"Improof\"},\"image\":{\"@id\":\"https:\/\/dev.improof.lu\/de\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dev.improof.lu\/de\/#\/schema\/person\/6063d9406f45fcc1dcb5892220ca0f23\",\"name\":\"Renata Santini\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\/\/dev.improof.lu\/de\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/6740c58e3dbd2bb13dd48cf0ff004e6d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/6740c58e3dbd2bb13dd48cf0ff004e6d?s=96&d=mm&r=g\",\"caption\":\"Renata Santini\"},\"sameAs\":[\"http:\/\/www.csl.lu\"],\"url\":\"https:\/\/dev.improof.lu\/de\/articles\/author\/renata-santini\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"L\u2019intelligence artificielle : quelles ambitions pour quels r\u00e9sultats ? - Improof","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dev.improof.lu\/de\/articles\/intelligence-artificielle\/","og_locale":"de_DE","og_type":"article","og_title":"L\u2019intelligence artificielle : quelles ambitions pour quels r\u00e9sultats ?","og_description":"Le pr\u00e9sent article se donne pour objectif de cerner les ambitions, mais aussi les dangers que repr\u00e9sente l\u2019IA dans le secteur sp\u00e9cifique de l\u2019\u00e9ducation. Nous verrons, en d\u00e9pit de la r\u00e9cente adoption de l\u2019Artifical Intelligence Act par l\u2019ensemble des \u00c9tats membres de l\u2019Europe, que l\u2019IA est partout pr\u00e9sente et que les dangers qu\u2019elle pr\u00e9sente pour l\u2019\u00e9ducation et, au-del\u00e0, pour l\u2019intelligence humaine sont aussi r\u00e9els que savamment d\u00e9ni\u00e9s. Enfin, \u00e0 quoi doit servir et \u00e0 quoi doit se limiter l\u2019IA, sp\u00e9cifiquement dans le domaine de l\u2019\u00e9ducation, un d\u00e9bat plus que jamais ouvert.","og_url":"https:\/\/dev.improof.lu\/de\/articles\/intelligence-artificielle\/","og_site_name":"Improof","article_published_time":"2024-07-25T12:50:26+00:00","article_modified_time":"2024-07-25T12:50:27+00:00","og_image":[{"url":"https:\/\/dev.improof.lu\/app\/uploads\/2024\/07\/Sans-titre.jpg"}],"author":"Renata Santini","twitter_card":"summary_large_image","twitter_title":"L\u2019intelligence artificielle : quelles ambitions pour quels r\u00e9sultats ?","twitter_description":"Le pr\u00e9sent article se donne pour objectif de cerner les ambitions, mais aussi les dangers que repr\u00e9sente l\u2019IA dans le secteur sp\u00e9cifique de l\u2019\u00e9ducation. Nous verrons, en d\u00e9pit de la r\u00e9cente adoption de l\u2019Artifical Intelligence Act par l\u2019ensemble des \u00c9tats membres de l\u2019Europe, que l\u2019IA est partout pr\u00e9sente et que les dangers qu\u2019elle pr\u00e9sente pour l\u2019\u00e9ducation et, au-del\u00e0, pour l\u2019intelligence humaine sont aussi r\u00e9els que savamment d\u00e9ni\u00e9s. Enfin, \u00e0 quoi doit servir et \u00e0 quoi doit se limiter l\u2019IA, sp\u00e9cifiquement dans le domaine de l\u2019\u00e9ducation, un d\u00e9bat plus que jamais ouvert.","twitter_image":"https:\/\/dev.improof.lu\/app\/uploads\/2024\/07\/Sans-titre.jpg","twitter_misc":{"Written by":"Renata Santini","Est. reading time":"25 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/dev.improof.lu\/de\/articles\/intelligence-artificielle\/#article","isPartOf":{"@id":"https:\/\/dev.improof.lu\/de\/articles\/intelligence-artificielle\/"},"author":{"name":"Renata Santini","@id":"https:\/\/dev.improof.lu\/de\/#\/schema\/person\/6063d9406f45fcc1dcb5892220ca0f23"},"headline":"L\u2019intelligence artificielle : quelles ambitions pour quels r\u00e9sultats ?","datePublished":"2024-07-25T12:50:26+00:00","dateModified":"2024-07-25T12:50:27+00:00","mainEntityOfPage":{"@id":"https:\/\/dev.improof.lu\/de\/articles\/intelligence-artificielle\/"},"wordCount":4952,"commentCount":0,"publisher":{"@id":"https:\/\/dev.improof.lu\/de\/#organization"},"articleSection":["Unkategorisiert"],"inLanguage":"de-DE","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dev.improof.lu\/de\/articles\/intelligence-artificielle\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/dev.improof.lu\/de\/articles\/intelligence-artificielle\/","url":"https:\/\/dev.improof.lu\/de\/articles\/intelligence-artificielle\/","name":"L\u2019intelligence artificielle : quelles ambitions pour quels r\u00e9sultats ? - Improof","isPartOf":{"@id":"https:\/\/dev.improof.lu\/de\/#website"},"datePublished":"2024-07-25T12:50:26+00:00","dateModified":"2024-07-25T12:50:27+00:00","breadcrumb":{"@id":"https:\/\/dev.improof.lu\/de\/articles\/intelligence-artificielle\/#breadcrumb"},"inLanguage":"de-DE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dev.improof.lu\/de\/articles\/intelligence-artificielle\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/dev.improof.lu\/de\/articles\/intelligence-artificielle\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/dev.improof.lu\/de\/"},{"@type":"ListItem","position":2,"name":"L\u2019intelligence artificielle : quelles ambitions pour quels r\u00e9sultats ?"}]},{"@type":"WebSite","@id":"https:\/\/dev.improof.lu\/de\/#website","url":"https:\/\/dev.improof.lu\/de\/","name":"Improof","description":"Tagline goes here","publisher":{"@id":"https:\/\/dev.improof.lu\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dev.improof.lu\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de-DE"},{"@type":"Organization","@id":"https:\/\/dev.improof.lu\/de\/#organization","name":"Improof","url":"https:\/\/dev.improof.lu\/de\/","logo":{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/dev.improof.lu\/de\/#\/schema\/logo\/image\/","url":"https:\/\/dev.improof.lu\/app\/uploads\/2022\/10\/improof-logo-svg.png","contentUrl":"https:\/\/dev.improof.lu\/app\/uploads\/2022\/10\/improof-logo-svg.png","width":652,"height":209,"caption":"Improof"},"image":{"@id":"https:\/\/dev.improof.lu\/de\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/dev.improof.lu\/de\/#\/schema\/person\/6063d9406f45fcc1dcb5892220ca0f23","name":"Renata Santini","image":{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/dev.improof.lu\/de\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/6740c58e3dbd2bb13dd48cf0ff004e6d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6740c58e3dbd2bb13dd48cf0ff004e6d?s=96&d=mm&r=g","caption":"Renata Santini"},"sameAs":["http:\/\/www.csl.lu"],"url":"https:\/\/dev.improof.lu\/de\/articles\/author\/renata-santini\/"}]}},"_links":{"self":[{"href":"https:\/\/dev.improof.lu\/de\/wp-json\/wp\/v2\/posts\/2091","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.improof.lu\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dev.improof.lu\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dev.improof.lu\/de\/wp-json\/wp\/v2\/users\/20"}],"replies":[{"embeddable":true,"href":"https:\/\/dev.improof.lu\/de\/wp-json\/wp\/v2\/comments?post=2091"}],"version-history":[{"count":1,"href":"https:\/\/dev.improof.lu\/de\/wp-json\/wp\/v2\/posts\/2091\/revisions"}],"predecessor-version":[{"id":2093,"href":"https:\/\/dev.improof.lu\/de\/wp-json\/wp\/v2\/posts\/2091\/revisions\/2093"}],"wp:attachment":[{"href":"https:\/\/dev.improof.lu\/de\/wp-json\/wp\/v2\/media?parent=2091"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dev.improof.lu\/de\/wp-json\/wp\/v2\/categories?post=2091"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dev.improof.lu\/de\/wp-json\/wp\/v2\/tags?post=2091"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}