{"id":2204,"date":"2024-10-31T09:53:53","date_gmt":"2024-10-31T09:53:53","guid":{"rendered":"https:\/\/dev.improof.lu\/?p=2204"},"modified":"2024-10-31T09:53:54","modified_gmt":"2024-10-31T09:53:54","slug":"inegalites-de-genre-pensions","status":"publish","type":"post","link":"https:\/\/dev.improof.lu\/de\/articles\/inegalites-de-genre-pensions\/","title":{"rendered":"R\u00e9duire l\u2019\u00e9cart de genre au niveau des pensions : un imp\u00e9ratif social"},"content":{"rendered":"<p>Dans le cadre des discussions sur une potentielle r\u00e9forme des pensions, l\u2019\u00e9cart persistant entre les pensions des hommes et des femmes reste une probl\u00e9matique encore trop souvent sous-estim\u00e9e et doit \u00eatre un sujet d\u2019importance.<\/p>\n<p>Bien que les in\u00e9galit\u00e9s de pensions ne soient pas directement imputables au syst\u00e8me de pension, mais plut\u00f4t aux in\u00e9galit\u00e9s survenues tout au long de la vie professionnelle, leur ampleur reste trop importante pour ne pas \u00eatre abord\u00e9e.<\/p>\n<h2>1. In\u00e9galit\u00e9s actuelles : quel est le point de d\u00e9part ?<\/h2>\n<p>Les pensions de vieillesse (anticip\u00e9es[1]) sont, en effet, tr\u00e8s clairement sup\u00e9rieures pour les hommes que pour les femmes. Si on consid\u00e8re l\u2019ensemble des b\u00e9n\u00e9ficiaires d\u2019une pension de vieillesse, il s\u2019av\u00e8re que les pensions des femmes s\u2019\u00e9l\u00e8vent, en moyenne, \u00e0 1 946 euros, soit 26,9% (717 euros) inf\u00e9rieures aux pensions des hommes.<\/p>\n<p>Du fait qu\u2019une partie des b\u00e9n\u00e9ficiaires ont une carri\u00e8re dite migratoire, c\u2019est-\u00e0-dire qu\u2019ils ont travaill\u00e9 dans au moins deux pays, et que, d\u00e8s lors, certaines carri\u00e8res ne sont gu\u00e8re comparables, il est important de compl\u00e9ter l\u2019analyse en \u00e9tudiant uniquement les pensionn\u00e9s avec une carri\u00e8re purement luxembourgeoise (non-migratoire). Ici, les in\u00e9galit\u00e9s de genre sont consid\u00e9rablement sup\u00e9rieures qu\u2019au niveau total : en moyenne, les femmes avec une carri\u00e8re purement luxembourgeoise per\u00e7oivent une pension de vieillesse de moins de 2 600 euros, un niveau qui est 42,2% (1 900 euros) inf\u00e9rieur \u00e0 celui des hommes avec une carri\u00e8re non-migratoire.<\/p>\n<p>Parmi les b\u00e9n\u00e9ficiaires d\u2019une pension de vieillesse r\u00e9sidant au Luxembourg et ind\u00e9pendamment d\u2019une carri\u00e8re professionnelle frontali\u00e8re ou non, les femmes ont des pensions qui sont 39,4% (soit 1 600 euros) inf\u00e9rieures \u00e0 celles des hommes.<\/p>\n<p><em><strong>Graphique 1 : In\u00e9galit\u00e9s au niveau des pensions de vieillesse moyennes, 2022<\/strong><\/em><\/p>\n<p><img decoding=\"async\" src=\"https:\/\/dev.improof.lu\/app\/uploads\/2024\/10\/Graf1_true.jpg\" \/><\/p>\n<p><span style=\"font-size: 8pt;\">Source : Inspection g\u00e9n\u00e9rale de la s\u00e9curit\u00e9 sociale<\/span><\/p>\n<p>Cette in\u00e9galit\u00e9, visible au niveau des moyennes, est tout aussi apparente lorsque l\u2019on \u00e9tudie la r\u00e9partition des pensions de mani\u00e8re plus g\u00e9n\u00e9rale. Dans le graphique ci-dessous qui reprend la r\u00e9partition des pensions de vieillesse des carri\u00e8res non-migratoires, il est clairement observable que les niveaux de pension inf\u00e9rieurs \u00e0 3 100 euros sont plus fr\u00e9quents chez les femmes, tandis que les niveaux au-del\u00e0 de 3 100 euros sont plus r\u00e9pandus chez les hommes.<\/p>\n<p><em><strong>Graphique 2 : R\u00e9partition des pensions de vieillesse de carri\u00e8res non-migratoires, 2022<\/strong><\/em><\/p>\n<p><img decoding=\"async\" src=\"https:\/\/dev.improof.lu\/app\/uploads\/2024\/10\/graf2.jpg\" \/><\/p>\n<p><span style=\"font-size: 8pt;\">Source : Inspection g\u00e9n\u00e9rale de la s\u00e9curit\u00e9 sociale<\/span><\/p>\n<p>Force est de constater que parmi l\u2019ensemble des b\u00e9n\u00e9ficiaires d\u2019une pension de vieillesse, 32,0% des femmes ont des pensions inf\u00e9rieures \u00e0 2 000 euros alors que ce taux ne s\u2019\u00e9l\u00e8ve qu\u2019\u00e0 3,3% chez les hommes. En revanche, plus d\u2019un tiers des pensions des hommes sont au-del\u00e0 de 5 000 euros alors seules 7,6% des femmes per\u00e7oivent un tel niveau de pension.<\/p>\n<p>Le fait que les femmes soient surrepr\u00e9sent\u00e9es au sein des b\u00e9n\u00e9ficiaires de tr\u00e8s faibles pensions de vieillesse explique d\u2019ailleurs que parmi les environ 36 000 b\u00e9n\u00e9ficiaires d\u2019un compl\u00e9ment pour pension minimum, 79,3% sont des femmes.<\/p>\n<p>L\u2019in\u00e9galit\u00e9 de genre au niveau des pensions n\u2019est certes pas un ph\u00e9nom\u00e8ne purement luxembourgeois, mais le concept harmonis\u00e9 au niveau europ\u00e9en de Gender Pension Gap permet de montrer que le Luxembourg est le pays connaissant la plus grande in\u00e9galit\u00e9 apr\u00e8s la Malte et les Pays-Bas.<\/p>\n<p><em><strong>Graphique 3 : Gender pension gap, 2023<\/strong><\/em><\/p>\n<p><img decoding=\"async\" src=\"https:\/\/dev.improof.lu\/app\/uploads\/2024\/10\/graf3.jpg\" \/><\/p>\n<p><span style=\"font-size: 8pt;\">Source : Eurostat<\/span><\/p>\n<h2>2. Raisons pour l\u2019in\u00e9galit\u00e9 au niveau des pensions<\/h2>\n<p>En ce qui concerne les raisons pour l\u2019in\u00e9galit\u00e9 de genre au niveau des pensions, il convient de noter que celles-ci ne sont pas dues \u00e0 des in\u00e9galit\u00e9s intrins\u00e8ques du syst\u00e8me de pensions, mais qu\u2019il s\u2019agit d\u2019un prolongement d\u2019in\u00e9galit\u00e9s au cours de la vie active.<\/p>\n<p>En effet, les pensionn\u00e9es actuelles, c\u2019est-\u00e0-dire les actives d\u2019il y a quelques ann\u00e9es, voire d\u00e9cennies, avaient, en moyenne, un taux d\u2019emploi significativement inf\u00e9rieur \u00e0 celui des hommes. En 1995 par exemple, 79% des hommes entre 15 et 59 ans \u00e9taient en emploi tandis que chez les femmes ce taux ne s\u2019\u00e9levait qu\u2019\u00e0 45%.<\/p>\n<p>La tr\u00e8s forte in\u00e9galit\u00e9 au niveau du taux d\u2019emploi et, par ricochet, des p\u00e9riodes contributives, au cours des derni\u00e8res d\u00e9cennies se traduit aujourd\u2019hui en in\u00e9galit\u00e9 au niveau des pensions.<\/p>\n<p><em><strong>Graphique 4 : \u00c9volution du taux d\u2019emploi par sexe pour les 15-59 ans<\/strong><\/em><\/p>\n<p><img decoding=\"async\" src=\"https:\/\/dev.improof.lu\/app\/uploads\/2024\/10\/graf4.jpg\" \/><\/p>\n<p><span style=\"font-size: 8pt;\">Source : Eurostat<\/span><\/p>\n<p>Ce taux d\u2019emploi inf\u00e9rieur pour les femmes explique que les carri\u00e8res d\u2019assurance sont consid\u00e9rablement plus courtes pour les femmes que pour les hommes. Ainsi, parmi les pensionn\u00e9s, les femmes affichent en moyenne une p\u00e9riode de stage dans l\u2019assurance pension de 37,8 ans (p\u00e9riodes compl\u00e9mentaires comprises) contre 41,0 ans en moyenne pour les hommes.<\/p>\n<p>Il s\u2019ajoute que les p\u00e9riodes compl\u00e9mentaires (comme les p\u00e9riodes d\u2019\u00e9ducation pour les enfants, les p\u00e9riodes d\u2019\u00e9tudes, etc.) qui ne donnent pas lieu au paiement de cotisations repr\u00e9sentent une part plus importante de la carri\u00e8re d\u2019assurance chez les femmes : ces p\u00e9riodes repr\u00e9sentent 6,9% (2,6 ans) des carri\u00e8res des femmes, mais seulement 1,7% (0,7 an) de la carri\u00e8re des hommes en moyenne chez les pensionn\u00e9s actuels. Or, \u00e9tant donn\u00e9 que pendant les p\u00e9riodes compl\u00e9mentaires, il n&#8217;y a pas de paiement de cotisations, ces p\u00e9riodes sont bien prises en compte pour d\u00e9terminer le moment de l\u2019ouverture du droit \u00e0 la pension, mais elles n\u2019ont pas d\u2019impact sur le niveau de la pension[2].<\/p>\n<p>\u00c0 c\u00f4t\u00e9 de la plus courte dur\u00e9e de carri\u00e8re et le fait qu\u2019une plus grande partie de la carri\u00e8re n\u2019ait pas donn\u00e9 lieu au versement de cotisations, le recours au temps partiel repr\u00e9sente une autre raison expliquant les \u00e9carts de pension entre hommes et femmes. En effet, m\u00eame parmi la population en emploi qui est d\u00e9j\u00e0 proportionnellement plus restreinte chez les femmes que chez les hommes, le recours au temps partiel \u00e9tait par le pass\u00e9 (et l\u2019est toujours) consid\u00e9rablement plus important chez les femmes de sorte que les revenus sur lesquels sont pay\u00e9es les cotisations sont plus faibles. Ainsi, le temps partiel, et les plus faibles niveaux de salaire qui vont avec, explique aussi une partie de l\u2019in\u00e9galit\u00e9 observ\u00e9e aujourd\u2019hui au niveau des pensions.<\/p>\n<p><em><strong>Graphique 5 : \u00c9volution du taux de temps partiels pour les 15-59 ans<\/strong><\/em><\/p>\n<p><img decoding=\"async\" src=\"https:\/\/dev.improof.lu\/app\/uploads\/2024\/10\/graf5.jpg\" \/><\/p>\n<p><span style=\"font-size: 8pt;\">Source : Eurostat<\/span><\/p>\n<p>Aux effets de structure de l\u2019emploi (moindre taux d\u2019activit\u00e9 et plus de temps partiels) s\u2019ajoute que des in\u00e9galit\u00e9s salariales (plus de femmes dans des emplois peu r\u00e9mun\u00e9rateurs, moins de primes\/bonus, moins de salaire pour un m\u00eame emploi) au cours des derni\u00e8res d\u00e9cennies conduisent \u00e0 des pensions plus \u00e9lev\u00e9es pour les hommes que pour les femmes.<\/p>\n<h2>3. Tendances des in\u00e9galit\u00e9s actuelles<\/h2>\n<p>Bien que le niveau des in\u00e9galit\u00e9s de pensions est vertigineusement \u00e9lev\u00e9, il convient de noter que les in\u00e9galit\u00e9s observ\u00e9es aujourd\u2019hui sont d\u00e9j\u00e0 en baisse depuis les derni\u00e8res ann\u00e9es.<\/p>\n<p>En effet, en analysant l\u2019\u00e9volution des in\u00e9galit\u00e9s de genre au niveau des pensions de vieillesse, force est de constater que celles-ci \u00e9taient (encore) plus importantes autrefois.<\/p>\n<p>Pour ce qui est de l\u2019ensemble des b\u00e9n\u00e9ficiaires d\u2019une pension de vieillesse (carri\u00e8res frontali\u00e8res ou non, r\u00e9sidents ou non), les femmes avaient un niveau de pension moyen inf\u00e9rieur de 44,4% au niveau per\u00e7u par les hommes en 2001 \u2013 contre un \u00e9cart de \u00ab seulement \u00bb 26,9% en 2022. Autrement dit, l\u2019\u00e9cart s\u2019est r\u00e9duit de 17,5 points de pourcentage au cours des deux derni\u00e8res d\u00e9cennies, ce qui \u00e9quivaut \u00e0 une baisse des in\u00e9galit\u00e9s de 39,4%.<\/p>\n<p>En analysant les b\u00e9n\u00e9ficiaires de pensions de vieillesse avec une carri\u00e8re purement luxembourgeoise pour \u00e9viter de comparer des niveaux de pensions incomparables, le constat selon lequel les in\u00e9galit\u00e9s de genre au niveau de la pension sont \u00e0 la baisse reste valide. En effet, en 2010, les pensions de vieillesse des femmes avec une pension purement luxembourgeoise \u00e9taient 51,8% inf\u00e9rieures \u00e0 celle des hommes en moyenne \u2013 aujourd\u2019hui ce taux s\u2019\u00e9l\u00e8ve \u00e0 42,2% et est donc en baisse de 18,5% (soit 9,6 points de pourcentage).<\/p>\n<p>Cette analyse reste valide si on ne consid\u00e8re que les b\u00e9n\u00e9ficiaires r\u00e9sidents d\u2019une pension de vieillesse. Pour ceux-ci, l\u2019in\u00e9galit\u00e9 a baiss\u00e9 de 21,2% depuis 2010, ce qui correspond \u00e0 une r\u00e9duction de l\u2019\u00e9cart des pensions des femmes et des hommes de plus de dix points de pourcentage.<\/p>\n<p><em><strong>Graphique 6-8 : \u00c9volution des in\u00e9galit\u00e9s de pensions entre hommes et femmes pour 1) le total des b\u00e9n\u00e9ficiaires, les seuls b\u00e9n\u00e9ficiaires avec une carri\u00e8re non-migratoire et les seuls b\u00e9n\u00e9ficiaires r\u00e9sidents<\/strong><\/em><\/p>\n<p><img decoding=\"async\" src=\"https:\/\/dev.improof.lu\/app\/uploads\/2024\/10\/graf6.jpg\" \/><\/p>\n<p><span style=\"font-size: 8pt;\">Source : Inspection g\u00e9n\u00e9rale de la s\u00e9curit\u00e9 sociale<\/span><\/p>\n<p>Les in\u00e9galit\u00e9s au niveau des pensions connaissent donc une tendance baissi\u00e8re au cours des derni\u00e8res ann\u00e9es. Sachant que les pensions pay\u00e9es sont un stock et que seulement une partie de ce stock se renouvelle annuellement (du fait du d\u00e9c\u00e8s des uns et de l\u2019entr\u00e9e en pension des autres), la baisse g\u00e9n\u00e9ralis\u00e9e est due \u00e0 une diminution des in\u00e9galit\u00e9s au niveau des pensions de vieillesse nouvellement attribu\u00e9es.<\/p>\n<p>Cette r\u00e9duction est en grande partie due \u00e0 la hausse du taux d\u2019emploi des femmes au cours des derni\u00e8res ann\u00e9es, m\u00eame si leur recours au temps partiel a augment\u00e9. La baisse de l\u2019\u00e9cart du niveau de pension est certainement aussi li\u00e9e \u00e0 la tendance vers une plus grande \u00e9galisation dans le march\u00e9 du travail.<\/p>\n<p>Qui plus est, les p\u00e9riodes compl\u00e9mentaires repr\u00e9sentent une part de moins en moins importante de la carri\u00e8re d\u2019assurance des femmes, alors m\u00eame que la prolongation g\u00e9n\u00e9ralis\u00e9e de la dur\u00e9e des \u00e9tudes sup\u00e9rieures devrait avoir un effet haussier sur le nombre de ces p\u00e9riodes compl\u00e9mentaires. Pour les pensions nouvellement attribu\u00e9es, les p\u00e9riodes compl\u00e9mentaires repr\u00e9sentent 5,5% (2,1 ans) des ann\u00e9es d\u2019assurance des femmes, contre 6,9% (2,6 ans) pour l\u2019ensemble des pensions aux femmes en cours de paiement \u2013 signe sans doute de la baisse des interruptions de carri\u00e8re pour l\u2019\u00e9ducation des enfants (\u00e2g\u00e9s de moins de 6 ans). Chez les hommes, la partie de la carri\u00e8re due \u00e0 des p\u00e9riodes compl\u00e9mentaires a tendance \u00e0 augmenter et se situe dor\u00e9navant \u00e0 2,9% (1,2 an) pour les pensions nouvellement attribu\u00e9es.<\/p>\n<h2>4. Quelles perspectives pour les in\u00e9galit\u00e9s dans le futur ?<\/h2>\n<p>Bien que les in\u00e9galit\u00e9s au niveau des pensions entre hommes et femmes tendent \u00e0 diminuer, force est de constater qu\u2019elles risquent de perdurer \u2013 m\u00eame si \u00e0 un niveau inf\u00e9rieur.<\/p>\n<p>Le taux d\u2019emploi des femmes \u00e9tant toujours fortement inf\u00e9rieur au taux d\u2019emploi des hommes (voir graphique 4) et le temps partiel \u00e9tant toujours consid\u00e9rablement plus important chez les femmes que chez les hommes (voir graphique 5), il est \u00e9vident que dans le futur, les pensions des hommes seront toujours sup\u00e9rieures en moyenne \u00e0 celles des femmes. En effet, \u00e9tant donn\u00e9 que la pension de vieillesse d\u00e9pend principalement du niveau de revenu cotisable, le fait que les femmes ont des revenus annuels inf\u00e9rieurs \u00e0 ceux des hommes ne m\u00e8nera certainement pas \u00e0 l\u2019\u00e9galit\u00e9 au niveau des pensions.<\/p>\n<p>Les in\u00e9galit\u00e9s de genre au niveau des pensions au Luxembourg, bien qu\u2019elles se r\u00e9duisent, demeurent et demeureront donc un probl\u00e8me structurel important.<\/p>\n<p>Les \u00e9carts observ\u00e9s aujourd\u2019hui sont le reflet de d\u00e9savantages cumul\u00e9s au cours des carri\u00e8res professionnelles des femmes, marqu\u00e9es par des interruptions plus fr\u00e9quentes, des p\u00e9riodes non-contributives, des emplois \u00e0 temps partiel et des niveaux de r\u00e9mun\u00e9ration inf\u00e9rieurs. Si bien que des progr\u00e8s ont \u00e9t\u00e9 r\u00e9alis\u00e9s en mati\u00e8re d&#8217;emploi f\u00e9minin, les \u00e9carts restent trop importants pour \u00eatre ignor\u00e9s.<\/p>\n<p>Vu le recours beaucoup plus r\u00e9current des femmes que des hommes au travail \u00e0 temps partiel, les disparit\u00e9s au niveau des pensions ne sont pas pr\u00eates \u00e0 dispara\u00eetre. La solution-cl\u00e9 pour y r\u00e9pondre serait une r\u00e9duction g\u00e9n\u00e9ralis\u00e9e de la dur\u00e9e du travail avec maintien du salaire \u00ab for\u00e7ant \u00bb les hommes \u00e0 consacrer plus de temps aux t\u00e2ches \u00ab care \u00bb et permettant aux femmes de travailler \u00e0 temps plein.<\/p>\n<p>M\u00eame si la source des in\u00e9galit\u00e9s actuelles est certes en amont du d\u00e9part \u00e0 la retraite, l\u2019ampleur du probl\u00e8me requiert qu\u2019il soit analys\u00e9 de pr\u00e8s lors de chaque discussion au niveau des pensions et des efforts pour r\u00e9duire ces in\u00e9galit\u00e9s sont indispensables.<\/p>\n<p>La hausse d\u2019une pension minimum qui est avant tout un \u00e9l\u00e9ment dont b\u00e9n\u00e9ficient les femmes, la promotion de l\u2019assurance volontaire en cas d\u2019interruption de carri\u00e8re et la simplification de la disposition pr\u00e9voyant qu\u2019en cas de divorce le conjoint participe aux co\u00fbts pour le rachat des p\u00e9riodes d\u2019assurance ne sont qu\u2019une s\u00e9lection parmi les nombreuses am\u00e9liorations possibles.<\/p>\n<p>En tout cas, la r\u00e9duction de dispositifs qui reviennent principalement au profit des femmes doit \u00eatre \u00e9vit\u00e9e de toute force. Ainsi, la revendication de la suppression des baby-years demand\u00e9e par le groupe patronal dans le cadre de l\u2019avis du Conseil \u00e9conomique et social relatif aux pensions est \u00e0 r\u00e9futer, sachant que 80% des b\u00e9n\u00e9ficiaires de ce r\u00e9gime sont des femmes.<\/p>\n<p>De m\u00eame, la non-reconnaissance des p\u00e9riodes compl\u00e9mentaires telles que les p\u00e9riodes d\u2019\u00e9ducation d\u2019un enfant \u00e2g\u00e9 de moins de six ans ou les p\u00e9riodes d\u2019\u00e9tudes est \u00e0 refuser \u2013 aujourd\u2019hui, les femmes profitent significativement plus de ces r\u00e9gimes que les hommes. Supprimer les baby-years et\/ou les p\u00e9riodes compl\u00e9mentaires revient, soit \u00e0 obliger les assur\u00e9s de prolonger leur carri\u00e8re d\u2019activit\u00e9, soit \u00e0 r\u00e9duire consid\u00e9rablement le niveau de pension des assur\u00e9s qui profitent de ces dispositifs.<\/p>\n<p>L\u2019extension des baby-years serait en fait \u00e0 l\u2019ordre du jour, mais non pas en les diluant tel que pr\u00e9vu par le programme gouvernemental, mais en les prolongeant sur base des dispositions actuellement en vigueur, c\u2019est-\u00e0-dire moyennant des cotisations au niveau du salaire pr\u00e9c\u00e9dent le d\u00e9but des baby-years.<\/p>\n<p>Par ailleurs, il y a lieu de r\u00e9fl\u00e9chir sur la n\u00e9cessit\u00e9 d\u2019instaurer le splitting des droits de pension acquis pendant la dur\u00e9e de vie en couple en cas de r\u00e9duction du temps de travail par l\u2019un des partenaires.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dans le cadre des discussions sur une potentielle r\u00e9forme des pensions, l\u2019\u00e9cart persistant entre les pensions des hommes et des femmes reste une probl\u00e9matique encore trop souvent sous-estim\u00e9e et doit \u00eatre un sujet d\u2019importance.<\/p>\n","protected":false},"author":11,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[3],"tags":[],"class_list":["post-2204","post","type-post","status-publish","format-standard","hentry","category-unkategorisiert","topic-sozialversicherung","topic-ungleichheiten","format-text-de"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>R\u00e9duire l\u2019\u00e9cart de genre au niveau des pensions : un imp\u00e9ratif social - Improof<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dev.improof.lu\/de\/articles\/inegalites-de-genre-pensions\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"R\u00e9duire l\u2019\u00e9cart de genre au niveau des pensions : un imp\u00e9ratif social\" \/>\n<meta property=\"og:description\" content=\"Dans le cadre des discussions sur une potentielle r\u00e9forme des pensions, l\u2019\u00e9cart persistant entre les pensions des hommes et des femmes reste une probl\u00e9matique encore trop souvent sous-estim\u00e9e et doit \u00eatre un sujet d\u2019importance.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dev.improof.lu\/de\/articles\/inegalites-de-genre-pensions\/\" \/>\n<meta property=\"og:site_name\" content=\"Improof\" \/>\n<meta property=\"article:published_time\" content=\"2024-10-31T09:53:53+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-10-31T09:53:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dev.improof.lu\/app\/uploads\/2024\/10\/pension.jpg\" \/>\n<meta name=\"author\" content=\"Nermin Plavsic\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"R\u00e9duire l\u2019\u00e9cart de genre au niveau des pensions : un imp\u00e9ratif social\" \/>\n<meta name=\"twitter:description\" content=\"Dans le cadre des discussions sur une potentielle r\u00e9forme des pensions, l\u2019\u00e9cart persistant entre les pensions des hommes et des femmes reste une probl\u00e9matique encore trop souvent sous-estim\u00e9e et doit \u00eatre un sujet d\u2019importance.\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/dev.improof.lu\/app\/uploads\/2024\/10\/pension.jpg\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Nermin Plavsic\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"12 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/dev.improof.lu\/de\/articles\/inegalites-de-genre-pensions\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dev.improof.lu\/de\/articles\/inegalites-de-genre-pensions\/\"},\"author\":{\"name\":\"Nermin Plavsic\",\"@id\":\"https:\/\/dev.improof.lu\/de\/#\/schema\/person\/8b7e0720f9ab34bd8b12af9dbf2592a6\"},\"headline\":\"R\u00e9duire l\u2019\u00e9cart de genre au niveau des pensions : un imp\u00e9ratif social\",\"datePublished\":\"2024-10-31T09:53:53+00:00\",\"dateModified\":\"2024-10-31T09:53:54+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dev.improof.lu\/de\/articles\/inegalites-de-genre-pensions\/\"},\"wordCount\":2493,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dev.improof.lu\/de\/#organization\"},\"image\":{\"@id\":\"https:\/\/dev.improof.lu\/de\/articles\/inegalites-de-genre-pensions\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dev.improof.lu\/app\/uploads\/2024\/10\/Graf1_true.jpg\",\"articleSection\":[\"Unkategorisiert\"],\"inLanguage\":\"de-DE\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dev.improof.lu\/de\/articles\/inegalites-de-genre-pensions\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dev.improof.lu\/de\/articles\/inegalites-de-genre-pensions\/\",\"url\":\"https:\/\/dev.improof.lu\/de\/articles\/inegalites-de-genre-pensions\/\",\"name\":\"R\u00e9duire l\u2019\u00e9cart de genre au niveau des pensions : un imp\u00e9ratif social - Improof\",\"isPartOf\":{\"@id\":\"https:\/\/dev.improof.lu\/de\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dev.improof.lu\/de\/articles\/inegalites-de-genre-pensions\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dev.improof.lu\/de\/articles\/inegalites-de-genre-pensions\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dev.improof.lu\/app\/uploads\/2024\/10\/Graf1_true.jpg\",\"datePublished\":\"2024-10-31T09:53:53+00:00\",\"dateModified\":\"2024-10-31T09:53:54+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/dev.improof.lu\/de\/articles\/inegalites-de-genre-pensions\/#breadcrumb\"},\"inLanguage\":\"de-DE\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dev.improof.lu\/de\/articles\/inegalites-de-genre-pensions\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\/\/dev.improof.lu\/de\/articles\/inegalites-de-genre-pensions\/#primaryimage\",\"url\":\"https:\/\/dev.improof.lu\/app\/uploads\/2024\/10\/Graf1_true.jpg\",\"contentUrl\":\"https:\/\/dev.improof.lu\/app\/uploads\/2024\/10\/Graf1_true.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dev.improof.lu\/de\/articles\/inegalites-de-genre-pensions\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/dev.improof.lu\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"R\u00e9duire l\u2019\u00e9cart de genre au niveau des pensions : un imp\u00e9ratif social\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dev.improof.lu\/de\/#website\",\"url\":\"https:\/\/dev.improof.lu\/de\/\",\"name\":\"Improof\",\"description\":\"Tagline goes here\",\"publisher\":{\"@id\":\"https:\/\/dev.improof.lu\/de\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dev.improof.lu\/de\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de-DE\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/dev.improof.lu\/de\/#organization\",\"name\":\"Improof\",\"url\":\"https:\/\/dev.improof.lu\/de\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\/\/dev.improof.lu\/de\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dev.improof.lu\/app\/uploads\/2022\/10\/improof-logo-svg.png\",\"contentUrl\":\"https:\/\/dev.improof.lu\/app\/uploads\/2022\/10\/improof-logo-svg.png\",\"width\":652,\"height\":209,\"caption\":\"Improof\"},\"image\":{\"@id\":\"https:\/\/dev.improof.lu\/de\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dev.improof.lu\/de\/#\/schema\/person\/8b7e0720f9ab34bd8b12af9dbf2592a6\",\"name\":\"Nermin Plavsic\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\/\/dev.improof.lu\/de\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/1b010c13286dbffe130fb77dd68cc999?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/1b010c13286dbffe130fb77dd68cc999?s=96&d=mm&r=g\",\"caption\":\"Nermin Plavsic\"},\"url\":\"https:\/\/dev.improof.lu\/de\/articles\/author\/nermin-plavsic\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"R\u00e9duire l\u2019\u00e9cart de genre au niveau des pensions : un imp\u00e9ratif social - Improof","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dev.improof.lu\/de\/articles\/inegalites-de-genre-pensions\/","og_locale":"de_DE","og_type":"article","og_title":"R\u00e9duire l\u2019\u00e9cart de genre au niveau des pensions : un imp\u00e9ratif social","og_description":"Dans le cadre des discussions sur une potentielle r\u00e9forme des pensions, l\u2019\u00e9cart persistant entre les pensions des hommes et des femmes reste une probl\u00e9matique encore trop souvent sous-estim\u00e9e et doit \u00eatre un sujet d\u2019importance.","og_url":"https:\/\/dev.improof.lu\/de\/articles\/inegalites-de-genre-pensions\/","og_site_name":"Improof","article_published_time":"2024-10-31T09:53:53+00:00","article_modified_time":"2024-10-31T09:53:54+00:00","og_image":[{"url":"https:\/\/dev.improof.lu\/app\/uploads\/2024\/10\/pension.jpg"}],"author":"Nermin Plavsic","twitter_card":"summary_large_image","twitter_title":"R\u00e9duire l\u2019\u00e9cart de genre au niveau des pensions : un imp\u00e9ratif social","twitter_description":"Dans le cadre des discussions sur une potentielle r\u00e9forme des pensions, l\u2019\u00e9cart persistant entre les pensions des hommes et des femmes reste une probl\u00e9matique encore trop souvent sous-estim\u00e9e et doit \u00eatre un sujet d\u2019importance.","twitter_image":"https:\/\/dev.improof.lu\/app\/uploads\/2024\/10\/pension.jpg","twitter_misc":{"Written by":"Nermin Plavsic","Est. reading time":"12 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/dev.improof.lu\/de\/articles\/inegalites-de-genre-pensions\/#article","isPartOf":{"@id":"https:\/\/dev.improof.lu\/de\/articles\/inegalites-de-genre-pensions\/"},"author":{"name":"Nermin Plavsic","@id":"https:\/\/dev.improof.lu\/de\/#\/schema\/person\/8b7e0720f9ab34bd8b12af9dbf2592a6"},"headline":"R\u00e9duire l\u2019\u00e9cart de genre au niveau des pensions : un imp\u00e9ratif social","datePublished":"2024-10-31T09:53:53+00:00","dateModified":"2024-10-31T09:53:54+00:00","mainEntityOfPage":{"@id":"https:\/\/dev.improof.lu\/de\/articles\/inegalites-de-genre-pensions\/"},"wordCount":2493,"commentCount":0,"publisher":{"@id":"https:\/\/dev.improof.lu\/de\/#organization"},"image":{"@id":"https:\/\/dev.improof.lu\/de\/articles\/inegalites-de-genre-pensions\/#primaryimage"},"thumbnailUrl":"https:\/\/dev.improof.lu\/app\/uploads\/2024\/10\/Graf1_true.jpg","articleSection":["Unkategorisiert"],"inLanguage":"de-DE","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dev.improof.lu\/de\/articles\/inegalites-de-genre-pensions\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/dev.improof.lu\/de\/articles\/inegalites-de-genre-pensions\/","url":"https:\/\/dev.improof.lu\/de\/articles\/inegalites-de-genre-pensions\/","name":"R\u00e9duire l\u2019\u00e9cart de genre au niveau des pensions : un imp\u00e9ratif social - Improof","isPartOf":{"@id":"https:\/\/dev.improof.lu\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dev.improof.lu\/de\/articles\/inegalites-de-genre-pensions\/#primaryimage"},"image":{"@id":"https:\/\/dev.improof.lu\/de\/articles\/inegalites-de-genre-pensions\/#primaryimage"},"thumbnailUrl":"https:\/\/dev.improof.lu\/app\/uploads\/2024\/10\/Graf1_true.jpg","datePublished":"2024-10-31T09:53:53+00:00","dateModified":"2024-10-31T09:53:54+00:00","breadcrumb":{"@id":"https:\/\/dev.improof.lu\/de\/articles\/inegalites-de-genre-pensions\/#breadcrumb"},"inLanguage":"de-DE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dev.improof.lu\/de\/articles\/inegalites-de-genre-pensions\/"]}]},{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/dev.improof.lu\/de\/articles\/inegalites-de-genre-pensions\/#primaryimage","url":"https:\/\/dev.improof.lu\/app\/uploads\/2024\/10\/Graf1_true.jpg","contentUrl":"https:\/\/dev.improof.lu\/app\/uploads\/2024\/10\/Graf1_true.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/dev.improof.lu\/de\/articles\/inegalites-de-genre-pensions\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/dev.improof.lu\/de\/"},{"@type":"ListItem","position":2,"name":"R\u00e9duire l\u2019\u00e9cart de genre au niveau des pensions : un imp\u00e9ratif social"}]},{"@type":"WebSite","@id":"https:\/\/dev.improof.lu\/de\/#website","url":"https:\/\/dev.improof.lu\/de\/","name":"Improof","description":"Tagline goes here","publisher":{"@id":"https:\/\/dev.improof.lu\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dev.improof.lu\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de-DE"},{"@type":"Organization","@id":"https:\/\/dev.improof.lu\/de\/#organization","name":"Improof","url":"https:\/\/dev.improof.lu\/de\/","logo":{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/dev.improof.lu\/de\/#\/schema\/logo\/image\/","url":"https:\/\/dev.improof.lu\/app\/uploads\/2022\/10\/improof-logo-svg.png","contentUrl":"https:\/\/dev.improof.lu\/app\/uploads\/2022\/10\/improof-logo-svg.png","width":652,"height":209,"caption":"Improof"},"image":{"@id":"https:\/\/dev.improof.lu\/de\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/dev.improof.lu\/de\/#\/schema\/person\/8b7e0720f9ab34bd8b12af9dbf2592a6","name":"Nermin Plavsic","image":{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/dev.improof.lu\/de\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/1b010c13286dbffe130fb77dd68cc999?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1b010c13286dbffe130fb77dd68cc999?s=96&d=mm&r=g","caption":"Nermin Plavsic"},"url":"https:\/\/dev.improof.lu\/de\/articles\/author\/nermin-plavsic\/"}]}},"_links":{"self":[{"href":"https:\/\/dev.improof.lu\/de\/wp-json\/wp\/v2\/posts\/2204","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.improof.lu\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dev.improof.lu\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dev.improof.lu\/de\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/dev.improof.lu\/de\/wp-json\/wp\/v2\/comments?post=2204"}],"version-history":[{"count":1,"href":"https:\/\/dev.improof.lu\/de\/wp-json\/wp\/v2\/posts\/2204\/revisions"}],"predecessor-version":[{"id":2206,"href":"https:\/\/dev.improof.lu\/de\/wp-json\/wp\/v2\/posts\/2204\/revisions\/2206"}],"wp:attachment":[{"href":"https:\/\/dev.improof.lu\/de\/wp-json\/wp\/v2\/media?parent=2204"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dev.improof.lu\/de\/wp-json\/wp\/v2\/categories?post=2204"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dev.improof.lu\/de\/wp-json\/wp\/v2\/tags?post=2204"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}