{"id":2473,"date":"2025-03-05T13:44:57","date_gmt":"2025-03-05T13:44:57","guid":{"rendered":"https:\/\/dev.improof.lu\/?p=2473"},"modified":"2025-03-05T13:44:57","modified_gmt":"2025-03-05T13:44:57","slug":"travail-changement-climatique","status":"publish","type":"post","link":"https:\/\/dev.improof.lu\/de\/articles\/travail-changement-climatique\/","title":{"rendered":"Adapter les lieux de travail au changement climatique"},"content":{"rendered":"<p>L&#8217;\u00e9t\u00e9 2024 a enregistr\u00e9 de <span style=\"text-decoration: underline;\"><em><a href=\"https:\/\/theconversation.com\/extreme-heat-is-breaking-global-records-why-this-isnt-just-summer-and-what-climate-change-has-to-do-with-it-234249\" target=\"_blank\" rel=\"noopener\">nouveaux records mondiaux<\/a><\/em><\/span> de vagues de chaleur, d&#8217;\u00e9v\u00e9nements climatiques extr\u00eames et d&#8217;incendies de for\u00eat dans des r\u00e9gions extr\u00eamement s\u00e8ches. D\u2019apr\u00e8s \u00ab Copernicus \u00bb, le 22 juillet 2024 a \u00e9t\u00e9 la <span style=\"text-decoration: underline;\"><em><a href=\"https:\/\/climate.copernicus.eu\/new-record-daily-global-average-temperature-reached-july-2024\" target=\"_blank\" rel=\"noopener\">journ\u00e9e la plus chaude<\/a><\/em><\/span> enregistr\u00e9e sur Terre dans l&#8217;histoire r\u00e9cente, surpassant un record \u00e9tabli la veille. L\u2019Europe est le continent qui se r\u00e9chauffe le plus rapidement, <span style=\"text-decoration: underline;\"><em><a href=\"https:\/\/www.eea.europa.eu\/en\/newsroom\/news\/europe-is-not-prepared-for\" target=\"_blank\" rel=\"noopener\">rapporte<\/a><\/em><\/span> l\u2019Agence europ\u00e9enne pour l\u2019environnement. Depuis les ann\u00e9es 1980, l\u2019Europe s\u2019est r\u00e9chauff\u00e9e \u00e0 environ deux fois le taux mondial.<\/p>\n<p>Le rapport r\u00e9cemment publi\u00e9 par le <span style=\"text-decoration: underline;\"><em><a href=\"https:\/\/www.socialeurope.eu\/cop28-must-focus-on-the-climate-fuelled-health-crisis\" target=\"_blank\" rel=\"noopener\">Lancet Countdown<\/a><\/em><\/span> pour l&#8217;Europe <span style=\"text-decoration: underline;\"><em><a href=\"https:\/\/www.thelancet.com\/journals\/lanpub\/article\/PIIS2468-2667(24)00055-0\/fulltext\" target=\"_blank\" rel=\"noopener\">d\u00e9montre<\/a><\/em><\/span> que le changement climatique affecte d\u00e9j\u00e0 les \u00eatres humains et les soci\u00e9t\u00e9s dans leur ensemble. Il se concentre sur les effets n\u00e9fastes sur la sant\u00e9, soulignant la n\u00e9cessit\u00e9 \u00ab d\u2019actions rapides de mitigation et d&#8217;adaptation climatique r\u00e9actives pour la sant\u00e9 \u00bb. Le lieu de travail est un domaine cl\u00e9 pour ces actions.<\/p>\n<h2>Directement affect\u00e9s<\/h2>\n<p>Les lieux de travail sont <span style=\"text-decoration: underline;\"><em><a href=\"https:\/\/www.socialeurope.eu\/heat-stress-at-work-a-political-emergency\" target=\"_blank\" rel=\"noopener\">directement affect\u00e9s<\/a><\/em><\/span> par le changement climatique. La hausse des temp\u00e9ratures et la multiplication des \u00e9v\u00e9nements climatiques extr\u00eames peuvent renforcer les <span style=\"text-decoration: underline;\"><em><a href=\"https:\/\/www.nature.com\/articles\/s41562-022-01467-8\" target=\"_blank\" rel=\"noopener\">risques physiques et psychosociaux<\/a><\/em><\/span> au travail, affectant aussi le bien-\u00eatre des travailleurs.\u00a0 M\u00eame des temp\u00e9ratures l\u00e9g\u00e8rement plus \u00e9lev\u00e9es peuvent affecter les <span style=\"text-decoration: underline;\"><em><a href=\"https:\/\/press.princeton.edu\/books\/hardcover\/9780691221038\/slow-burn?srsltid=AfmBOoqoC442-WwvN2n4-GYExKg8cipUb3dgjvSHSYUABxXGlmGI1i5I\" target=\"_blank\" rel=\"noopener\">performances cognitives<\/a><\/em><\/span> et la prise de d\u00e9cision, ainsi qu&#8217;augmenter le risque d&#8217;accidents et de blessures li\u00e9s au travail. Les travailleurs \u00e0 l\u2019ext\u00e9rieur, les travailleurs en int\u00e9rieur sans acc\u00e8s \u00e0 la climatisation et les travailleurs de premi\u00e8re ligne sont particuli\u00e8rement vuln\u00e9rables, comme le souligne le rapport du Lancet.<\/p>\n<p>Bien que les employeurs soient l\u00e9galement responsables de la sant\u00e9 et de la s\u00e9curit\u00e9 des travailleurs et soient tenus de r\u00e9aliser des \u00e9valuations des risques en vertu de la <a href=\"https:\/\/osha.europa.eu\/de\/legislation\/directives\/the-osh-framework-directive\/1\" target=\"_blank\" rel=\"noopener\">l\u00e9gislation<\/a> contraignante de l\u2019Union europ\u00e9enne, les repr\u00e9sentants du personnel et les syndicats jouent un r\u00f4le crucial dans la r\u00e9gulation des dangers au travail. Ils peuvent inciter les employeurs \u00e0 r\u00e9duire les dangers sur le lieu de travail, influencer le niveau de supervision r\u00e9glementaire et \u00e9duquer les travailleurs aux <span style=\"text-decoration: underline;\"><em><a href=\"https:\/\/lerawebillinois.web.illinois.edu\/index.php\/PFL\/article\/view\/581\" target=\"_blank\" rel=\"noopener\">risques professionnels<\/a><\/em><\/span>.<\/p>\n<p>De plus, les risques \u00e9mergents ou renforc\u00e9s li\u00e9s au changement climatique peuvent \u00eatre abord\u00e9s par le biais du dialogue social entre les employeurs et les syndicats au sein du lieu de travail ou au niveau sectoriel. Cela peut impliquer des <span style=\"text-decoration: underline;\"><em><a href=\"https:\/\/pubmed.ncbi.nlm.nih.gov\/26842343\/\" target=\"_blank\" rel=\"noopener\">mesures<\/a><\/em><\/span> telles que la r\u00e9duction du temps consacr\u00e9 \u00e0 des activit\u00e9s \u00e0 haute intensit\u00e9, l&#8217;introduction de p\u00e9riodes de repos plus longues ou l\u2019adaptation des horaires de travail.<\/p>\n<h2>\u00c9valuations des risques en milieu de travail<\/h2>\n<p>Malgr\u00e9 ces possibilit\u00e9s, les employeurs et les syndicats semblent <span style=\"text-decoration: underline;\"><em><a href=\"https:\/\/www.etui.org\/publications\/heatwaves-occupational-hazard\" target=\"_blank\" rel=\"noopener\">lents<\/a><\/em><\/span> \u00e0 int\u00e9grer l\u2019adaptation au changement climatique dans leurs politiques de s\u00e9curit\u00e9 et de sant\u00e9 au travail (SST), probablement parce qu&#8217;ils consid\u00e8rent encore les dangers li\u00e9s au changement climatique comme exceptionnels. Les \u00e9valuations obligatoires des risques en milieu de travail \u2014 un outil cl\u00e9 pour identifier et att\u00e9nuer les dangers conform\u00e9ment \u00e0 la l\u00e9gislation de l&#8217;UE \u2014 sont souvent mises en \u0153uvre <span style=\"text-decoration: underline;\"><em><a href=\"https:\/\/osha.europa.eu\/en\/publications\/summary-esener-2019-overview-report-how-european-workplaces-manage-safety-and-health\" target=\"_blank\" rel=\"noopener\">de mani\u00e8re in\u00e9gale<\/a><\/em><\/span>, selon les pays, les secteurs et les entreprises de tailles diff\u00e9rentes.<\/p>\n<p>Un <span style=\"text-decoration: underline;\"><em><a href=\"https:\/\/osha.europa.eu\/en\/publications\/summary-esener-2019-overview-report-how-european-workplaces-manage-safety-and-health\" target=\"_blank\" rel=\"noopener\">obstacle<\/a><\/em><\/span> majeur, selon l\u2019Agence europ\u00e9enne pour la s\u00e9curit\u00e9 et la sant\u00e9 au travail, r\u00e9side dans l\u2019id\u00e9e que les risques professionnels sont d\u00e9j\u00e0 bien identifi\u00e9s. Cela peut \u00eatre particuli\u00e8rement dangereux lorsqu\u2019il s&#8217;agit du changement climatique, compte tenu de l&#8217;ampleur et du caract\u00e8re cumulatif des changements en cours, qui risquent de devenir encore plus graves \u00e0 l\u2019avenir.<\/p>\n<p>Des indicateurs sp\u00e9cifiques au niveau des lieux de travail sont n\u00e9cessaires pour suivre les \u00e9volutions et permettre des initiatives d&#8217;adaptation sur mesure. Pour \u00e9largir la base de connaissances n\u00e9cessaires \u00e0 la prise de d\u00e9cision fond\u00e9e sur des donn\u00e9es probantes, des informations provenant des statistiques publiques sont n\u00e9cessaires. \u00c0 cette fin, des enqu\u00eates europ\u00e9ennes \u00e0 large \u00e9chantillon qui recueillent des informations dans divers pays et secteurs pourraient \u00eatre \u00e9largies.<\/p>\n<h2>Manque de connaissances d\u00e9taill\u00e9es<\/h2>\n<p>L\u2019Enqu\u00eate europ\u00e9enne des entreprises sur les risques nouveaux et \u00e9mergents (<span style=\"text-decoration: underline;\"><em><a href=\"https:\/\/osha.europa.eu\/en\/facts-and-figures\/esener\" target=\"_blank\" rel=\"noopener\">ESENER<\/a><\/em><\/span>) contient divers \u00e9l\u00e9ments sur les \u00e9valuations des risques. Ceux-ci pourraient \u00eatre \u00e9tendus pour recueillir des informations sur le nombre d\u2019entreprises int\u00e9grant des aspects li\u00e9s au climat.<\/p>\n<p>Bien qu\u2019il soit probable que les \u00e9valuations des risques dans des secteurs comme la construction, o\u00f9 le travail en ext\u00e9rieur pr\u00e9domine, incluent d\u00e9j\u00e0 des aspects tels que la chaleur ou l\u2019exposition aux radiations ultraviolettes, nous manquons de connaissances d\u00e9taill\u00e9es. Il reste \u00e9galement \u00e0 voir si ces aspects jouent un r\u00f4le dans les lieux de travail o\u00f9 la repr\u00e9sentation des employ\u00e9s et la culture de la SST sont plus faibles, en particulier dans les petites entreprises du secteur des services.<\/p>\n<p>Le changement climatique lui-m\u00eame g\u00e9n\u00e8re des risques psychosociaux, comme la peur de perdre son emploi ou du moins de devoir effectuer une transition professionnelle, dans un contexte de <span style=\"text-decoration: underline;\"><em><a href=\"https:\/\/www.oecd.org\/en\/publications\/impacts-of-green-growth-policies-on-labour-markets-and-wage-income-distribution_ea3696f4-en.html\" target=\"_blank\" rel=\"noopener\">transformations<\/a><\/em><\/span> sectorielles. La question de savoir si les risques ainsi g\u00e9n\u00e9r\u00e9s sont abord\u00e9s sur les lieux de travail est \u00e9galement une question empirique ouverte.<\/p>\n<p>L\u2019Enqu\u00eate europ\u00e9enne sur les conditions de travail (<span style=\"text-decoration: underline;\"><em><a href=\"https:\/\/www.eurofound.europa.eu\/en\/surveys\/european-working-conditions-surveys-ewcs\" target=\"_blank\" rel=\"noopener\">EWCS<\/a><\/em><\/span>), qui cible les travailleurs individuels, comprend une question sur \u00ab l\u2019exposition \u00e0 la chaleur \u00bb et toute une gamme d\u2019autres \u00e9l\u00e9ments sur la sant\u00e9 et la s\u00e9curit\u00e9 au travail. Des questions suppl\u00e9mentaires, ax\u00e9es sur la r\u00e9alisation d\u2019une \u00e9valuation des risques ou les actions sp\u00e9cifiques men\u00e9es pour aborder le changement climatique au sein de leur lieu de travail, fourniraient des informations pr\u00e9cieuses. Bien que l\u2019EWCS cible les travailleurs et non les lieux de travail, les informations qu\u2019ils offrent peuvent fournir des indices sur l\u2019engagement des lieux de travail vis-\u00e0-vis du changement climatique.<\/p>\n<p>En attendant des indicateurs statistiques et des donn\u00e9es pr\u00e9cises sur l\u2019impact du changement climatique sur les lieux de travail, la recherche qualitative peut aider \u00e0 sensibiliser et \u00e0 identifier des pratiques susceptibles d\u2019\u00eatre r\u00e9pliqu\u00e9es \u00e0 grande \u00e9chelle. Cette recherche devrait se concentrer sur des initiatives concr\u00e8tes pour adapter les lieux de travail aux nouvelles r\u00e9alit\u00e9s r\u00e9sultant du changement climatique.<\/p>\n<h2>Un travail favorable \u00e0 la sant\u00e9<\/h2>\n<p>Pour faire face au changement climatique, les chercheurs, les d\u00e9cideurs politiques et les partenaires sociaux doivent se concentrer sur le lieu de travail et les aspects qui y sont li\u00e9s. C\u2019est le contexte dans lequel les d\u00e9cisions concernant l\u2019organisation du travail sont prises.<\/p>\n<p>Organiser le travail de mani\u00e8re humaine et favorable \u00e0 la sant\u00e9 en p\u00e9riode de changement climatique est crucial. D\u2019une part, cela permet de maintenir les travailleurs en poste malgr\u00e9 les p\u00e9nuries de main-d&#8217;\u0153uvre, ce qui affecte la prosp\u00e9rit\u00e9 \u00e9conomique. D\u2019autre part, cela contribue \u00e0 pr\u00e9venir les maladies professionnelles et les d\u00e9parts anticip\u00e9s \u00e0 la retraite, au b\u00e9n\u00e9fice de la sant\u00e9 des travailleurs et des syst\u00e8mes de protection sociale.<\/p>\n<p><em>Cet article a d\u2019abord \u00e9t\u00e9 publi\u00e9 sur <strong><a href=\"https:\/\/www.socialeurope.eu\/adapting-workplaces-to-climate-change\" target=\"_blank\" rel=\"noopener\"><span style=\"text-decoration: underline;\">Social Europe<\/span><\/a><\/strong>. Les opinions exprim\u00e9es ici sont celles des auteurs et ne refl\u00e8tent pas n\u00e9cessairement celles de leurs employeurs.<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le rapport r\u00e9cemment publi\u00e9 par le Lancet Countdown pour l&#8217;Europe d\u00e9montre que le changement climatique affecte d\u00e9j\u00e0 les \u00eatres humains et les soci\u00e9t\u00e9s dans leur ensemble. Il se concentre sur les effets n\u00e9fastes sur la sant\u00e9, soulignant la n\u00e9cessit\u00e9 \u00ab d\u2019actions rapides de mitigation et d&#8217;adaptation climatique r\u00e9actives pour la sant\u00e9 \u00bb. Le lieu de travail est un domaine cl\u00e9 pour ces actions.<\/p>\n","protected":false},"author":11,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[3],"tags":[],"class_list":["post-2473","post","type-post","status-publish","format-standard","hentry","category-unkategorisiert","topic-arbeit","topic-nachhaltige-entwicklung","format-text-de"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Adapter les lieux de travail au changement climatique - Improof<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dev.improof.lu\/de\/articles\/travail-changement-climatique\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Adapter les lieux de travail au changement climatique\" \/>\n<meta property=\"og:description\" content=\"Le rapport r\u00e9cemment publi\u00e9 par le Lancet Countdown pour l&#039;Europe d\u00e9montre que le changement climatique affecte d\u00e9j\u00e0 les \u00eatres humains et les soci\u00e9t\u00e9s dans leur ensemble. Il se concentre sur les effets n\u00e9fastes sur la sant\u00e9, soulignant la n\u00e9cessit\u00e9 \u00ab d\u2019actions rapides de mitigation et d&#039;adaptation climatique r\u00e9actives pour la sant\u00e9 \u00bb. Le lieu de travail est un domaine cl\u00e9 pour ces actions.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dev.improof.lu\/de\/articles\/travail-changement-climatique\/\" \/>\n<meta property=\"og:site_name\" content=\"Improof\" \/>\n<meta property=\"article:published_time\" content=\"2025-03-05T13:44:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dev.improof.lu\/app\/uploads\/2025\/03\/worker.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1076\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Nermin Plavsic\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Adapter les lieux de travail au changement climatique\" \/>\n<meta name=\"twitter:description\" content=\"Le rapport r\u00e9cemment publi\u00e9 par le Lancet Countdown pour l&#039;Europe d\u00e9montre que le changement climatique affecte d\u00e9j\u00e0 les \u00eatres humains et les soci\u00e9t\u00e9s dans leur ensemble. Il se concentre sur les effets n\u00e9fastes sur la sant\u00e9, soulignant la n\u00e9cessit\u00e9 \u00ab d\u2019actions rapides de mitigation et d&#039;adaptation climatique r\u00e9actives pour la sant\u00e9 \u00bb. Le lieu de travail est un domaine cl\u00e9 pour ces actions.\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/dev.improof.lu\/app\/uploads\/2025\/03\/worker.jpg\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Nermin Plavsic\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/dev.improof.lu\/de\/articles\/travail-changement-climatique\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dev.improof.lu\/de\/articles\/travail-changement-climatique\/\"},\"author\":{\"name\":\"Nermin Plavsic\",\"@id\":\"https:\/\/dev.improof.lu\/de\/#\/schema\/person\/8b7e0720f9ab34bd8b12af9dbf2592a6\"},\"headline\":\"Adapter les lieux de travail au changement climatique\",\"datePublished\":\"2025-03-05T13:44:57+00:00\",\"dateModified\":\"2025-03-05T13:44:57+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dev.improof.lu\/de\/articles\/travail-changement-climatique\/\"},\"wordCount\":1239,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dev.improof.lu\/de\/#organization\"},\"articleSection\":[\"Unkategorisiert\"],\"inLanguage\":\"de-DE\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dev.improof.lu\/de\/articles\/travail-changement-climatique\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dev.improof.lu\/de\/articles\/travail-changement-climatique\/\",\"url\":\"https:\/\/dev.improof.lu\/de\/articles\/travail-changement-climatique\/\",\"name\":\"Adapter les lieux de travail au changement climatique - Improof\",\"isPartOf\":{\"@id\":\"https:\/\/dev.improof.lu\/de\/#website\"},\"datePublished\":\"2025-03-05T13:44:57+00:00\",\"dateModified\":\"2025-03-05T13:44:57+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/dev.improof.lu\/de\/articles\/travail-changement-climatique\/#breadcrumb\"},\"inLanguage\":\"de-DE\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dev.improof.lu\/de\/articles\/travail-changement-climatique\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dev.improof.lu\/de\/articles\/travail-changement-climatique\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/dev.improof.lu\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Adapter les lieux de travail au changement climatique\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dev.improof.lu\/de\/#website\",\"url\":\"https:\/\/dev.improof.lu\/de\/\",\"name\":\"Improof\",\"description\":\"Tagline goes here\",\"publisher\":{\"@id\":\"https:\/\/dev.improof.lu\/de\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dev.improof.lu\/de\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de-DE\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/dev.improof.lu\/de\/#organization\",\"name\":\"Improof\",\"url\":\"https:\/\/dev.improof.lu\/de\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\/\/dev.improof.lu\/de\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dev.improof.lu\/app\/uploads\/2022\/10\/improof-logo-svg.png\",\"contentUrl\":\"https:\/\/dev.improof.lu\/app\/uploads\/2022\/10\/improof-logo-svg.png\",\"width\":652,\"height\":209,\"caption\":\"Improof\"},\"image\":{\"@id\":\"https:\/\/dev.improof.lu\/de\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dev.improof.lu\/de\/#\/schema\/person\/8b7e0720f9ab34bd8b12af9dbf2592a6\",\"name\":\"Nermin Plavsic\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\/\/dev.improof.lu\/de\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/1b010c13286dbffe130fb77dd68cc999?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/1b010c13286dbffe130fb77dd68cc999?s=96&d=mm&r=g\",\"caption\":\"Nermin Plavsic\"},\"url\":\"https:\/\/dev.improof.lu\/de\/articles\/author\/nermin-plavsic\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Adapter les lieux de travail au changement climatique - Improof","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dev.improof.lu\/de\/articles\/travail-changement-climatique\/","og_locale":"de_DE","og_type":"article","og_title":"Adapter les lieux de travail au changement climatique","og_description":"Le rapport r\u00e9cemment publi\u00e9 par le Lancet Countdown pour l'Europe d\u00e9montre que le changement climatique affecte d\u00e9j\u00e0 les \u00eatres humains et les soci\u00e9t\u00e9s dans leur ensemble. Il se concentre sur les effets n\u00e9fastes sur la sant\u00e9, soulignant la n\u00e9cessit\u00e9 \u00ab d\u2019actions rapides de mitigation et d'adaptation climatique r\u00e9actives pour la sant\u00e9 \u00bb. Le lieu de travail est un domaine cl\u00e9 pour ces actions.","og_url":"https:\/\/dev.improof.lu\/de\/articles\/travail-changement-climatique\/","og_site_name":"Improof","article_published_time":"2025-03-05T13:44:57+00:00","og_image":[{"width":1920,"height":1076,"url":"https:\/\/dev.improof.lu\/app\/uploads\/2025\/03\/worker.jpg","type":"image\/jpeg"}],"author":"Nermin Plavsic","twitter_card":"summary_large_image","twitter_title":"Adapter les lieux de travail au changement climatique","twitter_description":"Le rapport r\u00e9cemment publi\u00e9 par le Lancet Countdown pour l'Europe d\u00e9montre que le changement climatique affecte d\u00e9j\u00e0 les \u00eatres humains et les soci\u00e9t\u00e9s dans leur ensemble. Il se concentre sur les effets n\u00e9fastes sur la sant\u00e9, soulignant la n\u00e9cessit\u00e9 \u00ab d\u2019actions rapides de mitigation et d'adaptation climatique r\u00e9actives pour la sant\u00e9 \u00bb. Le lieu de travail est un domaine cl\u00e9 pour ces actions.","twitter_image":"https:\/\/dev.improof.lu\/app\/uploads\/2025\/03\/worker.jpg","twitter_misc":{"Written by":"Nermin Plavsic","Est. reading time":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/dev.improof.lu\/de\/articles\/travail-changement-climatique\/#article","isPartOf":{"@id":"https:\/\/dev.improof.lu\/de\/articles\/travail-changement-climatique\/"},"author":{"name":"Nermin Plavsic","@id":"https:\/\/dev.improof.lu\/de\/#\/schema\/person\/8b7e0720f9ab34bd8b12af9dbf2592a6"},"headline":"Adapter les lieux de travail au changement climatique","datePublished":"2025-03-05T13:44:57+00:00","dateModified":"2025-03-05T13:44:57+00:00","mainEntityOfPage":{"@id":"https:\/\/dev.improof.lu\/de\/articles\/travail-changement-climatique\/"},"wordCount":1239,"commentCount":0,"publisher":{"@id":"https:\/\/dev.improof.lu\/de\/#organization"},"articleSection":["Unkategorisiert"],"inLanguage":"de-DE","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dev.improof.lu\/de\/articles\/travail-changement-climatique\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/dev.improof.lu\/de\/articles\/travail-changement-climatique\/","url":"https:\/\/dev.improof.lu\/de\/articles\/travail-changement-climatique\/","name":"Adapter les lieux de travail au changement climatique - Improof","isPartOf":{"@id":"https:\/\/dev.improof.lu\/de\/#website"},"datePublished":"2025-03-05T13:44:57+00:00","dateModified":"2025-03-05T13:44:57+00:00","breadcrumb":{"@id":"https:\/\/dev.improof.lu\/de\/articles\/travail-changement-climatique\/#breadcrumb"},"inLanguage":"de-DE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dev.improof.lu\/de\/articles\/travail-changement-climatique\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/dev.improof.lu\/de\/articles\/travail-changement-climatique\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/dev.improof.lu\/de\/"},{"@type":"ListItem","position":2,"name":"Adapter les lieux de travail au changement climatique"}]},{"@type":"WebSite","@id":"https:\/\/dev.improof.lu\/de\/#website","url":"https:\/\/dev.improof.lu\/de\/","name":"Improof","description":"Tagline goes here","publisher":{"@id":"https:\/\/dev.improof.lu\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dev.improof.lu\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de-DE"},{"@type":"Organization","@id":"https:\/\/dev.improof.lu\/de\/#organization","name":"Improof","url":"https:\/\/dev.improof.lu\/de\/","logo":{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/dev.improof.lu\/de\/#\/schema\/logo\/image\/","url":"https:\/\/dev.improof.lu\/app\/uploads\/2022\/10\/improof-logo-svg.png","contentUrl":"https:\/\/dev.improof.lu\/app\/uploads\/2022\/10\/improof-logo-svg.png","width":652,"height":209,"caption":"Improof"},"image":{"@id":"https:\/\/dev.improof.lu\/de\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/dev.improof.lu\/de\/#\/schema\/person\/8b7e0720f9ab34bd8b12af9dbf2592a6","name":"Nermin Plavsic","image":{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/dev.improof.lu\/de\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/1b010c13286dbffe130fb77dd68cc999?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1b010c13286dbffe130fb77dd68cc999?s=96&d=mm&r=g","caption":"Nermin Plavsic"},"url":"https:\/\/dev.improof.lu\/de\/articles\/author\/nermin-plavsic\/"}]}},"_links":{"self":[{"href":"https:\/\/dev.improof.lu\/de\/wp-json\/wp\/v2\/posts\/2473","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.improof.lu\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dev.improof.lu\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dev.improof.lu\/de\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/dev.improof.lu\/de\/wp-json\/wp\/v2\/comments?post=2473"}],"version-history":[{"count":1,"href":"https:\/\/dev.improof.lu\/de\/wp-json\/wp\/v2\/posts\/2473\/revisions"}],"predecessor-version":[{"id":2474,"href":"https:\/\/dev.improof.lu\/de\/wp-json\/wp\/v2\/posts\/2473\/revisions\/2474"}],"wp:attachment":[{"href":"https:\/\/dev.improof.lu\/de\/wp-json\/wp\/v2\/media?parent=2473"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dev.improof.lu\/de\/wp-json\/wp\/v2\/categories?post=2473"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dev.improof.lu\/de\/wp-json\/wp\/v2\/tags?post=2473"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}