{"id":1628,"date":"2024-01-30T15:10:45","date_gmt":"2024-01-30T15:10:45","guid":{"rendered":"https:\/\/dev.improof.lu\/?p=1628"},"modified":"2024-01-31T15:08:05","modified_gmt":"2024-01-31T15:08:05","slug":"reflexions-politique-d-immigration","status":"publish","type":"post","link":"https:\/\/dev.improof.lu\/en\/articles\/reflexions-politique-d-immigration\/","title":{"rendered":"R\u00e9flexions pour une politique d\u2019immigration adapt\u00e9e \u00e0 la r\u00e9alit\u00e9"},"content":{"rendered":"<p>Le Luxembourg est et restera un pays d\u2019immigration dont la croissance de la population est tr\u00e8s majoritairement due aux migrations.<\/p>\n<p>\u00ab Au 1er janvier 2023, le Luxembourg comptait 660 809 habitants, soit 15 412 de plus qu\u2019en 2022 (+2.4%) \u2026 La part des personnes de nationalit\u00e9 \u00e9trang\u00e8re a continuellement augment\u00e9 au cours du temps en passant de 26.3% en 1981 \u00e0 47.4% en 2023 \u00bb.[1] Entre les recensements de 2011 et 2021, la population a augment\u00e9 de 131.588 personnes soit 25.7%[2]. Cet accroissement est majoritairement d\u00fb \u00e0 l\u2019immigration nette[3]. Ainsi, en 2021, la population n\u00e9e \u00e0 l&#8217;\u00e9tranger repr\u00e9sente 49,3% de la population totale (contre 40,1% en 2011), alors que 47,2% de la population totale n&#8217;a pas la nationalit\u00e9 luxembourgeoise (contre 43% en 2011). 73,7% de la population a un arri\u00e8re-plan migratoire[4], alors qu\u2019ils n\u2019\u00e9taient que 61,2% en 2011.[5]<\/p>\n<p>Depuis des ann\u00e9es, le solde migratoire \u2013 la diff\u00e9rence annuelle entre le nombre de personnes ayant immigr\u00e9s et celles ayant \u00e9migr\u00e9s \u2013 est positif de plus ou moins 10.000 migrants\/an. Durant les derni\u00e8res d\u00e9cennies, le nombre d\u2019immigr\u00e9s est en augmentation, passant de 5.990 en 1984 \u00e0 26.668 en 2019. Durant la m\u00eame p\u00e9riode, le nombre d\u2019\u00e9migr\u00e9s, c.-\u00e0-d. les personnes qui quittent le Luxembourg, est pass\u00e9 de 5.502 \u00e0 15.593[6]. Les migrations dans notre pays sont donc tr\u00e8s dynamiques et se caract\u00e9risent par une forte rotation.<\/p>\n<p>A ces chiffres s\u2019ajoutent les frontaliers, de plus en plus nombreux, qui viennent tous les jours travailler au Luxembourg. En 2021, sur 458.000 salari\u00e9s travaillant au Luxembourg, 212.000 \u00e9taient des frontaliers[7]. Notons que 73,5% des salari\u00e9s au Luxembourg n\u2019ont pas la nationalit\u00e9 luxembourgeoise.<\/p>\n<p>Les flux migratoires vers le Luxembourg se sont diversifi\u00e9s et ont un impact sur toutes les couches de la population ; les immigr\u00e9s sont surrepr\u00e9sent\u00e9s aux deux extr\u00e9mit\u00e9s de l\u2019\u00e9chelle des qualifications[8]. Entre 2011 et 2021, la part des migrants originaires de pays tiers \u00e0 l\u2019Union europ\u00e9enne surtout d\u2019Asie (+251%), d\u2019Afrique (+143,6%) et du continent am\u00e9ricain (102,8%) a fortement augment\u00e9, donnant un visage de plus en plus cosmopolite au pays[9].<\/p>\n<p>Depuis la fin du 20\u00e8me si\u00e8cle, le Luxembourg a enregistr\u00e9 l\u2019arriv\u00e9e de nombreux r\u00e9fugi\u00e9s des Balkans, d\u2019Afrique comme d\u2019Asie. Les 5 derni\u00e8res ann\u00e9es en moyenne 1.800 demandes de protection internationale ont \u00e9t\u00e9 d\u00e9pos\u00e9es au Luxembourg, dont environ la moiti\u00e9 a obtenu l\u2019autorisation de rester et de travailler dans notre pays.<\/p>\n<p>Face \u00e0 tous ces d\u00e9fis et opportunit\u00e9s, il faut imaginer une politique migratoire aussi dynamique que les flux migratoires, adapt\u00e9e \u00e0 la r\u00e9alit\u00e9 du march\u00e9 de l\u2019emploi et aux motifs d\u2019immigration.<\/p>\n<p><em><strong>La demande d\u2019autorisation de s\u00e9jour pour travailler devrait pouvoir se faire aussi depuis le Luxembourg<\/strong><\/em><\/p>\n<p>Les ressortissants de l\u2019Union europ\u00e9enne b\u00e9n\u00e9ficient de la libre circulation, donc du libre acc\u00e8s au march\u00e9 du travail sans restrictions, mais ils ne sont pas assez nombreux \u00e0 vouloir travailler au Luxembourg pour r\u00e9pondre aux besoins de l\u2019\u00e9conomie.<\/p>\n<p>Les personnes d\u00e9tenant un passeport d\u2019un pays tiers \u00e0 l\u2019Union europ\u00e9enne peuvent travailler au Luxembourg sous certaines conditions tr\u00e8s strictes. La loi sur la libre circulation des personnes et l\u2019immigration de 2008 exige des ressortissants de pays tiers d\u00e9sirant obtenir une autorisation de s\u00e9jour comme travailleur salari\u00e9 (hautement qualifi\u00e9 ou non) que la demande soit \u00ab introduite par le ressortissant d\u2019un pays tiers aupr\u00e8s du ministre et doit \u00eatre favorablement avis\u00e9e avant son entr\u00e9e sur le territoire \u00bb[10]. Concr\u00e8tement, cela signifie que tout ressortissant de pays tiers qui souhaite travailler au Luxembourg, doit trouver un employeur avant m\u00eame d\u2019\u00eatre au Luxembourg et que toute personne se trouvant d\u00e9j\u00e0 sur le territoire est exclue et ne peut pas introduire de demande.<\/p>\n<p>Le choix, d\u2019exclure un migrant d\u2019une d\u00e9marche r\u00e9guli\u00e8re de demande de titre de s\u00e9jour pour travail, simplement parce que celui-ci se trouve d\u00e9j\u00e0 sur le territoire du Grand-duch\u00e9, est discutable, surtout quand certains cas sont r\u00e9gularis\u00e9s de mani\u00e8re exceptionnelle. \u00ab Le ministre peut accorder une autorisation de s\u00e9jour pour des motifs humanitaires d\u2019une exceptionnelle gravit\u00e9 au ressortissant de pays tiers \u00bb[11], ce qui concerne uniquement un nombre limit\u00e9 de cas, r\u00e9pondant \u00e0 des crit\u00e8res sp\u00e9cifiques non d\u00e9finis. L\u2019analyse de ces demandes est faite au \u00ab cas par cas \u00bb. Cette pratique discr\u00e9tionnaire est aussi \u00e9voqu\u00e9e dans l\u2019accord de coalition : \u00ab Le Gouvernement ne pr\u00e9voit pas de r\u00e9gularisation g\u00e9n\u00e9rale des r\u00e9fugi\u00e9s d\u00e9bout\u00e9s, mais il d\u00e9cidera au cas par cas \u00bb[12]. Accorder au cas par cas un droit de s\u00e9jour ou de travail sans crit\u00e8res clairs, \u00e9quitables et transparents, laisse le demandeur et son futur employeur \u00e0 la merci du bon vouloir du ministre et de son administration. Ceci n\u2019est pas digne du fonctionnement d\u2019un \u00c9tat d\u00e9mocratique.<\/p>\n<p>On constate la venue, soit ill\u00e9gale, soit sous couvert de la demande d\u2019asile, de nombreux migrants. Les demandes de protection internationale n\u2019aboutissent pas si les demandeurs ne peuvent pas prouver que leur vie est en danger dans leur pays d\u2018origine ou s\u2019ils sont originaires de pays class\u00e9s comme \u00ab s\u00fbrs \u00bb. Ces ressortissants ont des raisons de fuir leur pays \u00e0 cause de la pauvret\u00e9, du ch\u00f4mage ambiant, de conflits internes\u2026 Mieux vaut leur donner une chance de trouver un emploi l\u00e9gal sur notre march\u00e9 de l\u2019emploi que de les laisser v\u00e9g\u00e9ter dans l\u2019incertitude et la clandestinit\u00e9.<\/p>\n<p><em><strong>L\u2019\u00e9mission de visas temporaires pour la recherche d\u2019un travail permettrait la venue l\u00e9gale de migrants \u00e9conomiques \u00e0 la recherche d\u2019une vie meilleure et \u00e9viterait leur chute dans la clandestinit\u00e9<\/strong><\/em><\/p>\n<p>Ils pourraient \u00eatre \u00e9mis dans les ambassades repr\u00e9sentants le Grand-Duch\u00e9. Cela donnerait l\u2019occasion \u00e0 ces migrants de venir l\u00e9galement et de rechercher pendant une certain temps un emploi vacant au Luxembourg. On \u00e9viterait ainsi que certains migrants recourent p. ex. \u00e0 la demande d\u2019asile comme porte d\u2019entr\u00e9e au Luxembourg, ce qui serait b\u00e9n\u00e9fique dans tous les sens : un besoin moins important en structures d\u2019accueil des demandeurs d\u2019asile, des d\u00e9lais plus courts pour ceux qui demandent la protection\u2026<\/p>\n<p><em><strong>L\u2019exigence d\u2019un contrat \u00e0 dur\u00e9e ind\u00e9termin\u00e9e (CDI) pour obtenir une 1\u00e8re autorisation de s\u00e9jour pour travailleur salari\u00e9 ne devrait plus \u00eatre requise, un contrat \u00e0 dur\u00e9e d\u00e9termin\u00e9e (CDD) devrait suffire<\/strong><\/em><\/p>\n<p>C\u2019est en fait une pratique de l\u2019administration, la condition d\u2019un CDI ne figurant pas dans la loi qui dit devoir \u00eatre \u00ab en possession d&#8217;un contrat de travail conclu pour un poste d\u00e9clar\u00e9 vacant aupr\u00e8s de l&#8217;Agence pour le d\u00e9veloppement de l&#8217;emploi \u00bb[13]. Or, le CDI est g\u00e9n\u00e9ralement exig\u00e9. Un CDD am\u00e8ne souvent un refus de la demande sous pr\u00e9texte qu\u2019apr\u00e8s ce premier CDD, il n\u2019y aurait pas de garantie que la personne retrouve un emploi. Cependant, un CDI ne donne pas de meilleure garantie, car il peut \u00eatre r\u00e9sili\u00e9 \u00e0 tout moment, m\u00eame sans pr\u00e9avis durant la p\u00e9riode d\u2019essai.<\/p>\n<p>A certains demandeurs de protection internationale d\u00e9bout\u00e9s du droit d\u2019asile et issus de pays, o\u00f9 le gouvernement sait qu\u2019ils ne pourront y \u00eatre renvoy\u00e9s, la Direction de l\u2019Immigration envoie une lettre les invitant \u00e0 pr\u00e9senter un CDI pour pouvoir b\u00e9n\u00e9ficier d\u2019une autorisation de s\u00e9jour pour travailleurs salari\u00e9s et ainsi pouvoir rester au pays. Or la grande majorit\u00e9 de ces personnes manque d\u2019exp\u00e9riences de travail sur le march\u00e9 de l\u2019emploi luxembourgeois et peinent \u00e0 trouver un CDI. Face aux difficult\u00e9s d\u2019organiser le retour des r\u00e9fugi\u00e9s d\u00e9bout\u00e9s du droit d\u2019asile, on ferait mieux de leur faciliter l\u2019int\u00e9gration sur le march\u00e9 de l\u2019emploi au lieu de les laisser v\u00e9g\u00e9ter sans perspective et perdre du temps de vie pr\u00e9cieux pour apprendre, travailler, \u00e9voluer.<\/p>\n<p><em><strong>Un syst\u00e8me \u00e0 points consid\u00e9rant l\u2019ensemble des comp\u00e9tences et atouts de la personne devrait \u00eatre mis en place pour accorder une autorisation de s\u00e9jour voire r\u00e9gulariser la situation administrative d\u2019une personne<\/strong><\/em><\/p>\n<p>En Allemagne vient d\u2019\u00eatre introduit la Chancenkarte mit einem Punktesystem (carte des chances avec un syst\u00e8me de points) qui \u00e9value des crit\u00e8res d\u2019apprentissage de la langue, de travail, d\u2019implication soci\u00e9tale, d\u2019engagement b\u00e9n\u00e9vole pour \u00e9mettre une autorisation de s\u00e9jour et de travail[14]. Un exemple int\u00e9ressant \u00e0 suivre au Luxembourg car cela permettrait de consid\u00e9rer l\u2019ensemble des comp\u00e9tences des personnes d\u00e9sirant travailler au Luxembourg.<\/p>\n<p>Il faut arr\u00eater de consid\u00e9rer comme d\u00e9terminants pour acc\u00e9der au s\u00e9jour l\u00e9gal au Luxembourg que la demande soit effectu\u00e9e avant l\u2019arriv\u00e9e au Luxembourg, que le contrat de travail soit un CDI et que l\u2019employeur potentiel dispose d\u2019une autorisation d\u2019engager un ressortissant de pays tiers.<\/p>\n<p><em><strong>La liste des m\u00e9tiers tr\u00e8s en p\u00e9nurie doit \u00eatre plus souple et \u00e9largie \u00e0 davantage de m\u00e9tiers<\/strong><\/em><\/p>\n<p>Suites \u00e0 la simplification des proc\u00e9dures en vigueur depuis le 1.9.2023, l&#8217;obtention du certificat permettant \u00e0 l\u2019employeur d&#8217;embaucher un ressortissant de pays tiers est facilit\u00e9e. Le test du march\u00e9[15] n\u2019est plus exig\u00e9 pour certains m\u00e9tiers, s\u2019ils figurent sur la liste des m\u00e9tiers tr\u00e8s en p\u00e9nurie qui est mise \u00e0 jour par l\u2019ADEM. Sur la liste de 2023 ne figurait presque pas de m\u00e9tiers peu qualifi\u00e9s. Or, parmi les m\u00e9tiers les plus recherch\u00e9s en 2023, l\u2019ADEM cite en 5\u00e8me position le personnel de cuisine, en 7\u00e8me le service en restauration, en 11\u00e8me le nettoyage des locaux, en 15\u00e8me la plonge, ce qui montre que ces secteurs ont un besoin urgent de main d\u2019\u0153uvre[16]. Il faut que cette liste soit \u00e9largie \u00e0 davantage de m\u00e9tiers, entre autres de la restauration et de l\u2019h\u00f4tellerie.<\/p>\n<p>Une communication claire et trimestrielle devrait \u00eatre faite par les administrations comp\u00e9tentes sur les effets de l\u2018application de cette mesure, il faut \u00e9valuer son impact.<\/p>\n<p>Pour justifier le refus d\u2019accorder aux employeurs l\u2019autorisation d\u2019engager un ressortissant de pays tiers pour des m\u00e9tiers peu qualifi\u00e9s, l\u2019argument avanc\u00e9 est qu\u2019il y a assez de ch\u00f4meurs peu qualifi\u00e9s qui pourraient occuper ces postes peu qualifi\u00e9s vacants. Or, peu de candidats motiv\u00e9s se pr\u00e9sentent aux employeurs, pr\u00eats \u00e0 accepter des emplois peu qualifi\u00e9s, souvent p\u00e9nibles. L\u2019administration refuse au patron l\u2019autorisation d\u2019employer un ressortissant de pays tiers motiv\u00e9, sous pr\u00e9texte qu\u2019il y a assez de ch\u00f4meurs sur le march\u00e9 de l\u2019emploi pouvant occuper le poste. Se pose la question du droit au choix du candidat par l\u2019employeur pour un poste vacant non ou peu qualifi\u00e9.<\/p>\n<p>L\u2019accord de coalition pr\u00e9voit d\u2019assouplir les conditions d\u2019obtention d\u2019une autorisation d\u2019occupation temporaire AOT aux demandeurs de protection internationale DPI. \u00ab Quatre mois apr\u00e8s l\u2019introduction de leur demande de protection internationale, les DPI pourront conclure un contrat de travail dans les domaines \u00e0 forte p\u00e9nurie de main d\u2019\u0153uvre \u00bb[17]. Pourquoi juste ces domaines ? Pourquoi ne pas faciliter aux DPI d\u00e8s leur arriv\u00e9e l\u2019acc\u00e8s \u00e0 l\u2019emploi et ainsi les autonomiser d\u00e8s leur venue.<\/p>\n<p>L\u2019AOT perd imm\u00e9diatement sa validit\u00e9 lorsque la proc\u00e9dure d\u2019asile est d\u00e9finitivement refus\u00e9e. Quel employeur est pr\u00eat \u00e0 engager un demandeur de protection internationale, s\u2019il sait qu\u2019il ne pourra pas le garder lorsque sa demande d\u2019asile est d\u00e9finitivement refus\u00e9e ?<\/p>\n<p><em><strong>La libre circulation doit \u00eatre accord\u00e9e aux citoyens originaires de pays tiers disposant d\u2019un s\u00e9jour permanent dans un autre pays membre de l\u2019UE, au m\u00eame titre que les ressortissants de l\u2019Union<\/strong><\/em><\/p>\n<p>Certains ressortissants de pays tiers sont l\u00e9galement install\u00e9s depuis de nombreuses ann\u00e9es dans un autre pays de l\u2019Union et y disposent d\u2019un s\u00e9jour permanent. Certains aimeraient venir travailler au Luxembourg, les crises \u00e9conomiques dans le pays de l\u2019Union o\u00f9 ils r\u00e9sident, ne leur donnant plus de r\u00e9elles perspectives d\u2019emploi. Le libre acc\u00e8s au march\u00e9 de l\u2019emploi de l\u2019Union ne s\u2019applique pas \u00e0 eux, alors que souvent ces citoyens sont form\u00e9s, sont des travailleurs exp\u00e9riment\u00e9s, ayant une exp\u00e9rience de vie dans un autre pays de l\u2019Union. Actuellement, ils sont tenus de remplir les m\u00eames conditions que ceux qui sont encore dans leur pays d\u2019origine et ils doivent effectuer les m\u00eames d\u00e9marches administratives, sans aucune facilitation de la proc\u00e9dure.<\/p>\n<p><em><strong>Un soutien technique pour les demandes d\u2019autorisation de s\u00e9jour devrait exister pour les employeurs et les futurs b\u00e9n\u00e9ficiaires d\u2019une telle autorisation<\/strong><\/em><\/p>\n<p>Certains employeurs sont induits en erreur, car sur certaines autorisations de s\u00e9jour permanent \u00e9mises dans d\u2019autres pays de l\u2019Union figure la mention qu\u2019elles sont valables dans toute l\u2019Union europ\u00e9enne. Or, ces citoyens peuvent se d\u00e9placer librement en tant que touriste, mais ils n\u2019ont pas le libre acc\u00e8s aux emplois dans un autre pays de l\u2019Union comme c\u2019est le cas pour les ressortissants de l\u2019UE. Ils emploient des ressortissants de pays tiers sans les autorisations n\u00e9cessaires et s\u2019exposent \u00e0 des sanctions et le salari\u00e9 concern\u00e9 \u00e0 l\u2019expulsion.<\/p>\n<p>Un accompagnement technique des dossiers devrait exister, la l\u00e9gislation sur la libre circulation et l\u2019immigration \u00e9tant tr\u00e8s complexe &#8211; on peine \u00e0 s\u2019y retrouver. Des formations devraient \u00eatre propos\u00e9es aux employeurs afin de garantir le bon d\u00e9roulement des demandes.<\/p>\n<p>Ceci permettrait d\u2019\u00e9viter &#8211; surtout aux petits employeurs &#8211; d\u2019\u00eatre sanctionn\u00e9s, s\u2019ils emploient \u00e0 leur insu un ressortissant de pays tiers sans avoir rempli les conditions pr\u00e9vues par la loi. Cela donnerait aussi une s\u00e9curit\u00e9 aux ressortissants de pays tiers que leur dossier est valablement trait\u00e9 et \u00e9viterait que des personnes sans scrupules les exploitent, voire les induisent en erreur, pour introduire une demande de s\u00e9jour.<\/p>\n<p><em><strong>Les longs d\u00e9lais de d\u00e9livrance des autorisations de travail et l\u2019impossibilit\u00e9 pour l\u2019entreprise comme pour le salari\u00e9 de conna\u00eetre en temps r\u00e9el la progression de sa demande doit cesser<\/strong><\/em><\/p>\n<p>Le d\u00e9lai de d\u00e9livrance des autorisations de travail avant l\u2019arriv\u00e9e du salari\u00e9 sur le territoire luxembourgeois s\u2019accompagne bien souvent d\u2019un manque de communication des autorit\u00e9s comp\u00e9tentes sur le statut de progression de la demande. Le d\u00e9lai de r\u00e9ponse du minist\u00e8re est en principe de 4 mois maximum. En cas d&#8217;absence de r\u00e9ponse dans ce d\u00e9lai, le requ\u00e9rant peut consid\u00e9rer sa demande comme rejet\u00e9e[18]. Cette lenteur de traitement engendre une forte inqui\u00e9tude pour le candidat comme pour l\u2019entreprise concern\u00e9e. On constate aussi de longs d\u00e9lais de r\u00e9ponse pour les titres de s\u00e9jours d\u00e9finitifs d\u00e9livr\u00e9s apr\u00e8s l\u2019autorisation temporaire de 3 mois. Il n\u2019est donc pas rare qu\u2019un contrat de travail doit \u00eatre suspendu, en l\u2019absence de l\u2019obtention du titre de s\u00e9jour pour activit\u00e9 salari\u00e9e dans des d\u00e9lais raisonnables.[19] L\u2019employeur a peur d\u2019\u00eatre sanctionn\u00e9 en cas de contr\u00f4le et pr\u00e9f\u00e8re alors ne pas employer le ressortissant Non UE.<\/p>\n<p>Le demandeur d\u2019une autorisation de s\u00e9jour ainsi que son futur employeur devraient pouvoir suivre en temps r\u00e9el l\u2019\u00e9tat d\u2019avancement du dossier et dialoguer avec une personne de contact unique en charge de sa demande. Dans l\u2019accord de coalition est indiqu\u00e9 \u00ab Un portail en ligne sera cr\u00e9\u00e9 pour consolider toutes les informations n\u00e9cessaires pour les candidats potentiels et les entreprises int\u00e9ress\u00e9es \u00bb[20]. Esp\u00e9rons que cette plateforme verra le jour rapidement. Elle devra \u00eatre multilingue et devra faciliter les d\u00e9marches d\u2019entr\u00e9e et de s\u00e9jour des ressortissants de pays tiers, salari\u00e9s, \u00e9tudiants et chercheurs en r\u00e9alisant l\u2019ensemble des d\u00e9marches en ligne.<\/p>\n<p><em><strong>Les ressortissants de pays tiers r\u00e9sidant dans les pays voisins devraient pouvoir venir travailler au Luxembourg en tant que frontaliers<\/strong><\/em><\/p>\n<p>Actuellement, seuls les ressortissants de pays tiers peuvent travailler comme frontalier au Luxembourg, si leur conjoint a une nationalit\u00e9 de l\u2019Union europ\u00e9enne et travaille d\u00e9j\u00e0 comme frontalier au Luxembourg. Chaque pays membre de l\u2019Union peut se doter d\u2019une politique migratoire propre, si elle n\u2019entrave pas celles en vigueur dans l\u2019Union. Le Luxembourg pourrait ainsi \u00e9largir son bassin de recrutement dans les pays frontaliers en accordant l\u2019acc\u00e8s au march\u00e9 de l\u2019emploi aux ressortissants de pays tiers r\u00e9sidant aux fronti\u00e8res du Luxembourg.<\/p>\n<p>Comme il est tr\u00e8s difficile sur le march\u00e9 du logement luxembourgeois de se loger, une telle mesure permettrait aux ressortissants de pays tiers travaillant l\u00e9galement au Luxembourg de s\u2019installer dans la r\u00e9gion frontali\u00e8re. Encore faudra-t-il s\u2019entendre avec les pays voisins sur leur droit d\u2019y r\u00e9sider tout en travaillant au Luxembourg.<\/p>\n<p><em><strong>Des programmes cibl\u00e9s sur la formation professionnelle, l\u2019acc\u00e8s au travail doivent exister d\u00e8s la venue des r\u00e9fugi\u00e9s\/migrants au pays afin d\u2019assurer de meilleures chances d\u2019int\u00e9gration et d\u2019autonomisation<\/strong><\/em><\/p>\n<p>Les r\u00e9fugi\u00e9s d\u2019Ukraine \u00e0 qui la protection temporaire est accord\u00e9e ont un acc\u00e8s sans restriction \u00e0 l\u2019emploi. Ils peuvent travailler librement sur le 1er march\u00e9 de l\u2019emploi ou occuper un emploi dans une structure subventionn\u00e9e par l\u2019\u00c9tat (CIGL \u2026). Les offres et services de l\u2019ADEM leur sont aussi accessibles. Lorsqu\u2019ils trouvent un emploi, ils peuvent quitter leur statut de b\u00e9n\u00e9ficiaire de protection temporaire et obtenir une autorisation de s\u00e9jour pour travailleur salari\u00e9.<\/p>\n<p>Pourquoi ne pas \u00e9tendre ce droit aux autres demandeurs de protection internationale, voire aux sans-papiers pouvant justifier d\u2019une pr\u00e9sence au pays depuis un certain temps.<\/p>\n<p>Une \u00e9valuation de l\u2019insertion sur le march\u00e9 de l\u2019emploi des r\u00e9fugi\u00e9s d\u2019Ukraine fait d\u00e9faut. Or, elle serait importante pour voir si ce dispositif est concluant et s\u2019il pourrait \u00eatre \u00e9tendu aux autres r\u00e9fugi\u00e9s ou migrants.<\/p>\n<p>La possibilit\u00e9 de s\u2019inscrire comme demandeurs d\u2019emploi, d\u2019ouvrir l\u2019acc\u00e8s \u00e0 la formation professionnelle, de pouvoir acc\u00e9der \u00e0 toutes les fonctionnalit\u00e9s du jobboard de l\u2019ADEM\u2026 favorise l\u2019int\u00e9gration au march\u00e9 de l\u2019emploi. Ce serait un apport \u00e0 la protection de la sant\u00e9 mentale et aux ressources personnelles de ces personnes ayant souvent v\u00e9cu des traumas graves.<\/p>\n<p>Nos administrations devraient s\u2019employer \u00e0 autonomiser les personnes, \u00e0 les int\u00e9grer sur le march\u00e9 de l\u2019emploi. Leurs d\u00e9cisions devraient \u00eatre positives en mati\u00e8re d\u2019acc\u00e8s \u00e0 une formation professionnelle, d\u2019autorisations accord\u00e9es aux employeurs \u00e0 employer un ressortissant de pays tiers. Il faut cesser d\u2019avoir une politique des refus, mais viser l\u2019inclusion de ces personnes.<\/p>\n<p><em><strong>Une autorisation de s\u00e9jour devrait \u00eatre accord\u00e9e si le r\u00e9fugi\u00e9 se trouve en situation d\u2019emploi ou de formation lorsque sa demande de protection est refus\u00e9e<\/strong><\/em><\/p>\n<p>Dans l\u2019accord de coalition figure que[21] \u00ab\u00a0 le contrat de travail d\u2019un demandeur de protection internationale DPI n\u2019influencera en rien les proc\u00e9dures pr\u00e9vues en cas de d\u00e9boutement ! \u00bb<\/p>\n<p>Le DPI ayant montr\u00e9 sa volont\u00e9 \u00e0 devenir \u00e9conomiquement ind\u00e9pendant pendant sa demande d\u2019asile en exer\u00e7ant un emploi, devrait pouvoir rester et continuer \u00e0 travailler.<\/p>\n<p>Aux d\u00e9bout\u00e9s du droit d\u2019asile qui suivent un apprentissage, l\u2019assurance de pouvoir terminer cet apprentissage devrait aussi \u00eatre donn\u00e9e. Leur formation ayant souvent d\u00e9but\u00e9 alors qu\u2019ils \u00e9taient demandeurs de protection internationale, ils doivent l\u2019interrompre au moment o\u00f9 leur demande de protection est d\u00e9finitivement rejet\u00e9e. Ceci est incompr\u00e9hensible compte tenu des efforts d\u00e9ploy\u00e9s par les r\u00e9fugi\u00e9s apprentis, les patrons et l\u2019\u00e9cole qui les encadrent.<\/p>\n<p><em><strong>L\u2019autorisation de travail pour suivre une formation professionnelle des adultes pourrait rem\u00e9dier au manque de main d\u2019\u0153uvre dans certains secteurs<\/strong><\/em><\/p>\n<p>L\u2019artisanat est constamment \u00e0 la recherche de main d\u2019\u0153uvre qualifi\u00e9e ou d\u2019apprentis.<\/p>\n<p>Les conditions restrictives d\u2019acc\u00e8s au travail pr\u00e9vues dans la loi sur l\u2019immigration pour les ressortissants de pays tiers ne devraient pas \u00eatre appliqu\u00e9es pour des formations professionnelles, surtout dans les secteurs en manque de main d\u2019\u0153uvre.<\/p>\n<p>Des fili\u00e8res de pr\u00e9-formation professionnelle pour adultes permettant aux inscrits d\u2019approfondir leur bagage linguistique de mani\u00e8re cibl\u00e9e et d\u2019obtenir une pr\u00e9-formation dans le domaine professionnel choisi comme c\u2019est le cas \u00e0 l\u2019EHTL[22] devraient \u00eatre possibles dans de nombreux autres domaines.<\/p>\n<p>Les \u00e9l\u00e8ves terminant une classe CLIJA (classe d\u2019int\u00e9gration jeunes adultes) avec un avis d\u2019orientation peuvent actuellement suivre un apprentissage pour adultes.<\/p>\n<p>Des pratiques positives, mais peu promues !<\/p>\n<p>L\u2019acc\u00e8s \u00e0 la formation des adultes permettrait aux personnes int\u00e9ress\u00e9es : demandeurs de protection internationale DPI, b\u00e9n\u00e9ficiaires de protection internationale BPI, mais aussi conjoints de Non UE\u2026 de mieux int\u00e9grer le march\u00e9 de l\u2019emploi luxembourgeois. La r\u00e9ussite d\u2019une pr\u00e9-formation devrait donner droit \u00e0 une autorisation de s\u00e9jour pour rechercher un emploi dans ce domaine via la formation des adultes.<\/p>\n<p>L\u2019apprentissage des adultes devrait \u00eatre accessible aux int\u00e9ress\u00e9s sans devoir justifier d\u2019une ann\u00e9e de s\u00e9jour et de travail au Luxembourg et \u00eatre assortie d\u2019une autorisation de s\u00e9jour imm\u00e9diate d\u00e8s qu\u2019un employeur est trouv\u00e9 &#8211; ceci permettrait de former des migrants \u00e0 la recherche d\u2019un emploi tout en leur assurant un revenu d\u2019au moins le salaire minimum et pourrait r\u00e9pondre au manque de main d\u2019\u0153uvre dans certains secteurs.<\/p>\n<p><em><strong>Rem\u00e9dier \u00e0 la p\u00e9nurie d\u2019emploi par une politique de reconnaissance des dipl\u00f4mes moins restrictive et plus transparente<\/strong><\/em><\/p>\n<p>Aux barri\u00e8res linguistiques s\u2019ajoutent la reconnaissance des dipl\u00f4mes et des qualifications formelles obtenues \u00e0 l\u2019\u00e9tranger. L\u2019absence de reconnaissance des dipl\u00f4mes reste un sujet phare qui freine la mobilit\u00e9 des salari\u00e9s, au sein de la Grande R\u00e9gion et au-del\u00e0, obligeant souvent \u00e0 un \u00ab empilement \u00bb de modules de formation et de certificats qui ne font pas toujours sens. La difficult\u00e9 pour nombre d\u2019\u00e9trangers d\u2019obtenir la reconnaissance de leurs dipl\u00f4mes limite leur acc\u00e8s au march\u00e9 de l\u2019emploi. Il en r\u00e9sulte que des comp\u00e9tences disponibles sur le territoire, et dont le Luxembourg a besoin, ne peuvent \u00eatre mobilis\u00e9es.[23]<\/p>\n<p>L\u2019Allemagne facilite depuis novembre 2023 la venue de travailleurs qualifi\u00e9s issus d&#8217;\u00c9tats hors de l&#8217;UE ayant une qualification professionnelle. \u00ab Wer zwei Jahre Berufserfahrung und einen Abschluss im Heimatland hat, kann als Fachkraft nach Deutschland kommen \u00bb[24]. Des voies de certification des comp\u00e9tences devront \u00eatre mises en place avec les chambres professionnelles pour ouvrir ainsi la reconnaissance de dipl\u00f4mes professionnels. Une voie int\u00e9ressante qui pourrait \u00eatre men\u00e9e dans le cadre d\u2019une politique d\u2019aide au d\u00e9veloppement responsable et\/ou de l\u2019immigration circulaire (voir ces points plus loin) afin d\u2019\u00e9viter le \u00ab Brain drain \u00bb au d\u00e9triment des pays du Sud.<\/p>\n<p>Face \u00e0 l\u2019\u00e9norme p\u00e9nurie des m\u00e9tiers de sant\u00e9, la reconnaissance des dipl\u00f4mes dans les domaines de la sant\u00e9 devrait \u00eatre revue, facilit\u00e9e, unifi\u00e9e, harmonis\u00e9e au niveau de l\u2019UE et adapt\u00e9e aux r\u00e9alit\u00e9s. Il faut cr\u00e9er des ponts au sein des organismes de formation au Luxembourg permettant ces reconnaissances. Certaines personnes issues de pays tiers, dont un nombre substantiel a la nationalit\u00e9 luxembourgeoise, sont hautement qualifi\u00e9es et jouissent d\u2019une riche exp\u00e9rience professionnelle. Certains r\u00e9sident pendant des ann\u00e9es au Luxembourg et malgr\u00e9 de multiples d\u00e9marches restent sans reconnaissance de dipl\u00f4mes et sans autorisation de travailler m\u00eame dans des domaines \u00e0 forte n\u00e9cessit\u00e9. Ces situations sont tr\u00e8s difficiles pour les personnes elles-m\u00eames, mais cela constitue aussi une perte \u00e9conomique consid\u00e9rable pour le pays, car elles ne peuvent pas exercer leur m\u00e9tier faute de reconnaissance de leur dipl\u00f4me. Ainsi, p. ex. pour les m\u00e9decins, on pourrait s\u2019imaginer que la facult\u00e9 des Sciences, des Technologies et de M\u00e9decine pourrait se charger d\u2019organiser des programmes courts de reconnaissance des dipl\u00f4mes de pays tiers en collaboration avec des h\u00f4pitaux pour la pratique. Cette probl\u00e9matique devrait \u00eatre reconnue comme urgente et prioritaire par les minist\u00e8res responsables, car on sait que 77% des sp\u00e9cialistes actuellement en exercice seront \u00e0 la retraite en 2034[25].<\/p>\n<p>Ces dossiers de reconnaissance des dipl\u00f4mes sont trait\u00e9s avec des lenteurs extr\u00eames. Il existe un manque de transparence des crit\u00e8res, du processus et des organes d\u00e9cisionnels. Il faut un r\u00e8glement clair, adapt\u00e9, compr\u00e9hensible et sens\u00e9 scientifiquement pour moderniser, harmoniser et surtout faciliter la reconnaissance.<\/p>\n<p><em><strong>Les ressortissants de pays tiers sans s\u00e9jour r\u00e9gulier au Luxembourg devraient \u00eatre r\u00e9gularis\u00e9s<\/strong><\/em><\/p>\n<p>La derni\u00e8re r\u00e9gularisation exceptionnelle a eu lieu en 2013, accordant le s\u00e9jour l\u00e9gal \u00e0 environ 670 personnes. Cela fait donc plus de 10 ans !<\/p>\n<p>Les migrants, n\u2019ayant jamais fait de demande d\u2019asile, sont au Luxembourg, travaillent sans autorisation, vivent dans la clandestinit\u00e9. Ils s\u2019exposent \u00e0 de nombreux abus et exploitations. Il est difficile de chiffrer leur nombre. Pendant la p\u00e9riode du Covid19, l\u2019ASTI avait mis en place une distribution de bons alimentaires pour les personnes en situation de s\u00e9jour irr\u00e9gulier. Cette action, financ\u00e9e par des dons priv\u00e9s et le soutien de fondations, a \u00e9t\u00e9 lanc\u00e9e pour permettre aux personnes ayant perdu leurs revenus suite \u00e0 la pand\u00e9mie de Covid19, d\u2019avoir acc\u00e8s aux produits de premi\u00e8re n\u00e9cessit\u00e9 dans les \u00e9piceries sociales g\u00e9r\u00e9es par Caritas et la Croix-Rouge. \u00ab 450 personnes ont b\u00e9n\u00e9fici\u00e9 de ce soutien, dont 160 mineurs \u00bb[26].<\/p>\n<p>Les ressortissants de pays tiers sans s\u00e9jour r\u00e9gulier au Luxembourg ou les personnes d\u00e9bout\u00e9es du droit d\u2019asile, d\u00e9j\u00e0 pr\u00e9sents sur le territoire luxembourgeois, vivent dans la clandestinit\u00e9 ou l\u2019incertitude. Elles sont exclues de toutes les mesures sociales telles que l\u2019acc\u00e8s au Revis, les allocations de vie ch\u00e8re, mais \u00e9galement les indemnit\u00e9s p\u00e9cuniaires, le ch\u00f4mage et les allocations familiales. Elles sont p\u00e9nalis\u00e9es si elles travaillent sans autorisation de s\u00e9jour, car elles risquent l\u2019expulsion, alors que les patrons qui les emploient \u00e9copent, en cas de contr\u00f4le, d\u2019amendes souvent symboliques, certains engagent par la suite la prochaine victime.<\/p>\n<p>Comment \u00e9viter de telles situations et mettre en place une r\u00e9gularisation l\u00e9gale du s\u00e9jour de ces personnes ?<\/p>\n<p>Il faut arr\u00eater de \u00ab tol\u00e9rer \u00bb des personnes sur le territoire sans leur donner une perspective r\u00e9elle. Les \u00ab tol\u00e9rances \u00bb octroy\u00e9es donnent le droit aux personnes de rester sur le territoire, sans cependant leur donner un droit de s\u00e9jour. Il faut des m\u00e9canismes clairs et transparents pour transformer ces \u00ab tol\u00e9rances \u00bb en acc\u00e8s au march\u00e9 de l\u2019emploi sans traitement des dossiers \u00ab au cas par cas \u00bb.<\/p>\n<p>L\u2019Allemagne a mis en place des m\u00e9canismes d\u2019acc\u00e8s au travail l\u00e9gal pour les ressortissants de pays tiers avec l\u2019objectif de stopper la \u00ab\u00a0 Kettenduldung \u00bb. Ces dispositions accordent une \u00ab 18-monatige Aufenthaltserlaubnis wird Menschen, die am 31. Oktober 2022 seit f\u00fcnf Jahren geduldet, gestattet oder mit einer Aufenthaltserlaubnis in Deutschland leben, nicht straff\u00e4llig geworden sind und sich zur freiheitlich demokratischen Grundordnung bekennen. Gut integrierte Jugendliche und Heranwachsende k\u00f6nnen bereits nach drei Jahren Aufenthalt sowie bis zur Vollendung des 27. Lebensjahres eine Aufenthaltserlaubnis erhalten. \u00bb[27]. Sans devoir copier cette mesure \u00e0 la lettre, une telle approche permettrait au \u00ab migrant tol\u00e9r\u00e9 \u00bb de se retrouver en situation de s\u00e9jour l\u00e9gale lorsqu\u2019il recherche des potentiels employeurs et donc faciliterait son acc\u00e8s \u00e0 l\u2019emploi.<\/p>\n<p>Dans l\u2019accord de coalition est \u00e9crit \u00ab le Gouvernement ne pr\u00e9voit pas de r\u00e9gularisation g\u00e9n\u00e9rale de r\u00e9fugi\u00e9s d\u00e9bout\u00e9s, mais pourra d\u00e9cider au cas par cas si des personnes, qui sont au Luxembourg depuis plusieurs ann\u00e9es, sans s\u2019\u00eatre soustraites \u00e0 une mesure d\u2019\u00e9loignement, pourront \u00eatre r\u00e9gularis\u00e9es \u00bb[28]. Pourquoi pr\u00e9coniser le \u00ab cas par cas \u00bb exceptionnel, sachant que plus de la moiti\u00e9 des demandes d\u2019asile sont refus\u00e9es et que beaucoup de r\u00e9fugi\u00e9s d\u00e9bout\u00e9s de leur demande d\u2019asile ne peuvent pas \u00eatre renvoy\u00e9es dans leur pays.<\/p>\n<p><em><strong>Les mesures d\u2019int\u00e9gration \u00e0 l\u2019emploi doivent \u00eatre compl\u00e9mentaires \u00e0 la politique migratoire et cibler un accompagnement individuel \u00e0 l\u2019emploi d\u00e8s l\u2019arriv\u00e9e au pays<\/strong><\/em><\/p>\n<p>L\u2019\u00e9tude Migrant Integration Policy Index MIPEX 2020[29] souligne l\u2019absence au Luxembourg de parcours d\u2019accompagnement individuel facilitant l\u2019int\u00e9gration \u00e0 l\u2019emploi. Un tel parcours inclut, d\u00e8s l\u2019arriv\u00e9e au pays, un accueil structur\u00e9 du migrant ou du r\u00e9fugi\u00e9 dans le but de l\u2019int\u00e9grer rapidement au march\u00e9 du travail. Il permet d\u2019\u00e9valuer les possibilit\u00e9s r\u00e9elles d\u2019emploi \/ de formation \/ d\u2019orientation professionnelle d\u00e8s l\u2019arriv\u00e9e au pays d\u2019accueil. Ces programmes d\u2019insertion et de parcours \u00e0 l\u2019emploi de migrants permettraient d\u00e8s leur arriv\u00e9e d\u2019\u00eatre orient\u00e9s, de les former aux exigences de notre march\u00e9 de l\u2019emploi. Des exp\u00e9riences comme celles acquises dans le programme Coach4Work de l\u2019ASTI qui met \u00e0 disposition de personnes \u00e0 la recherche d\u2019un emploi un coach \u00e0 l\u2019emploi b\u00e9n\u00e9vole devraient \u00eatre institutionnalis\u00e9es et \u00e9largies.[30]<\/p>\n<p>N\u2019oublions pas que de nombreuses personnes immigrent suite \u00e0 un mariage ou \u00e0 un regroupement familial. Elles pourraient aussi profiter d\u2019un tel accompagnement.<\/p>\n<p><em><strong>Mener une politique d\u2019aide au d\u00e9veloppement responsable favorisant l\u2019immigration circulaire et des voies d\u2019entr\u00e9e l\u00e9gales de migrants \u00e0 travers des programmes de d\u00e9veloppement du Minist\u00e8re de la Coop\u00e9ration<\/strong><\/em><\/p>\n<p>L\u2019immigration circulaire d\u00e9signe une forme de migration g\u00e9r\u00e9e de fa\u00e7on \u00e0 permettre un certain degr\u00e9 de mobilit\u00e9 l\u00e9gal, dans les deux sens, entre deux pays. Vivre et travailler dans un autre pays, y partager et renforcer ses comp\u00e9tences, \u00e9largir son r\u00e9seau de contacts, puis retourner dans son pays d\u2019origine permettrait de profiter des plus-values de l\u2019exp\u00e9rience migratoire. Un timide essai dans ce sens a \u00e9t\u00e9 r\u00e9alis\u00e9 avec le Cap-Vert, mais sans \u00e9valuation connue pour l\u2019instant. Une immigration circulaire r\u00e9pondrait \u00e0 la n\u00e9cessit\u00e9 des pays d\u2019origine de b\u00e9n\u00e9ficier de transferts de comp\u00e9tences et d\u2019att\u00e9nuer les cons\u00e9quences de la fuite des cerveaux.<\/p>\n<p>On pourrait ainsi proposer des voies d\u2019entr\u00e9e l\u00e9gales aux migrants \u00e0 travers des programmes de d\u00e9veloppement soutenus par le Minist\u00e8re de la Coop\u00e9ration. Cr\u00e9er des programmes de d\u00e9veloppement visant l\u2019acc\u00e8s \u00e0 l\u2019exp\u00e9rience professionnelle dans nos entreprises et proposant au migrant qui retourne, apr\u00e8s un certain temps, dans son pays d\u2019origine, une perspective d\u2019emploi gr\u00e2ce \u00e0 un projet de d\u00e9veloppement, serait profitable pour tous.<\/p>\n<p style=\"text-align: center;\">***<\/p>\n<p>Le Luxembourg laisse passer le potentiel de beaucoup de personnes en adoptant des politiques d\u2019immigration, de formation et d\u2019insertion \u00e0 l\u2019emploi restrictives et arbitraires, privil\u00e9giant le \u00ab cas par cas \u00bb.<\/p>\n<p>L\u2019ADN du Luxembourg est son interculturalit\u00e9 et la diversit\u00e9 de ses habitants, et cela, depuis plus de 100 ans. Afin de rendre justice \u00e0 cette r\u00e9alit\u00e9 qui enrichit le Luxembourg et qui fait que nous sommes ce que nous sommes, il faut valoriser les personnes qui y vivent. Il faut arr\u00eater d\u2019emp\u00eacher les personnes de travailler au Luxembourg et ainsi de contribuer \u00e0 notre \u00e9conomie et vivre dignement. Les pousser vers la clandestinit\u00e9 ou leur donner que le choix de l\u2019asile pour acc\u00e9der l\u00e9galement au Luxembourg est contreproductif et entra\u00eene de nombreux probl\u00e8mes.<\/p>\n<p>Nous avons besoin d\u2019une politique migratoire accueillante et courageuse, reconnaissant et valorisant le potentiel des personnes d\u00e9sirant s\u2019installer au Luxembourg.<\/p>\n<p><em><span style=\"font-size: 10pt;\">Photo de <a href=\"https:\/\/unsplash.com\/fr\/@christianlue?utm_content=creditCopyText&amp;utm_medium=referral&amp;utm_source=unsplash\" target=\"_blank\" rel=\"noopener\"><span style=\"text-decoration: underline;\">Christian Lue<\/span><\/a> sur <a href=\"https:\/\/unsplash.com\/fr\/photos\/carte-blanche-rouge-et-verte-7dEyTJ7-8os?utm_content=creditCopyText&amp;utm_medium=referral&amp;utm_source=unsplash\" target=\"_blank\" rel=\"noopener\"><span style=\"text-decoration: underline;\">Unsplash<\/span><\/a><\/span><\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Face aux d\u00e9fis et opportunit\u00e9s de l\u2019immigration au Luxembourg, il faut imaginer une politique migratoire aussi dynamique que les flux migratoires, adapt\u00e9e \u00e0 la r\u00e9alit\u00e9 du march\u00e9 de l\u2019emploi et aux motifs d\u2019immigration.<\/p>\n","protected":false},"author":31,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-1628","post","type-post","status-publish","format-standard","hentry","category-uncategorized","topic-education","topic-inequalities","topic-work","format-text"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>R\u00e9flexions pour une politique d\u2019immigration adapt\u00e9e \u00e0 la r\u00e9alit\u00e9 - Improof<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dev.improof.lu\/en\/articles\/reflexions-politique-d-immigration\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"R\u00e9flexions pour une politique d\u2019immigration adapt\u00e9e \u00e0 la r\u00e9alit\u00e9\" \/>\n<meta property=\"og:description\" content=\"Face aux d\u00e9fis et opportunit\u00e9s de l\u2019immigration au Luxembourg, il faut imaginer une politique migratoire aussi dynamique que les flux migratoires, adapt\u00e9e \u00e0 la r\u00e9alit\u00e9 du march\u00e9 de l\u2019emploi et aux motifs d\u2019immigration.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dev.improof.lu\/en\/articles\/reflexions-politique-d-immigration\/\" \/>\n<meta property=\"og:site_name\" content=\"Improof\" \/>\n<meta property=\"article:published_time\" content=\"2024-01-30T15:10:45+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-01-31T15:08:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dev.improof.lu\/app\/uploads\/2024\/01\/globe.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1076\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Laura Zuccoli\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"R\u00e9flexions pour une politique d\u2019immigration adapt\u00e9e \u00e0 la r\u00e9alit\u00e9\" \/>\n<meta name=\"twitter:description\" content=\"Face aux d\u00e9fis et opportunit\u00e9s de l\u2019immigration au Luxembourg, il faut imaginer une politique migratoire aussi dynamique que les flux migratoires, adapt\u00e9e \u00e0 la r\u00e9alit\u00e9 du march\u00e9 de l\u2019emploi et aux motifs d\u2019immigration.\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/dev.improof.lu\/app\/uploads\/2024\/01\/globe.jpg\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Laura Zuccoli\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"27 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/dev.improof.lu\/en\/articles\/reflexions-politique-d-immigration\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dev.improof.lu\/en\/articles\/reflexions-politique-d-immigration\/\"},\"author\":{\"name\":\"Laura Zuccoli\",\"@id\":\"https:\/\/dev.improof.lu\/en\/#\/schema\/person\/96e34443189e0d2cd58cf2a7aa456c59\"},\"headline\":\"R\u00e9flexions pour une politique d\u2019immigration adapt\u00e9e \u00e0 la r\u00e9alit\u00e9\",\"datePublished\":\"2024-01-30T15:10:45+00:00\",\"dateModified\":\"2024-01-31T15:08:05+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dev.improof.lu\/en\/articles\/reflexions-politique-d-immigration\/\"},\"wordCount\":5394,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dev.improof.lu\/en\/#organization\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dev.improof.lu\/en\/articles\/reflexions-politique-d-immigration\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dev.improof.lu\/en\/articles\/reflexions-politique-d-immigration\/\",\"url\":\"https:\/\/dev.improof.lu\/en\/articles\/reflexions-politique-d-immigration\/\",\"name\":\"R\u00e9flexions pour une politique d\u2019immigration adapt\u00e9e \u00e0 la r\u00e9alit\u00e9 - Improof\",\"isPartOf\":{\"@id\":\"https:\/\/dev.improof.lu\/en\/#website\"},\"datePublished\":\"2024-01-30T15:10:45+00:00\",\"dateModified\":\"2024-01-31T15:08:05+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/dev.improof.lu\/en\/articles\/reflexions-politique-d-immigration\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dev.improof.lu\/en\/articles\/reflexions-politique-d-immigration\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dev.improof.lu\/en\/articles\/reflexions-politique-d-immigration\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/dev.improof.lu\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"R\u00e9flexions pour une politique d\u2019immigration adapt\u00e9e \u00e0 la r\u00e9alit\u00e9\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dev.improof.lu\/en\/#website\",\"url\":\"https:\/\/dev.improof.lu\/en\/\",\"name\":\"Improof\",\"description\":\"Tagline goes here\",\"publisher\":{\"@id\":\"https:\/\/dev.improof.lu\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dev.improof.lu\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/dev.improof.lu\/en\/#organization\",\"name\":\"Improof\",\"url\":\"https:\/\/dev.improof.lu\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/dev.improof.lu\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dev.improof.lu\/app\/uploads\/2022\/10\/improof-logo-svg.png\",\"contentUrl\":\"https:\/\/dev.improof.lu\/app\/uploads\/2022\/10\/improof-logo-svg.png\",\"width\":652,\"height\":209,\"caption\":\"Improof\"},\"image\":{\"@id\":\"https:\/\/dev.improof.lu\/en\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dev.improof.lu\/en\/#\/schema\/person\/96e34443189e0d2cd58cf2a7aa456c59\",\"name\":\"Laura Zuccoli\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/dev.improof.lu\/en\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/0eff38bbf3cb393c307b30a8f418dddb?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/0eff38bbf3cb393c307b30a8f418dddb?s=96&d=mm&r=g\",\"caption\":\"Laura Zuccoli\"},\"url\":\"https:\/\/dev.improof.lu\/en\/articles\/author\/zuccoli-laura\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"R\u00e9flexions pour une politique d\u2019immigration adapt\u00e9e \u00e0 la r\u00e9alit\u00e9 - Improof","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dev.improof.lu\/en\/articles\/reflexions-politique-d-immigration\/","og_locale":"en_US","og_type":"article","og_title":"R\u00e9flexions pour une politique d\u2019immigration adapt\u00e9e \u00e0 la r\u00e9alit\u00e9","og_description":"Face aux d\u00e9fis et opportunit\u00e9s de l\u2019immigration au Luxembourg, il faut imaginer une politique migratoire aussi dynamique que les flux migratoires, adapt\u00e9e \u00e0 la r\u00e9alit\u00e9 du march\u00e9 de l\u2019emploi et aux motifs d\u2019immigration.","og_url":"https:\/\/dev.improof.lu\/en\/articles\/reflexions-politique-d-immigration\/","og_site_name":"Improof","article_published_time":"2024-01-30T15:10:45+00:00","article_modified_time":"2024-01-31T15:08:05+00:00","og_image":[{"width":1920,"height":1076,"url":"https:\/\/dev.improof.lu\/app\/uploads\/2024\/01\/globe.jpg","type":"image\/jpeg"}],"author":"Laura Zuccoli","twitter_card":"summary_large_image","twitter_title":"R\u00e9flexions pour une politique d\u2019immigration adapt\u00e9e \u00e0 la r\u00e9alit\u00e9","twitter_description":"Face aux d\u00e9fis et opportunit\u00e9s de l\u2019immigration au Luxembourg, il faut imaginer une politique migratoire aussi dynamique que les flux migratoires, adapt\u00e9e \u00e0 la r\u00e9alit\u00e9 du march\u00e9 de l\u2019emploi et aux motifs d\u2019immigration.","twitter_image":"https:\/\/dev.improof.lu\/app\/uploads\/2024\/01\/globe.jpg","twitter_misc":{"Written by":"Laura Zuccoli","Est. reading time":"27 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/dev.improof.lu\/en\/articles\/reflexions-politique-d-immigration\/#article","isPartOf":{"@id":"https:\/\/dev.improof.lu\/en\/articles\/reflexions-politique-d-immigration\/"},"author":{"name":"Laura Zuccoli","@id":"https:\/\/dev.improof.lu\/en\/#\/schema\/person\/96e34443189e0d2cd58cf2a7aa456c59"},"headline":"R\u00e9flexions pour une politique d\u2019immigration adapt\u00e9e \u00e0 la r\u00e9alit\u00e9","datePublished":"2024-01-30T15:10:45+00:00","dateModified":"2024-01-31T15:08:05+00:00","mainEntityOfPage":{"@id":"https:\/\/dev.improof.lu\/en\/articles\/reflexions-politique-d-immigration\/"},"wordCount":5394,"commentCount":0,"publisher":{"@id":"https:\/\/dev.improof.lu\/en\/#organization"},"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dev.improof.lu\/en\/articles\/reflexions-politique-d-immigration\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/dev.improof.lu\/en\/articles\/reflexions-politique-d-immigration\/","url":"https:\/\/dev.improof.lu\/en\/articles\/reflexions-politique-d-immigration\/","name":"R\u00e9flexions pour une politique d\u2019immigration adapt\u00e9e \u00e0 la r\u00e9alit\u00e9 - Improof","isPartOf":{"@id":"https:\/\/dev.improof.lu\/en\/#website"},"datePublished":"2024-01-30T15:10:45+00:00","dateModified":"2024-01-31T15:08:05+00:00","breadcrumb":{"@id":"https:\/\/dev.improof.lu\/en\/articles\/reflexions-politique-d-immigration\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dev.improof.lu\/en\/articles\/reflexions-politique-d-immigration\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/dev.improof.lu\/en\/articles\/reflexions-politique-d-immigration\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/dev.improof.lu\/en\/"},{"@type":"ListItem","position":2,"name":"R\u00e9flexions pour une politique d\u2019immigration adapt\u00e9e \u00e0 la r\u00e9alit\u00e9"}]},{"@type":"WebSite","@id":"https:\/\/dev.improof.lu\/en\/#website","url":"https:\/\/dev.improof.lu\/en\/","name":"Improof","description":"Tagline goes here","publisher":{"@id":"https:\/\/dev.improof.lu\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dev.improof.lu\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/dev.improof.lu\/en\/#organization","name":"Improof","url":"https:\/\/dev.improof.lu\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/dev.improof.lu\/en\/#\/schema\/logo\/image\/","url":"https:\/\/dev.improof.lu\/app\/uploads\/2022\/10\/improof-logo-svg.png","contentUrl":"https:\/\/dev.improof.lu\/app\/uploads\/2022\/10\/improof-logo-svg.png","width":652,"height":209,"caption":"Improof"},"image":{"@id":"https:\/\/dev.improof.lu\/en\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/dev.improof.lu\/en\/#\/schema\/person\/96e34443189e0d2cd58cf2a7aa456c59","name":"Laura Zuccoli","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/dev.improof.lu\/en\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/0eff38bbf3cb393c307b30a8f418dddb?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0eff38bbf3cb393c307b30a8f418dddb?s=96&d=mm&r=g","caption":"Laura Zuccoli"},"url":"https:\/\/dev.improof.lu\/en\/articles\/author\/zuccoli-laura\/"}]}},"_links":{"self":[{"href":"https:\/\/dev.improof.lu\/en\/wp-json\/wp\/v2\/posts\/1628","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.improof.lu\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dev.improof.lu\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dev.improof.lu\/en\/wp-json\/wp\/v2\/users\/31"}],"replies":[{"embeddable":true,"href":"https:\/\/dev.improof.lu\/en\/wp-json\/wp\/v2\/comments?post=1628"}],"version-history":[{"count":3,"href":"https:\/\/dev.improof.lu\/en\/wp-json\/wp\/v2\/posts\/1628\/revisions"}],"predecessor-version":[{"id":1691,"href":"https:\/\/dev.improof.lu\/en\/wp-json\/wp\/v2\/posts\/1628\/revisions\/1691"}],"wp:attachment":[{"href":"https:\/\/dev.improof.lu\/en\/wp-json\/wp\/v2\/media?parent=1628"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dev.improof.lu\/en\/wp-json\/wp\/v2\/categories?post=1628"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dev.improof.lu\/en\/wp-json\/wp\/v2\/tags?post=1628"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}