{"id":2114,"date":"2024-10-03T10:02:39","date_gmt":"2024-10-03T10:02:39","guid":{"rendered":"https:\/\/dev.improof.lu\/?p=2114"},"modified":"2024-10-03T10:02:40","modified_gmt":"2024-10-03T10:02:40","slug":"financiarisation-du-foncier-constructible","status":"publish","type":"post","link":"https:\/\/dev.improof.lu\/en\/articles\/financiarisation-du-foncier-constructible\/","title":{"rendered":"La financiarisation du foncier constructible, vecteur principal de la crise du logement"},"content":{"rendered":"<h2>Appelons un chat un chat !<\/h2>\n<p>Cet article vise \u00e0 alimenter et stimuler le d\u00e9bat politique et soci\u00e9tal sur l\u2019imposition \u00e9quitable des plus-values et des rentes fonci\u00e8res. L\u2019introduction offre un panorama de la structure du march\u00e9 du foncier constructible et de ses cons\u00e9quences socio-\u00e9conomiques souvent n\u00e9fastes. La deuxi\u00e8me partie analyse les diff\u00e9rentes raisons pour lesquelles le foncier constructible est un bien qui m\u00e9rite un traitement fiscal particulier et dont la fiscalit\u00e9 devrait \u00eatre r\u00e9form\u00e9e en profondeur le plus rapidement possible. La derni\u00e8re partie propose plusieurs mesures pour baisser de mani\u00e8re progressive la rente fonci\u00e8re \u00e0 un niveau \u00e9conomiquement efficace et socialement acceptable.<\/p>\n<h2>La sp\u00e9culation et la r\u00e9tention fonci\u00e8res au Luxembourg<\/h2>\n<p>Dans le contexte de la crise du logement, et plus particuli\u00e8rement depuis le ralentissement important de l\u2019activit\u00e9 dans le secteur de la construction r\u00e9sidentielle, d\u00fb entre autres \u00e0 une politique mon\u00e9taire moins accommodante et \u00e0 l\u2019envol\u00e9e des prix de la construction, les diff\u00e9rents repr\u00e9sentants du secteur se livrent \u00e0 une surench\u00e8re d\u2019appels politiques cens\u00e9s relancer le march\u00e9.<\/p>\n<p>Leurs revendications, souvent couronn\u00e9es de succ\u00e8s[1], se focalisent g\u00e9n\u00e9ralement sur la simplification des proc\u00e9dures administratives et environnementales ou sur le subventionnement \u00e9tatique de b\u00e9n\u00e9fices priv\u00e9s par des aides financi\u00e8res qui p\u00e8sent lourdement sur les finances publiques.<\/p>\n<p>Cependant, au lieu de promouvoir la financiarisation accentu\u00e9e du march\u00e9 de l\u2019immobilier r\u00e9sidentiel \u2013 lui-m\u00eame vecteur de la crise du logement \u2013 par des subventions publiques co\u00fbteuses, r\u00e9gressives et g\u00e9n\u00e9ralement inefficaces, dont profitent en premier lieu les promoteurs et les multi-propri\u00e9taires, il serait pr\u00e9f\u00e9rable de s\u2019attaquer enfin \u00e0 la racine du probl\u00e8me : la rar\u00e9faction artificielle de terrains \u00e0 b\u00e2tir, provoqu\u00e9e \u00e0 dessein par un cercle exclusif de propri\u00e9taires fonciers.<\/p>\n<p><strong>L\u2019acc\u00e8s restreint au foncier constructible : barri\u00e8re primaire \u00e0 la dynamisation de la production de logements<\/strong><\/p>\n<p>Hormis le r\u00e9cent revirement de la politique mon\u00e9taire de la Banque centrale europ\u00e9enne (BCE), qui a entra\u00een\u00e9 une chute des investissements priv\u00e9s dans l&#8217;immobilier r\u00e9sidentiel et, par cons\u00e9quent, de la production de logements \u00e0 court et moyen terme, nous constatons que l\u2019activit\u00e9 enregistr\u00e9e en amont du choc inflationniste et du resserrement de la politique mon\u00e9taire \u00e9tait d\u00e9j\u00e0 largement insuffisante face \u00e0 l\u2019augmentation du nombre de m\u00e9nages.<\/p>\n<p>En effet, malgr\u00e9 le contexte fiscal extr\u00eamement favorable qui r\u00e9gnait tout au long de la d\u00e9cennie pr\u00e9c\u00e9dente \u2013 amortissement acc\u00e9l\u00e9r\u00e9, d\u00e9ductibilit\u00e9 int\u00e9grale des int\u00e9r\u00eats, etc. \u2013 ainsi que les taux d\u2019int\u00e9r\u00eat historiquement bas ayant soutenu l\u2019essor du march\u00e9 de l\u2019immobilier, force est de constater que ce succ\u00e8s de l\u2019investissement dans la pierre n\u2019a pas entrain\u00e9 une hausse suffisante au niveau de l\u2019offre de logements. Tout au contraire, celle-ci s\u2019est av\u00e9r\u00e9e peu \u00e9lastique : alors que le nombre de logements achev\u00e9s par an est rest\u00e9 stable, le nombre de nouveaux m\u00e9nages a \u00e9volu\u00e9 \u00e0 un rythme nettement plus dynamique durant cette p\u00e9riode et le d\u00e9s\u00e9quilibre entre offre et demande s&#8217;est ainsi fortement accentu\u00e9.<\/p>\n<p>Ce profond d\u00e9s\u00e9quilibre est principalement d\u00fb \u00e0 une s\u00e9rie d&#8217;obstacles structurels qui p\u00e8sent lourdement sur le volume et le prix de la production de logements. Il s\u2019agit en premier lieu de l&#8217;acc\u00e8s de plus en plus difficile et co\u00fbteux aux terrains \u00e0 b\u00e2tir.<\/p>\n<p><strong>La structure oligopolistique du march\u00e9 du foncier au Luxembourg<\/strong><\/p>\n<p>Le travail de recherche consid\u00e9rable, men\u00e9 notamment par l\u2019Observatoire de l\u2019habitat, nous offre un aper\u00e7u d\u00e9taill\u00e9 et r\u00e9v\u00e9lateur de l\u2019ampleur de la sp\u00e9culation et de la r\u00e9tention fonci\u00e8re au Luxembourg, qui appara\u00eet ainsi comme le principal vecteur de la crise du logement.<\/p>\n<p>Tout d\u2019abord, les chercheurs soulignent qu\u2019il existe une r\u00e9serve fonci\u00e8re consid\u00e9rable et relativement stable aux alentours de 4.300 hectares qui permettrait th\u00e9oriquement de construire environ 161.500 logements (aux densit\u00e9s actuelles) pouvant accueillir jusqu\u2019\u00e0 371.500 personnes, ce qui serait suffisant pour atteindre le seuil du million d\u2019habitants.[2]<\/p>\n<p>Les \u00e9tudes de l\u2019Observatoire d\u00e9crivent un march\u00e9 du foncier \u00e0 structure oligopolistique \u2013 le degr\u00e9 de concentration de la d\u00e9tention du potentiel foncier destin\u00e9 \u00e0 l\u2019habitat est tr\u00e8s \u00e9lev\u00e9 et la majorit\u00e9 des terrains se trouve dans les mains d\u2019une petite minorit\u00e9 de personnes ou de soci\u00e9t\u00e9s priv\u00e9es.[3]<\/p>\n<p>L\u2019analyse de la dynamique historique de la propri\u00e9t\u00e9 fonci\u00e8re au niveau local a r\u00e9v\u00e9l\u00e9 qu\u2019il existe d\u2019importantes dynasties familiales qui transmettent et conservent leurs biens fonciers de g\u00e9n\u00e9ration en g\u00e9n\u00e9ration, en sp\u00e9culant sur l\u2019accroissement de la valeur \u00e0 long terme. Ce mode op\u00e9ratoire est favoris\u00e9 par une imposition r\u00e9currente trop timide respectivement par l\u2019absence d\u2019imp\u00f4t sur les successions en ligne directe.[4]<\/p>\n<p>En outre, le march\u00e9 se caract\u00e9rise par un ph\u00e9nom\u00e8ne de \u00ab double concentration \u00bb[5] : les grands promoteurs locaux figurent \u00e9galement parmi les principaux propri\u00e9taires fonciers, une situation qu\u2019ils exploitent pour contr\u00f4ler l\u2019offre et les prix.[6]<\/p>\n<p>Cette concentration du pouvoir de march\u00e9 et la financiarisation du sol \u2013 les terrains constructibles sont avant tout consid\u00e9r\u00e9s comme des placements financiers en raison de leur forte rentabilit\u00e9 et de leur r\u00e9sistance aux fluctuations des march\u00e9s financiers \u2013 favorisent les comportements sp\u00e9culatifs et la r\u00e9tention fonci\u00e8re.<\/p>\n<p>Ce n\u2019est donc pas la raret\u00e9 de terrains constructibles qui est responsable des prix \u00e9lev\u00e9s, mais plut\u00f4t leur monopolisation ! La majeure partie de la r\u00e9serve fonci\u00e8re est d\u00e9tenue par un cercle restreint de propri\u00e9taires fortun\u00e9s, ce qui leur permet non seulement de contr\u00f4ler le niveau de l&#8217;offre et donc l&#8217;\u00e9volution future des prix de l&#8217;immobilier par le biais du rythme de la commercialisation, mais aussi d&#8217;orienter l&#8217;am\u00e9nagement du territoire, tant du point de vue de l&#8217;urbanisme que de la composition sociale.<\/p>\n<p><strong>Un risque socio-\u00e9conomique multidimensionnel<\/strong><\/p>\n<p>Cette concentration de la d\u00e9tention du foncier constructible conf\u00e8re \u00e0 cette classe sociale ais\u00e9e un poids socio-\u00e9conomique et politique totalement d\u00e9mesur\u00e9, difficilement compatible avec une soci\u00e9t\u00e9 d\u00e9mocratique.<\/p>\n<p>De surcro\u00eet, cette situation est d\u2019autant plus regrettable que les int\u00e9r\u00eats priv\u00e9s des propri\u00e9taires divergent r\u00e9guli\u00e8rement de ceux de la collectivit\u00e9 : les premiers poursuivent une vision \u00e0 long terme visant l\u2019extraction de la plus grande part possible de la richesse cr\u00e9\u00e9e par la soci\u00e9t\u00e9, tandis que les seconds ont besoin d\u2019une valorisation \u00e0 court terme (une th\u00e9rapie de choc) en vue d\u2019une forte dynamisation de la cr\u00e9ation de logements abordables et durables.<\/p>\n<p>Compte tenu du contexte \u00e9conomique et mon\u00e9taire actuel, qui a fortement affect\u00e9 les capacit\u00e9s financi\u00e8res des m\u00e9nages, les prix de l\u2019immobilier artificiellement dop\u00e9s[7] ont entrain\u00e9 un net ralentissement de l\u2019activit\u00e9 dans le secteur de la construction et comportent donc le risque d\u2019une destruction importante et potentiellement permanente d\u2019emplois et de tissu productif. Ce ph\u00e9nom\u00e8ne devrait toucher en premier lieu les petites et moyennes entreprises (PME) qui ne sont pas int\u00e9gr\u00e9es dans la cha\u00eene de valeur d\u2019un grand promoteur immobilier.<\/p>\n<p>En sus, il convient de noter que l&#8217;approche sp\u00e9culative des grands propri\u00e9taires fonciers pourrait s&#8217;av\u00e9rer myope et se retourner finalement contre eux si la crise du logement s&#8217;aggravait au point d&#8217;avoir un impact n\u00e9gatif s\u00e9rieux sur le d\u00e9veloppement \u00e9conomique du Luxembourg, annulant ainsi toutes les plus-values potentielles futures.<\/p>\n<h2>Un bien commun qui m\u00e9rite un traitement fiscal particulier<\/h2>\n<p>Le r\u00f4le de l\u2019acc\u00e8s artificiellement limit\u00e9 aux terrains constructibles dans le contexte de la crise du logement est donc bien document\u00e9 et g\u00e9n\u00e9ralement accept\u00e9.[8] Moins discut\u00e9es sont cependant les raisons pour lesquelles le foncier constructible est un bien qui m\u00e9rite un traitement fiscal tr\u00e8s particulier et fort diff\u00e9rent d\u2019autres formes de patrimoine (actifs financiers, etc.). En effet, les arguments en faveur d&#8217;un changement de paradigme dans la fiscalit\u00e9 du foncier vont bien au-del\u00e0 de la simple n\u00e9cessit\u00e9 de mobiliser le foncier pour lutter contre la p\u00e9nurie de logements.<\/p>\n<p><strong>Lutter contre la marchandisation du sol<\/strong><\/p>\n<p>La terre n\u2019est pas une marchandise comme les autres. Son acc\u00e8s est limit\u00e9, elle ne peut pas \u00eatre multipli\u00e9e et personne ne peut s\u2019en passer. Par cons\u00e9quent, son prix \u00e9volue au Luxembourg \u00e0 un rythme g\u00e9n\u00e9ralement sup\u00e9rieur \u00e0 la croissance de la richesse produite par la soci\u00e9t\u00e9 luxembourgeoise et les propri\u00e9taires fonciers s&#8217;en approprient ainsi une part toujours croissante. Il est donc indispensable de changer de paradigme et de limiter la rentabilit\u00e9 de la commercialisation du foncier \u00e0 un niveau qui soit socialement acceptable et qui permette de lutter contre les ph\u00e9nom\u00e8nes pr\u00e9cit\u00e9s.<\/p>\n<p><strong>La diff\u00e9rence entre cr\u00e9ation et extraction de richesse<\/strong><\/p>\n<p>\u00c0 cette fin, il faut tout d\u2019abord diff\u00e9rencier entre deux types d\u2019investissement :<\/p>\n<p>d\u2019un c\u00f4t\u00e9, il y a les investissements \u00ab productifs \u00bb (\u00ab Wealth Creation \u00bb) qui apportent un gain \u00e9conomique, social, environnemental, etc. \u00e0 la soci\u00e9t\u00e9.\u00a0 Il peut s\u2019agir d\u2019investissements qui augmentent la cr\u00e9ation de richesse ou qui sont vecteurs du bien-\u00eatre humain ou de la coh\u00e9sion sociale \u2013 investissements dans l\u2019innovation, la recherche et le d\u00e9veloppement, le capital technique (installations, machines, outillages), l\u2019\u00e9ducation, la sant\u00e9, etc.<\/p>\n<p>De l\u2019autre c\u00f4t\u00e9, il y a les investissements \u00ab improductifs \u00bb (\u00ab Rent Seeking \u00bb), ind\u00e9sirables d\u2019un point de vue \u00e9conomique ou social. La r\u00e9tention et la sp\u00e9culation fonci\u00e8res en sont un exemple typique. Il s\u2019agit d\u2019investissements inertes et improductifs qui ne g\u00e9n\u00e8rent ni croissance, ni richesse, ni bien-\u00eatre humain et qui n\u2019apportent aucune plus-value socio-\u00e9conomique \u00e0 la soci\u00e9t\u00e9. Leur objectif consiste dans la seule extraction d\u2019une partie croissante de la richesse d\u00e9j\u00e0 existante au profit de rentiers et au d\u00e9triment du reste de la soci\u00e9t\u00e9 qui n\u2019en tire non seulement aucun b\u00e9n\u00e9fice, mais qui souffre m\u00eame des cons\u00e9quences socio-\u00e9conomiques n\u00e9fastes du ph\u00e9nom\u00e8ne.<\/p>\n<p>Ces deux types d\u2019investissement se laissent repr\u00e9senter par une all\u00e9gorie bien connue : tandis que les premiers augmentent la taille du g\u00e2teau, les seconds ne visent qu&#8217;\u00e0 s&#8217;approprier une part maximale du g\u00e2teau d\u00e9j\u00e0 existant, provoquant ainsi une polarisation accrue de la richesse dans les mains de cette couche privil\u00e9gi\u00e9e.<\/p>\n<p>Dans le cas du Luxembourg, ces investissements risquent de siphonner \u00e0 la fois les ressources naturelles n\u00e9cessaires pour calmer la crise du droit au logement (le foncier) et les ressources financi\u00e8res n\u00e9cessaires aux investissements indispensables afin de faire face aux nombreux d\u00e9fis de notre \u00e8re (in\u00e9galit\u00e9s sociales, crise climatique, crise du logement, etc.).<\/p>\n<p><strong>Une plus-value cr\u00e9\u00e9e par la soci\u00e9t\u00e9, mais capt\u00e9e par les propri\u00e9taires<\/strong><\/p>\n<p>Outre le fait que les propri\u00e9taires ne cherchent qu&#8217;\u00e0 exploiter au maximum les richesses au d\u00e9triment du reste de la population, il faut en m\u00eame temps souligner que la plus-value qu\u2019ils g\u00e9n\u00e8rent \u00e0 l\u2019issue de la sp\u00e9culation fonci\u00e8re n\u2019est pas le r\u00e9sultat de leur investissement, mais le fruit du travail du collectif.<\/p>\n<p>Le foncier en soi n\u2019a aucune valeur inh\u00e9rente. Sa valeur r\u00e9sulte et d\u00e9pend du seul effort de la soci\u00e9t\u00e9 qui rend ce lieu attractif : progr\u00e8s \u00e9conomique, l\u2019acc\u00e8s aux infrastructures publiques (\u00e9ducation, transport, etc.) financ\u00e9es par ce m\u00eame collectif, croissance d\u00e9mographique, stabilit\u00e9 politique et coh\u00e9sion sociale (mis en danger par la sp\u00e9culation fonci\u00e8re), etc.<\/p>\n<p>Cependant, consid\u00e9rant le traitement fiscal favorable des rentes fonci\u00e8res au Luxembourg, la soci\u00e9t\u00e9 ne r\u00e9cup\u00e8re dans le meilleur des cas qu\u2019une partie infime de cette richesse qu\u2019elle a en fait cr\u00e9\u00e9e elle-m\u00eame.<\/p>\n<p>Pire encore, la soci\u00e9t\u00e9 est victime de cette extraction. Non seulement le propri\u00e9taire du terrain ne produit \u00e0 travers la d\u00e9tention du foncier pas de plus-value pour la soci\u00e9t\u00e9, mais l\u2019impact de son comportement est plut\u00f4t \u00e0 consid\u00e9rer comme \u00ab moins-value \u00bb, car la soci\u00e9t\u00e9 subit les cons\u00e9quences \u00e9conomiques et sociales n\u00e9fastes de ses actes.<\/p>\n<p><strong>Une extraction de richesse qui p\u00e8se sur l\u2019int\u00e9gralit\u00e9 de la cha\u00eene de valeur et qui provoque une redistribution gigantesque en faveur des propri\u00e9taires terriens<\/strong><\/p>\n<p>Notons que l\u2019impact de l\u2019extraction de la richesse \u00e0 travers la rente fonci\u00e8re ne se limite \u00e9videmment pas au seul prix du foncier ou de l\u2019immeuble y construit, mais qu\u2019elle se r\u00e9pand in fine sur toute la cha\u00eene de valeur et toute la soci\u00e9t\u00e9 : le secteur de la construction et l\u2019artisanat qui doivent r\u00e9duire leurs marges ou augmenter la pression sur les salaires afin d\u2019\u00e9viter que le prix final de l\u2019immeuble ne d\u00e9passe les capacit\u00e9s financi\u00e8res des acqu\u00e9reurs ; les derniers qui doivent s\u2019endetter fortement ; les occupants qui doivent soit payer un prix d\u00e9mesur\u00e9, soit un loyer exorbitant car la valeur dop\u00e9e du foncier est prise en compte lors du calcul, et puis tout le reste de la soci\u00e9t\u00e9 vu que les occupants (par exemple dans le cas d\u2019un bail commercial) doivent r\u00e9cup\u00e9rer leurs co\u00fbts \u00e0 travers une hausse du prix du service qu\u2019ils offrent (coiffeur, etc.) ou des biens qu\u2019ils commercialisent (caf\u00e9, croissant, etc.).<\/p>\n<p>Plus absurde encore, le locataire d&#8217;un local commercial, par son esprit d&#8217;entreprise, augmente lui-m\u00eame l&#8217;offre et donc l&#8217;attractivit\u00e9 du quartier\/lieu et donc la valeur du terrain dont il est locataire, dynamique qui se traduit in fine par l&#8217;\u00e9volution \u00e0 la hausse de son propre loyer. Ainsi, par le biais du loyer (la rente), il paie indirectement l\u2019augmentation de la valeur du terrain qu&#8217;il a lui-m\u00eame cr\u00e9\u00e9e.<\/p>\n<p>D&#8217;un point de vue macro\u00e9conomique, la faible imposition des rentes fonci\u00e8res favorise donc une extraction continue et une gigantesque redistribution, sans cesse croissante, des richesses de l&#8217;ensemble de la soci\u00e9t\u00e9 vers les propri\u00e9taires fonciers.<\/p>\n<h2>Les instruments fiscaux \u00e0 envisager<\/h2>\n<p>L\u2019imposition des rentes fonci\u00e8res au Luxembourg est actuellement d\u00e9risoire et ne refl\u00e8te ni le co\u00fbt socio-\u00e9conomique de la r\u00e9tention fonci\u00e8re, ni l\u2019importante contribution du collectif au d\u00e9veloppement de la valeur fonci\u00e8re imposable. La sp\u00e9culation et la r\u00e9tention fonci\u00e8res sont au centre d\u2019un v\u00e9ritable capitalisme improductif et injustifiable sur tous les niveaux qui pr\u00e9l\u00e8ve sa rente sur le reste de la soci\u00e9t\u00e9. Ne pas combattre ce ph\u00e9nom\u00e8ne n\u00e9faste \u00e9quivaut \u00e0 se soumettre au primat du simple rendement financier de quelques rentiers ais\u00e9s sur toute autre finalit\u00e9 \u00e9conomique ou sociale qui pourrait \u00eatre mise au profit de l\u2019int\u00e9gralit\u00e9 de la soci\u00e9t\u00e9 luxembourgeoise.<\/p>\n<p>La plus-value fonci\u00e8re cr\u00e9\u00e9e par la soci\u00e9t\u00e9 gr\u00e2ce au progr\u00e8s socio-\u00e9conomique devrait profiter en premier lieu \u00e0 l&#8217;ensemble de la soci\u00e9t\u00e9 et pas seulement \u00e0 un nombre tr\u00e8s limit\u00e9 de propri\u00e9taires terriens. Or, le r\u00e9gime fiscal actuellement en vigueur est dysfonctionnel et ne fait que r\u00e9compenser les comportements sp\u00e9culatifs.<\/p>\n<p>Compte tenu de l&#8217;ampleur de la structure oligopolistique du march\u00e9 foncier et des richesses qui y sont associ\u00e9es, la mobilisation de la propri\u00e9t\u00e9 fonci\u00e8re retenue du march\u00e9 n\u00e9cessite des r\u00e9formes politiques ambitieuses et incisives.<\/p>\n<p>Les propositions suivantes poursuivent plusieurs objectifs :<\/p>\n<p>1) Une imposition r\u00e9currente qui refl\u00e8te la valeur actualis\u00e9e du foncier ;<\/p>\n<p>2) La mobilisation du foncier constructible pour augmenter la production en logements ;<\/p>\n<p>3) Une taxation \u00e9quitable des rentes fonci\u00e8res, qui r\u00e9sultent principalement des efforts de la soci\u00e9t\u00e9 et non de ceux du propri\u00e9taire ;<\/p>\n<p>4) La protection des locataires face \u00e0 la flamb\u00e9e du prix du foncier qui se r\u00e9percute sur les loyers.<\/p>\n<p>Retenons d\u2019ores et d\u00e9j\u00e0 qu\u2019individuellement, les mesures seront inefficaces et inadapt\u00e9es pour atteindre les objectifs vis\u00e9s et que les propositions devraient \u00eatre \u00e9valu\u00e9es et mises en \u0153uvre en tant que paquet, car elles sont souvent compl\u00e9mentaires et se renforcent mutuellement.<\/p>\n<p><strong>R\u00e9former l\u2019imposition r\u00e9currente du foncier qui est anachronique et d\u00e9risoire<\/strong><\/p>\n<p>L\u2019imp\u00f4t foncier (IFON) actuellement en vigueur est anachronique, d\u00e9pass\u00e9 par l&#8217;\u00e9volution du march\u00e9 foncier et largement symbolique, puisque le foncier est tax\u00e9 \u00e0 un niveau ridiculement bas qui ne refl\u00e8te pas la valeur actuelle des terrains.<\/p>\n<p>Alors qu&#8217;un projet de loi avait \u00e9t\u00e9 d\u00e9pos\u00e9 par le pr\u00e9c\u00e9dent gouvernement[9], qui aurait certes constitu\u00e9 un pas dans la bonne direction, le mod\u00e8le propos\u00e9 \u00e9tait g\u00e9n\u00e9ralement trop timide et se limitait \u00e0 l&#8217;actualisation des valeurs fonci\u00e8res servant de base au calcul de l&#8217;IFON, tandis qu&#8217;une augmentation g\u00e9n\u00e9rale du montant de l&#8217;IFON n&#8217;\u00e9tait pas envisag\u00e9e.<\/p>\n<p>Compte tenu de l\u2019envol\u00e9e des valeurs fonci\u00e8res et afin de capter de mani\u00e8re r\u00e9currente une partie des plus-values afin de disposer des moyens n\u00e9cessaires pour investir, entre autres, dans l\u2019entretien des infrastructures, l\u2019IFON devrait \u00eatre tonifi\u00e9 de mani\u00e8re cons\u00e9quente \u00e0 travers une augmentation g\u00e9n\u00e9rale du niveau d\u2019imposition. En contrepartie, une baisse de l\u2019imposition des revenus du travail devrait \u00eatre envisag\u00e9e.<\/p>\n<p>Notons que le projet de loi a le grand m\u00e9rite d\u2019avoir propos\u00e9 un syst\u00e8me d\u2019\u00e9valuation fonci\u00e8re \u2013 automatis\u00e9 et informatis\u00e9 \u2013 qui permet d\u2019attribuer \u00e0 chaque bien immobilier imposable une valeur de base refl\u00e9tant la valeur fonci\u00e8re correspondante. La mise en \u0153uvre dudit syst\u00e8me est une condition pr\u00e9alable \u00e0 l\u2019introduction d\u2019une imposition cibl\u00e9e des valeurs fonci\u00e8res.[10]<\/p>\n<p>Entre autres, l\u2019IFON r\u00e9form\u00e9 devrait comporter une composante nationale progressive prenant en compte la valeur totale du patrimoine immobilier du contribuable, de mani\u00e8re \u00e0 lutter contre la concentration croissante de la propri\u00e9t\u00e9 immobili\u00e8re, \u00e0 limiter les app\u00e9tits commerciaux ou sp\u00e9culatifs et \u00e0 favoriser, dans une logique d\u2019allocation optimale des ressources, une meilleure circulation du capital, une utilisation optimis\u00e9e des biens immobiliers et une gestion dynamique du patrimoine immobilier, afin de fluidifier le march\u00e9 immobilier en vue d\u2019un r\u00e9\u00e9quilibrage esp\u00e9r\u00e9.<\/p>\n<p><strong>Introduire une taxe \u00e0 la mobilisation du foncier retenu<\/strong><\/p>\n<p>En plus de l&#8217;actualisation et du renforcement de l\u2019imposition r\u00e9currente des valeurs fonci\u00e8res, un imp\u00f4t national \u00e0 la mobilisation des terrains \u00e0 b\u00e2tir devrait \u00eatre introduit afin d\u2019inciter les propri\u00e9taires \u00e0 viabiliser leur foncier. Compte tenu de l&#8217;urgence de la crise du logement, les taux d&#8217;imposition et leur progressivit\u00e9 dans le temps doivent \u00eatre suffisamment ambitieux pour avoir un impact significatif \u00e0 court et moyen terme.<\/p>\n<p>Afin de favoriser la fluidification du march\u00e9 du foncier tout en luttant contre la r\u00e9tention multig\u00e9n\u00e9rationnelle, l&#8217;introduction d&#8217;un imp\u00f4t sur les successions en ligne directe de terrains constructibles devrait \u00eatre \u00e9tudi\u00e9e.<\/p>\n<p><strong>Une politique de la carotte qui ne fait que rassurer les sp\u00e9culateurs<\/strong><\/p>\n<p>Si les mesures susmentionn\u00e9es permettraient certes d\u2019augmenter l\u2019imposition r\u00e9currente du foncier et, dans le meilleur des cas, d\u2019inciter \u00e0 l\u2019am\u00e9nagement des surfaces constructibles, elles ne s\u2019attaquent pas \u00e0 l\u2019injustice qui r\u00e9sulte du fait que les rentiers profitent en cas de cession d\u2019une plus-value exorbitante, produit de l\u2019effort soci\u00e9tal, qui n\u2019est pas suffisamment impos\u00e9e et dont la soci\u00e9t\u00e9 ne r\u00e9cup\u00e8re par cons\u00e9quent qu\u2019une partie infime.<\/p>\n<p>Pour cette raison, l\u2019imposition des plus-values fonci\u00e8res devrait \u00e9galement \u00eatre augment\u00e9e. Cela dit, il est d\u2019autant plus regrettable que les gouvernements successifs aient pris le chemin inverse, en r\u00e9introduisant de facto syst\u00e9matiquement le \u00ab quart taux \u00bb (l\u2019imposition des plus-values immobili\u00e8res \u00e0 un quart du taux global)[11], fortement r\u00e9gressif, g\u00e9n\u00e9ralement inefficace[12] dans la mobilisation de terrains et co\u00fbteux pour les pouvoirs publics. En sus, comme les propri\u00e9taires semblent pouvoir compter sur la r\u00e9introduction r\u00e9guli\u00e8re du \u00ab quart taux \u00bb, l&#8217;instrument perd compl\u00e8tement son caract\u00e8re incitatif et ne fait finalement que rassurer les sp\u00e9culateurs.<\/p>\n<p>Notons d\u2019ailleurs que le traitement fiscal des plus-values de cession est d\u00e9j\u00e0 favorable \u00e0 l\u2019heure actuelle : le prix d\u2019acquisition de l\u2019immeuble est r\u00e9guli\u00e8rement adapt\u00e9 \u00e0 l\u2019\u00e9volution des prix (ce qui diminue la plus-value imposable) et le contribuable b\u00e9n\u00e9ficie d\u2019un abattement de 50.000 euros (100.000 euros dans le chef des \u00e9poux imposables collectivement) et, sous certaines conditions, d\u2019un abattement de 75.000 euros pour les immeubles acquis par voie de succession en ligne directe.<\/p>\n<p>En outre, le \u00ab quart taux \u00bb r\u00e9duit l\u2019effet incitatif d\u2019une autre mesure qui est cens\u00e9e promouvoir la constitution d\u2019une r\u00e9serve fonci\u00e8re en mains publiques telle que vis\u00e9e par le comit\u00e9 d\u2019acquisition du minist\u00e8re des Finances, condition sine qua non d\u2019une acc\u00e9l\u00e9ration de la cr\u00e9ation de logements abordables publics. En effet, la loi du Pacte Logement pr\u00e9voit que les plus-values et les b\u00e9n\u00e9fices de cession sur les ventes de terrains \u00e0 l\u2019Etat et aux communes sont exon\u00e9r\u00e9s de l\u2019imp\u00f4t sur le revenu.<\/p>\n<p>Vu que le taux d\u2019imposition maximal sur la plus-value tir\u00e9e de la vente d\u2019un terrain constructible se situe entre 21% et 42%, cette exon\u00e9ration correspond \u00e0 un gain fiscal consid\u00e9rable pour le vendeur. Logiquement, toute baisse du taux d\u2019imposition diminue le b\u00e9n\u00e9fice fiscal et donc l\u2019effet incitatif de cette exemption. Par cons\u00e9quent, la r\u00e9introduction du \u00ab quart taux \u00bb non seulement rassure les sp\u00e9culateurs tout en accordant des avantages fiscaux inefficaces, mais va \u00e9galement \u00e0 l&#8217;encontre de la politique du logement public.<\/p>\n<p><strong>Pour une augmentation progressive du taux d\u2019imposition des plus-values fonci\u00e8res<\/strong><\/p>\n<p>Pour lutter r\u00e9solument contre la financiarisation du foncier constructible, il faudrait plut\u00f4t annoncer une hausse progressive de l\u2019imposition des plus-values fonci\u00e8res, qui devraient \u00eatre soumises, ind\u00e9pendamment de la dur\u00e9e de d\u00e9tention, au moins au taux global, afin de les mettre sur un pied d\u2019\u00e9galit\u00e9 avec l\u2019imposition des revenus du travail. En effet, il est absurde que le travail productif soit impos\u00e9 \u00e0 un taux 2 ou 4 fois plus \u00e9lev\u00e9 que les plus-values fonci\u00e8res.<\/p>\n<p>Or, une augmentation progressive jusqu&#8217;\u00e0 un taux bien sup\u00e9rieur au taux global est tout \u00e0 fait d\u00e9fendable et justifiable d&#8217;un point de vue socio-\u00e9conomique, \u00e9tant donn\u00e9 que la plus-value r\u00e9sulte uniquement des efforts de la soci\u00e9t\u00e9 et \u00e9tant donn\u00e9 l\u2019impact n\u00e9faste de la financiarisation du foncier sur le d\u00e9veloppement actuel et futur du pays.<\/p>\n<p>Il convient, par ailleurs, de noter qu&#8217;une taxation plus \u00e9lev\u00e9e des plus-values immobili\u00e8res faciliterait fondamentalement la constitution d&#8217;une r\u00e9serve fonci\u00e8re en mains publiques, indispensable pour acc\u00e9l\u00e9rer la production de logements publics abordables. \u00c9tant donn\u00e9 que les plus-values fonci\u00e8res sont exempt\u00e9es de l\u2019imposition en cas de cession \u00e0 la main publique, toute hausse du taux d\u2019imposition renforcerait l\u2019attrait de cette disposition et permettrait aux pouvoirs publics de n\u00e9gocier des prix de vente plus bas, ce qui pr\u00e9serverait les finances publiques et permettrait de financer in fine un plus grand volume de logements.<\/p>\n<p>Dans le cas d&#8217;un changement d&#8217;affectation d&#8217;un terrain en zone constructible, qui entra\u00eene automatiquement une multiplication de la valeur du terrain, la plus-value qui en r\u00e9sulte devrait \u00eatre en grande partie r\u00e9cup\u00e9r\u00e9e et capt\u00e9e par la soci\u00e9t\u00e9, soit par une imposition \u00e9lev\u00e9e des plus-values latentes ayant le m\u00e9rite de dynamiser la circulation du capital, soit par une imposition accrue de la plus-value en cas de cession. Cette approche permettrait \u00e9galement d&#8217;endiguer la sp\u00e9culation sur les terrains situ\u00e9s \u00e0 proximit\u00e9 des zones constructibles.<\/p>\n<p><strong>R\u00e9former le plafonnement des loyers et limiter l\u2019incidence fonci\u00e8re dans le calcul des loyers<\/strong><\/p>\n<p>Compte tenu du march\u00e9 locatif sous forte pression, il est particuli\u00e8rement urgent d&#8217;instaurer un encadrement plus ambitieux des loyers. Le contr\u00f4le l\u00e9gal du niveau des loyers est toutefois un instrument controvers\u00e9, souvent d\u00e9crit comme inefficace et potentiellement contre-productif \u00e0 moyen et long terme. Ses d\u00e9tracteurs soulignent ainsi qu\u2019une politique plus interventionniste risque d\u2019affecter l&#8217;\u00e9quilibre du march\u00e9 en affaiblissant le rendement locatif (ratio loyer\/prix) et, par cons\u00e9quent, le niveau des investissements priv\u00e9s, ce qui provoquerait une rar\u00e9faction et une d\u00e9t\u00e9rioration de la qualit\u00e9 de l\u2019offre locative.<\/p>\n<p>Contr\u00f4ler et r\u00e9glementer les loyers tout en maintenant, en m\u00eame temps, un niveau \u00e9lev\u00e9 d&#8217;investissement priv\u00e9 dans l&#8217;immobilier r\u00e9sidentiel est donc souvent consid\u00e9r\u00e9 comme la quadrature du cercle. Pourtant, des r\u00e9formes favorisant une r\u00e9duction de l\u2019incidence fonci\u00e8re \u2013 la part du prix d\u2019acquisition du terrain dans le prix d\u2019un logement \u2013 permettraient de mod\u00e9rer l&#8217;\u00e9volution des loyers tout en pr\u00e9servant la rentabilit\u00e9 des investissements dans le logement locatif. Si les mesures susmentionn\u00e9es devaient d\u00e9j\u00e0 avoir un certain effet mod\u00e9rateur sur l&#8217;\u00e9volution des prix des terrains constructibles, il conviendrait en m\u00eame temps de dissuader les investisseurs-bailleurs de payer des prix d\u00e9mesur\u00e9s pour le foncier et de prot\u00e9ger les locataires contre le poids excessif du foncier qui se traduit par des loyers trop \u00e9lev\u00e9s.<\/p>\n<p>La loi sur le bail \u00e0 usage d\u2019habitation fixe le rendement locatif annuel maximal en fonction du capital investi dans le bien mis en location. Cependant, la l\u00e9gislation ne fait pas de distinction entre le capital investi respectivement dans le terrain ou dans le b\u00e2timent. Par cons\u00e9quent, la rar\u00e9faction artificielle du foncier se r\u00e9percute directement sur l\u2019\u00e9volution des loyers.<\/p>\n<p>Or, dans le cadre d\u2019une r\u00e9forme du bail \u00e0 loyer, il serait important d\u2019adopter une perspective qui d\u00e9passe la seule relation bailleur-locataire. Sinon, on risque de se concentrer sur l&#8217;arri\u00e8re-sc\u00e8ne et de n\u00e9gliger l&#8217;existence d&#8217;un troisi\u00e8me maillon dans cette relation, qui est dans de nombreux cas le premier responsable du niveau des loyers : le rentier foncier.<\/p>\n<p>En effet, une grande partie du loyer ne finit pas n\u00e9cessairement dans la poche du bailleur, mais passe indirectement, par le biais du prix pay\u00e9 pour le terrain, du bailleur au propri\u00e9taire initial du terrain, qui empoche en fin de compte une grande partie du rendement locatif.<\/p>\n<p>Il est en fait assez \u00e9tonnant que dans les discussions concernant la r\u00e9forme du bail \u00e0 usage d\u2019habitation, les investisseurs aient jusqu\u2019\u00e0 pr\u00e9sent r\u00e9ussi \u00e0 attirer l\u2019attention sur l\u2019argument selon lequel un plafonnement plus ferme serait \u00e0 \u00e9viter afin de garantir un rendement locatif suffisant par rapport aux co\u00fbts d&#8217;investissement, alors que le probl\u00e8me fondamental r\u00e9side dans l&#8217;augmentation constante de l&#8217;incidence fonci\u00e8re. En effet, en r\u00e9duisant la rente fonci\u00e8re, on pourrait limiter l&#8217;\u00e9volution des loyers tout en garantissant au bailleur un rendement locatif en ad\u00e9quation avec son investissement dans l\u2019immeuble respectivement les co\u00fbts d\u2019entretien du b\u00e2timent.<\/p>\n<p>Pour contrer cette redistribution continue de la richesse du bas vers le haut, une r\u00e9forme du bail \u00e0 loyer devrait viser \u00e0 limiter l&#8217;impact de la rente fonci\u00e8re sur l&#8217;\u00e9volution des loyers en passant progressivement \u00e0 un mod\u00e8le appliquant un taux de rendement maximal plus faible \u00e0 la part du capital investi dans le foncier, ce qui, combin\u00e9 aux autres mesures propos\u00e9es, exercerait progressivement une pression \u00e0 la baisse sur le prix du foncier.\u00a0 Ce mod\u00e8le devrait \u00e9galement \u00eatre \u00e9tendu aux baux commerciaux.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cet article vise \u00e0 alimenter et stimuler le d\u00e9bat politique et soci\u00e9tal sur l\u2019imposition \u00e9quitable des plus-values et des rentes fonci\u00e8res. Compte tenu de l&#8217;ampleur de la structure oligopolistique du march\u00e9 foncier et des richesses qui y sont associ\u00e9es, la mobilisation de la propri\u00e9t\u00e9 fonci\u00e8re retenue du march\u00e9 n\u00e9cessite des r\u00e9formes politiques ambitieuses et incisives.<\/p>\n","protected":false},"author":11,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-2114","post","type-post","status-publish","format-standard","hentry","category-uncategorized","topic-inequalities","topic-taxation","format-text"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>La financiarisation du foncier constructible, vecteur principal de la crise du logement - Improof<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dev.improof.lu\/en\/articles\/financiarisation-du-foncier-constructible\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La financiarisation du foncier constructible, vecteur principal de la crise du logement\" \/>\n<meta property=\"og:description\" content=\"Cet article vise \u00e0 alimenter et stimuler le d\u00e9bat politique et soci\u00e9tal sur l\u2019imposition \u00e9quitable des plus-values et des rentes fonci\u00e8res. Compte tenu de l&#039;ampleur de la structure oligopolistique du march\u00e9 foncier et des richesses qui y sont associ\u00e9es, la mobilisation de la propri\u00e9t\u00e9 fonci\u00e8re retenue du march\u00e9 n\u00e9cessite des r\u00e9formes politiques ambitieuses et incisives.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dev.improof.lu\/en\/articles\/financiarisation-du-foncier-constructible\/\" \/>\n<meta property=\"og:site_name\" content=\"Improof\" \/>\n<meta property=\"article:published_time\" content=\"2024-10-03T10:02:39+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-10-03T10:02:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dev.improof.lu\/app\/uploads\/2024\/10\/jpglogement.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1076\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Nermin Plavsic\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"La financiarisation du foncier constructible, vecteur principal de la crise du logement\" \/>\n<meta name=\"twitter:description\" content=\"Cet article vise \u00e0 alimenter et stimuler le d\u00e9bat politique et soci\u00e9tal sur l\u2019imposition \u00e9quitable des plus-values et des rentes fonci\u00e8res. Compte tenu de l&#039;ampleur de la structure oligopolistique du march\u00e9 foncier et des richesses qui y sont associ\u00e9es, la mobilisation de la propri\u00e9t\u00e9 fonci\u00e8re retenue du march\u00e9 n\u00e9cessite des r\u00e9formes politiques ambitieuses et incisives.\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/dev.improof.lu\/app\/uploads\/2024\/10\/jpglogement.jpg\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Nermin Plavsic\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"23 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/dev.improof.lu\/en\/articles\/financiarisation-du-foncier-constructible\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dev.improof.lu\/en\/articles\/financiarisation-du-foncier-constructible\/\"},\"author\":{\"name\":\"Nermin Plavsic\",\"@id\":\"https:\/\/dev.improof.lu\/en\/#\/schema\/person\/8b7e0720f9ab34bd8b12af9dbf2592a6\"},\"headline\":\"La financiarisation du foncier constructible, vecteur principal de la crise du logement\",\"datePublished\":\"2024-10-03T10:02:39+00:00\",\"dateModified\":\"2024-10-03T10:02:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dev.improof.lu\/en\/articles\/financiarisation-du-foncier-constructible\/\"},\"wordCount\":4739,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dev.improof.lu\/en\/#organization\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dev.improof.lu\/en\/articles\/financiarisation-du-foncier-constructible\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dev.improof.lu\/en\/articles\/financiarisation-du-foncier-constructible\/\",\"url\":\"https:\/\/dev.improof.lu\/en\/articles\/financiarisation-du-foncier-constructible\/\",\"name\":\"La financiarisation du foncier constructible, vecteur principal de la crise du logement - Improof\",\"isPartOf\":{\"@id\":\"https:\/\/dev.improof.lu\/en\/#website\"},\"datePublished\":\"2024-10-03T10:02:39+00:00\",\"dateModified\":\"2024-10-03T10:02:40+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/dev.improof.lu\/en\/articles\/financiarisation-du-foncier-constructible\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dev.improof.lu\/en\/articles\/financiarisation-du-foncier-constructible\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dev.improof.lu\/en\/articles\/financiarisation-du-foncier-constructible\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/dev.improof.lu\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La financiarisation du foncier constructible, vecteur principal de la crise du logement\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dev.improof.lu\/en\/#website\",\"url\":\"https:\/\/dev.improof.lu\/en\/\",\"name\":\"Improof\",\"description\":\"Tagline goes here\",\"publisher\":{\"@id\":\"https:\/\/dev.improof.lu\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dev.improof.lu\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/dev.improof.lu\/en\/#organization\",\"name\":\"Improof\",\"url\":\"https:\/\/dev.improof.lu\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/dev.improof.lu\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dev.improof.lu\/app\/uploads\/2022\/10\/improof-logo-svg.png\",\"contentUrl\":\"https:\/\/dev.improof.lu\/app\/uploads\/2022\/10\/improof-logo-svg.png\",\"width\":652,\"height\":209,\"caption\":\"Improof\"},\"image\":{\"@id\":\"https:\/\/dev.improof.lu\/en\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dev.improof.lu\/en\/#\/schema\/person\/8b7e0720f9ab34bd8b12af9dbf2592a6\",\"name\":\"Nermin Plavsic\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/dev.improof.lu\/en\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/1b010c13286dbffe130fb77dd68cc999?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/1b010c13286dbffe130fb77dd68cc999?s=96&d=mm&r=g\",\"caption\":\"Nermin Plavsic\"},\"url\":\"https:\/\/dev.improof.lu\/en\/articles\/author\/nermin-plavsic\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La financiarisation du foncier constructible, vecteur principal de la crise du logement - Improof","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dev.improof.lu\/en\/articles\/financiarisation-du-foncier-constructible\/","og_locale":"en_US","og_type":"article","og_title":"La financiarisation du foncier constructible, vecteur principal de la crise du logement","og_description":"Cet article vise \u00e0 alimenter et stimuler le d\u00e9bat politique et soci\u00e9tal sur l\u2019imposition \u00e9quitable des plus-values et des rentes fonci\u00e8res. Compte tenu de l'ampleur de la structure oligopolistique du march\u00e9 foncier et des richesses qui y sont associ\u00e9es, la mobilisation de la propri\u00e9t\u00e9 fonci\u00e8re retenue du march\u00e9 n\u00e9cessite des r\u00e9formes politiques ambitieuses et incisives.","og_url":"https:\/\/dev.improof.lu\/en\/articles\/financiarisation-du-foncier-constructible\/","og_site_name":"Improof","article_published_time":"2024-10-03T10:02:39+00:00","article_modified_time":"2024-10-03T10:02:40+00:00","og_image":[{"width":1920,"height":1076,"url":"https:\/\/dev.improof.lu\/app\/uploads\/2024\/10\/jpglogement.jpg","type":"image\/jpeg"}],"author":"Nermin Plavsic","twitter_card":"summary_large_image","twitter_title":"La financiarisation du foncier constructible, vecteur principal de la crise du logement","twitter_description":"Cet article vise \u00e0 alimenter et stimuler le d\u00e9bat politique et soci\u00e9tal sur l\u2019imposition \u00e9quitable des plus-values et des rentes fonci\u00e8res. Compte tenu de l'ampleur de la structure oligopolistique du march\u00e9 foncier et des richesses qui y sont associ\u00e9es, la mobilisation de la propri\u00e9t\u00e9 fonci\u00e8re retenue du march\u00e9 n\u00e9cessite des r\u00e9formes politiques ambitieuses et incisives.","twitter_image":"https:\/\/dev.improof.lu\/app\/uploads\/2024\/10\/jpglogement.jpg","twitter_misc":{"Written by":"Nermin Plavsic","Est. reading time":"23 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/dev.improof.lu\/en\/articles\/financiarisation-du-foncier-constructible\/#article","isPartOf":{"@id":"https:\/\/dev.improof.lu\/en\/articles\/financiarisation-du-foncier-constructible\/"},"author":{"name":"Nermin Plavsic","@id":"https:\/\/dev.improof.lu\/en\/#\/schema\/person\/8b7e0720f9ab34bd8b12af9dbf2592a6"},"headline":"La financiarisation du foncier constructible, vecteur principal de la crise du logement","datePublished":"2024-10-03T10:02:39+00:00","dateModified":"2024-10-03T10:02:40+00:00","mainEntityOfPage":{"@id":"https:\/\/dev.improof.lu\/en\/articles\/financiarisation-du-foncier-constructible\/"},"wordCount":4739,"commentCount":0,"publisher":{"@id":"https:\/\/dev.improof.lu\/en\/#organization"},"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dev.improof.lu\/en\/articles\/financiarisation-du-foncier-constructible\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/dev.improof.lu\/en\/articles\/financiarisation-du-foncier-constructible\/","url":"https:\/\/dev.improof.lu\/en\/articles\/financiarisation-du-foncier-constructible\/","name":"La financiarisation du foncier constructible, vecteur principal de la crise du logement - Improof","isPartOf":{"@id":"https:\/\/dev.improof.lu\/en\/#website"},"datePublished":"2024-10-03T10:02:39+00:00","dateModified":"2024-10-03T10:02:40+00:00","breadcrumb":{"@id":"https:\/\/dev.improof.lu\/en\/articles\/financiarisation-du-foncier-constructible\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dev.improof.lu\/en\/articles\/financiarisation-du-foncier-constructible\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/dev.improof.lu\/en\/articles\/financiarisation-du-foncier-constructible\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/dev.improof.lu\/en\/"},{"@type":"ListItem","position":2,"name":"La financiarisation du foncier constructible, vecteur principal de la crise du logement"}]},{"@type":"WebSite","@id":"https:\/\/dev.improof.lu\/en\/#website","url":"https:\/\/dev.improof.lu\/en\/","name":"Improof","description":"Tagline goes here","publisher":{"@id":"https:\/\/dev.improof.lu\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dev.improof.lu\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/dev.improof.lu\/en\/#organization","name":"Improof","url":"https:\/\/dev.improof.lu\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/dev.improof.lu\/en\/#\/schema\/logo\/image\/","url":"https:\/\/dev.improof.lu\/app\/uploads\/2022\/10\/improof-logo-svg.png","contentUrl":"https:\/\/dev.improof.lu\/app\/uploads\/2022\/10\/improof-logo-svg.png","width":652,"height":209,"caption":"Improof"},"image":{"@id":"https:\/\/dev.improof.lu\/en\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/dev.improof.lu\/en\/#\/schema\/person\/8b7e0720f9ab34bd8b12af9dbf2592a6","name":"Nermin Plavsic","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/dev.improof.lu\/en\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/1b010c13286dbffe130fb77dd68cc999?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1b010c13286dbffe130fb77dd68cc999?s=96&d=mm&r=g","caption":"Nermin Plavsic"},"url":"https:\/\/dev.improof.lu\/en\/articles\/author\/nermin-plavsic\/"}]}},"_links":{"self":[{"href":"https:\/\/dev.improof.lu\/en\/wp-json\/wp\/v2\/posts\/2114","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.improof.lu\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dev.improof.lu\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dev.improof.lu\/en\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/dev.improof.lu\/en\/wp-json\/wp\/v2\/comments?post=2114"}],"version-history":[{"count":1,"href":"https:\/\/dev.improof.lu\/en\/wp-json\/wp\/v2\/posts\/2114\/revisions"}],"predecessor-version":[{"id":2116,"href":"https:\/\/dev.improof.lu\/en\/wp-json\/wp\/v2\/posts\/2114\/revisions\/2116"}],"wp:attachment":[{"href":"https:\/\/dev.improof.lu\/en\/wp-json\/wp\/v2\/media?parent=2114"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dev.improof.lu\/en\/wp-json\/wp\/v2\/categories?post=2114"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dev.improof.lu\/en\/wp-json\/wp\/v2\/tags?post=2114"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}