{"id":621,"date":"2023-01-11T09:15:09","date_gmt":"2023-01-11T09:15:09","guid":{"rendered":"https:\/\/dev.improof.lu\/homoploutie\/"},"modified":"2024-01-31T15:31:04","modified_gmt":"2024-01-31T15:31:04","slug":"homoploutie","status":"publish","type":"post","link":"https:\/\/dev.improof.lu\/en\/articles\/homoploutie\/","title":{"rendered":"Homoploutie"},"content":{"rendered":"<p>Le syst\u00e8me capitaliste traditionnel a chang\u00e9, selon le constat de l\u2019\u00e9conomiste <a href=\"https:\/\/dev.improof.lu\/fr\/articles\/video-conversation-with-branko-milanovic-on-the-current-state-and-the-future-of-capitalism\/\" target=\"_blank\" rel=\"noopener\">Branko Milanovic dans son r\u00e9cent livre <em>Capitalism, Alone <\/em>(2019)<\/a>, mais aussi dans un article de 2020[2]. L\u2019\u00e9conomiste met en garde contre un nouveau type d\u2019in\u00e9galit\u00e9 qu\u2019il nomme <em>\u00ab\u00a0homoploutia\u00a0\u00bb<\/em> et qui se caract\u00e9rise par une double concentration de richesses. Plus pr\u00e9cis\u00e9ment, Milanovic et Berman ont fait l\u2019analyse que les personnes qui per\u00e7oivent les plus hauts revenus du capital sont de plus en plus souvent les m\u00eames qui touchent les revenus du travail les plus \u00e9lev\u00e9s. Cette \u00e9volution, contraire \u00e0 la pens\u00e9e classique du capitalisme selon laquelle les capitalistes qui vivent de leur (revenu du) capital sont une population distincte des travailleurs qui vivent de leur (revenu du) travail, met en avant un changement structurel du capitalisme traditionnel.<\/p>\n<p>Ainsi, d\u2019apr\u00e8s ces r\u00e9sultats reposant sur des donn\u00e9es nord-am\u00e9ricaines couvrant jusqu\u2019\u00e0 60 ann\u00e9es, les deux chercheurs montrent que les riches rentiers sont de plus en plus souvent aussi des salari\u00e9s disposant de revenus du travail tr\u00e8s importants. En 2020, 28% des m\u00e9nages appartenant aux 10% des plus riches en revenu du capital \u00e9taient ainsi aussi parmi les 10% des plus riches en revenu du travail aux \u00c9tats-Unis. Or d\u2019autres pays occidentaux ont des taux qui s\u2019approchent fortement de ceux-l\u00e0, confirmant une tendance g\u00e9n\u00e9rale vers l\u2019homoploutie.<\/p>\n<p><iframe class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" title=\"L&#039;homoploutie: une comparaison internationale (2015-2020)\" src=\"https:\/\/datawrapper.dwcdn.net\/OeVwf\/3\/#?secret=7uQE1uiCuu\" data-secret=\"7uQE1uiCuu\" scrolling=\"no\" frameborder=\"0\" height=\"400\"><\/iframe><\/p>\n<p>Partant, la question se pose si ce constat, confirm\u00e9 pour les \u00c9tats-Unis, mais aussi pour l\u2019Europe, est un ph\u00e9nom\u00e8ne qui est \u00e9galement valide et perceptible au Luxembourg.<\/p>\n<h2>L\u2019Homoploutie au Luxembourg<\/h2>\n<p>Une telle analyse des faits est possible en regardant combien de m\u00e9nages riches en revenu du capital sont aussi riches en revenu du travail, si bien qu\u2019ils se situent en m\u00eame temps dans le cinqui\u00e8me quintile (Q5)<a href=\"#_ftn3\" name=\"_ftnref3\">[3]<\/a> des deux sources de revenus. Dans le graphique ci-dessous, on peut observer depuis 1985 l\u2019\u00e9volution de cette part de la population doublement riche au Luxembourg\u00a0: le mouvement de cette double concentration des revenus (capitaux et travail) laisse peu de doute quant \u00e0 la r\u00e9ponse relative \u00e0 l\u2019\u00e9ventualit\u00e9 de voir ce ph\u00e9nom\u00e8ne observ\u00e9 par Milanovic aux \u00c9tats-Unis se produire au Luxembourg.<\/p>\n<p>https:\/\/datawrapper.dwcdn.net\/SqLlG\/4\/<\/p>\n<p>En effet, entre 1985 et 1995, environ 20% des m\u00e9nages appartenant au cinqui\u00e8me quintile des m\u00e9nages les plus riches en revenus du capital se trouvaient aussi dans le quintile des m\u00e9nages avec les revenus du travail les plus \u00e9lev\u00e9s. Ce taux a graduellement augment\u00e9 jusqu\u2019en 2007 pour atteindre son maximum de 32%\u00a0; ceci signifie qu\u2019en 2007 pr\u00e8s d\u2019un tiers des m\u00e9nages disposant des revenus du capital les plus \u00e9lev\u00e9s \u00e9taient aussi ceux avec les revenus du travail les plus hauts. Entre 2007 et 2010, ce taux a baiss\u00e9 de trois points, mais, depuis lors, il est de nouveau en l\u00e9g\u00e8re hausse, de mani\u00e8re \u00e0 se retrouver en 2019 de nouveau \u00e0 31%.<\/p>\n<p>Pour des raisons m\u00e9thodologiques d\u2019\u00e9chantillons trop petits, l\u2019analyse ci-dessus a \u00e9t\u00e9 faite au niveau de quintiles et pas au niveau de d\u00e9ciles[4]. Toutefois, le m\u00eame constat est aussi confirm\u00e9 par l\u2019analyse des d\u00e9ciles, m\u00eame si l\u2019\u00e9volution a \u00e9t\u00e9 moins dynamique. En effet, en 2019 19,4%[5] des m\u00e9nages dans le dixi\u00e8me d\u00e9cile des revenus du capital l\u2019\u00e9taient aussi dans le revenu du travail, alors que ce taux ne s\u2019\u00e9levait \u00e0 seulement 14,6% en 1991.<\/p>\n<p>La pr\u00e9pond\u00e9rance de l\u2019<em>\u00ab\u00a0homoploutie\u00a0\u00bb<\/em> (que nous francisons ici), c\u2019est-\u00e0-dire de la double concentration des revenus des capitaux et des revenus du travail les plus confortables, est donc effectivement non seulement le probl\u00e8me des \u00c9tats-Unis, mais affecte aussi le Luxembourg ainsi que probablement d\u2019autres pays d\u00e9velopp\u00e9s. Avec l\u2019\u00e9mergence de nouvelles formes de r\u00e9mun\u00e9ration, le syst\u00e8me classique du capitalisme, selon lequel il existe une claire distinction entre celui qui travaille (le travailleur) et celui qui investit (le capitaliste), perd donc une de ses caract\u00e9ristiques intrins\u00e8ques.<\/p>\n<h2>Sources et probl\u00e8mes li\u00e9s \u00e0 ce concept de l\u2019<em>\u00ab\u00a0homoploutie\u00a0\u00bb<\/em><\/h2>\n<p>Deux changements \u00e9conomiques majeurs renforcent, voire causent le ph\u00e9nom\u00e8ne ici d\u00e9crit et sont m\u00eame en progression.<\/p>\n<p>D\u2019un c\u00f4t\u00e9, la hausse extr\u00eame des r\u00e9mun\u00e9rations des cadres dirigeants dans les grandes entreprises depuis les ann\u00e9es 1980, en partie due \u00e0 la forte baisse des taux d\u2019imposition marginaux dans les pays occidentaux<sup>[6]<\/sup>, rend l\u2019\u00e9ventualit\u00e9 du travail de plus en plus attractive pour les rentiers. En effet, certains rentiers, disposant de revenus du capital suffisamment \u00e9lev\u00e9s pour ne pas devoir travailler, peuvent d\u00e9cider\u00a0 tout de m\u00eame d\u2019entrer sur le march\u00e9 du travail (le manque \u00e0 gagner de ne pas travailler ayant augment\u00e9), stimul\u00e9s par la perspective d\u2019atteindre de tels niveaux de salaires extr\u00eames qui sont distribu\u00e9s seulement \u00e0 une faible part de salari\u00e9s, notamment les cadres dirigeants. Ainsi, les personnes riches en revenus du capital accumulent aussi des revenus du travail.<\/p>\n<p>De l\u2019autre c\u00f4t\u00e9, cette hausse extr\u00eame des r\u00e9mun\u00e9rations des cadres dirigeants ouvre la possibilit\u00e9 aux travailleurs d\u2019investir dans du capital qui va ensuite g\u00e9n\u00e9rer des revenus potentiellement \u00e9lev\u00e9s. Il s\u2019ajoute que de nouvelles formes de r\u00e9mun\u00e9ration telles que les stock-options, souvent r\u00e9serv\u00e9es aux salari\u00e9s les mieux r\u00e9mun\u00e9r\u00e9s, cr\u00e9ent une relation entre salaires et revenus du capital. De cette mani\u00e8re, les personnes riches en revenus du travail commencent \u00e0 accumuler des revenus du capital.<\/p>\n<p>Ces deux effets sont sans doute, au moins en partie, responsables de l\u2019\u00e9mergence de cette nouvelle \u00e9lite \u00e9conomique que repr\u00e9sente l\u2019<em>\u00ab\u00a0homoploutie\u00a0\u00bb<\/em>. Toutefois, ces changements \u00e9conomiques et cette double concentration qui en r\u00e9sulte n\u2019auraient probablement pas \u00e9t\u00e9 possibles sans les changements structurels et politiques depuis les ann\u00e9es 1980, notamment la baisse graduelle des taux d\u2019imposition marginaux, la baisse des imp\u00f4ts sur les revenus des capitaux et l\u2019abolition quasi-compl\u00e8te des imp\u00f4ts sur le patrimoine.<\/p>\n<p>Or, l\u2019\u00e9tablissement m\u00eame d\u2019une telle \u00e9lite \u00e9conomique qui compte \u00e0 la fois parmi les plus riches en revenus du travail et en revenus du capital amplifie davantage les in\u00e9galit\u00e9s \u00e9conomiques\u00a0; \u00e0 lui seul, selon Milanovic, ce ph\u00e9nom\u00e8ne est responsable pour un cinqui\u00e8me de la croissance des in\u00e9galit\u00e9s aux \u00c9tats-Unis. Du fait de l\u2019accouplement assortatif[7], tout comme les in\u00e9galit\u00e9s d\u2019acc\u00e8s \u00e0 l\u2019\u00e9ducation qui favorisent cette nouvelle \u00e9lite \u00e9conomique, les in\u00e9galit\u00e9s s\u2019auto-entretiennent et constituent un cercle vicieux. Il parait d\u00e8s lors indispensable de s\u2019attaquer \u00e0 cette nouvelle forme d\u2019in\u00e9galit\u00e9 \u00e0 l\u2019aide d\u2019une <a href=\"https:\/\/dev.improof.lu\/de\/articles\/pour-une-imposition-plus-juste-du-capital-en-vue-de-reduire-les-inegalites\/\" target=\"_blank\" rel=\"noopener\">r\u00e9forme fiscale juste et \u00e9quitable<\/a>, afin d\u2019\u00e9viter que les in\u00e9galit\u00e9s de revenu, mais aussi les in\u00e9galit\u00e9s en g\u00e9n\u00e9ral ne se creusent davantage et ne menacent pour de bon la coh\u00e9sion sociale. Car, selon Milanovic, la gen\u00e8se de cette nouvelle \u00e9lite risque, entre autres, de compromettre le processus d\u00e9mocratique, avec une influence grandissante de cette nouvelle \u00ab classe \u00bb sur la politique et l\u2019\u00e9conomie.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00ab It is [\u2026] the movement toward the creation of a self-perpetuating<br \/>\nupper class and polarization between the elites<br \/>\nand the rest, that represents the most important threat<br \/>\nto the longer-term viability of liberal capitalism. \u00bb [1]<\/p>\n","protected":false},"author":8,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-621","post","type-post","status-publish","format-standard","hentry","category-uncategorized","topic-inequalities","format-text"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Homoploutie - Improof<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dev.improof.lu\/en\/articles\/homoploutie\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Homoploutie - Improof\" \/>\n<meta property=\"og:description\" content=\"\u00ab It is [\u2026] the movement toward the creation of a self-perpetuating upper class and polarization between the elites and the rest, that represents the most important threat to the longer-term viability of liberal capitalism. \u00bb [1]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dev.improof.lu\/fr\/articles\/homoploutie\/\" \/>\n<meta property=\"og:site_name\" content=\"Improof\" \/>\n<meta property=\"article:published_time\" content=\"2023-01-11T09:15:09+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-01-31T15:31:04+00:00\" \/>\n<meta name=\"author\" content=\"Dylan Theis\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Dylan Theis\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/dev.improof.lu\/fr\/articles\/homoploutie\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dev.improof.lu\/en\/articles\/homoploutie\/\"},\"author\":{\"name\":\"Dylan Theis\",\"@id\":\"https:\/\/dev.improof.lu\/en\/#\/schema\/person\/7aaf2286464ae00d2447ba7811787c41\"},\"headline\":\"Homoploutie\",\"datePublished\":\"2023-01-11T09:15:09+00:00\",\"dateModified\":\"2024-01-31T15:31:04+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dev.improof.lu\/en\/articles\/homoploutie\/\"},\"wordCount\":1197,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dev.improof.lu\/en\/#organization\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dev.improof.lu\/fr\/articles\/homoploutie\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dev.improof.lu\/en\/articles\/homoploutie\/\",\"url\":\"https:\/\/dev.improof.lu\/fr\/articles\/homoploutie\/\",\"name\":\"Homoploutie - Improof\",\"isPartOf\":{\"@id\":\"https:\/\/dev.improof.lu\/en\/#website\"},\"datePublished\":\"2023-01-11T09:15:09+00:00\",\"dateModified\":\"2024-01-31T15:31:04+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/dev.improof.lu\/fr\/articles\/homoploutie\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dev.improof.lu\/fr\/articles\/homoploutie\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dev.improof.lu\/fr\/articles\/homoploutie\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/dev.improof.lu\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Homoploutie\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dev.improof.lu\/en\/#website\",\"url\":\"https:\/\/dev.improof.lu\/en\/\",\"name\":\"Improof\",\"description\":\"Tagline goes here\",\"publisher\":{\"@id\":\"https:\/\/dev.improof.lu\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dev.improof.lu\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/dev.improof.lu\/en\/#organization\",\"name\":\"Improof\",\"url\":\"https:\/\/dev.improof.lu\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/dev.improof.lu\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dev.improof.lu\/app\/uploads\/2022\/10\/improof-logo-svg.png\",\"contentUrl\":\"https:\/\/dev.improof.lu\/app\/uploads\/2022\/10\/improof-logo-svg.png\",\"width\":652,\"height\":209,\"caption\":\"Improof\"},\"image\":{\"@id\":\"https:\/\/dev.improof.lu\/en\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dev.improof.lu\/en\/#\/schema\/person\/7aaf2286464ae00d2447ba7811787c41\",\"name\":\"Dylan Theis\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/dev.improof.lu\/en\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/1991007fbb4e5a769ee7f0a6a6cc3d0c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/1991007fbb4e5a769ee7f0a6a6cc3d0c?s=96&d=mm&r=g\",\"caption\":\"Dylan Theis\"},\"url\":\"https:\/\/dev.improof.lu\/en\/articles\/author\/dylan-theis\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Homoploutie - Improof","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dev.improof.lu\/en\/articles\/homoploutie\/","og_locale":"en_US","og_type":"article","og_title":"Homoploutie - Improof","og_description":"\u00ab It is [\u2026] the movement toward the creation of a self-perpetuating upper class and polarization between the elites and the rest, that represents the most important threat to the longer-term viability of liberal capitalism. \u00bb [1]","og_url":"https:\/\/dev.improof.lu\/fr\/articles\/homoploutie\/","og_site_name":"Improof","article_published_time":"2023-01-11T09:15:09+00:00","article_modified_time":"2024-01-31T15:31:04+00:00","author":"Dylan Theis","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Dylan Theis","Est. reading time":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/dev.improof.lu\/fr\/articles\/homoploutie\/#article","isPartOf":{"@id":"https:\/\/dev.improof.lu\/en\/articles\/homoploutie\/"},"author":{"name":"Dylan Theis","@id":"https:\/\/dev.improof.lu\/en\/#\/schema\/person\/7aaf2286464ae00d2447ba7811787c41"},"headline":"Homoploutie","datePublished":"2023-01-11T09:15:09+00:00","dateModified":"2024-01-31T15:31:04+00:00","mainEntityOfPage":{"@id":"https:\/\/dev.improof.lu\/en\/articles\/homoploutie\/"},"wordCount":1197,"commentCount":0,"publisher":{"@id":"https:\/\/dev.improof.lu\/en\/#organization"},"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dev.improof.lu\/fr\/articles\/homoploutie\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/dev.improof.lu\/en\/articles\/homoploutie\/","url":"https:\/\/dev.improof.lu\/fr\/articles\/homoploutie\/","name":"Homoploutie - Improof","isPartOf":{"@id":"https:\/\/dev.improof.lu\/en\/#website"},"datePublished":"2023-01-11T09:15:09+00:00","dateModified":"2024-01-31T15:31:04+00:00","breadcrumb":{"@id":"https:\/\/dev.improof.lu\/fr\/articles\/homoploutie\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dev.improof.lu\/fr\/articles\/homoploutie\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/dev.improof.lu\/fr\/articles\/homoploutie\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/dev.improof.lu\/en\/"},{"@type":"ListItem","position":2,"name":"Homoploutie"}]},{"@type":"WebSite","@id":"https:\/\/dev.improof.lu\/en\/#website","url":"https:\/\/dev.improof.lu\/en\/","name":"Improof","description":"Tagline goes here","publisher":{"@id":"https:\/\/dev.improof.lu\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dev.improof.lu\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/dev.improof.lu\/en\/#organization","name":"Improof","url":"https:\/\/dev.improof.lu\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/dev.improof.lu\/en\/#\/schema\/logo\/image\/","url":"https:\/\/dev.improof.lu\/app\/uploads\/2022\/10\/improof-logo-svg.png","contentUrl":"https:\/\/dev.improof.lu\/app\/uploads\/2022\/10\/improof-logo-svg.png","width":652,"height":209,"caption":"Improof"},"image":{"@id":"https:\/\/dev.improof.lu\/en\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/dev.improof.lu\/en\/#\/schema\/person\/7aaf2286464ae00d2447ba7811787c41","name":"Dylan Theis","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/dev.improof.lu\/en\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/1991007fbb4e5a769ee7f0a6a6cc3d0c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1991007fbb4e5a769ee7f0a6a6cc3d0c?s=96&d=mm&r=g","caption":"Dylan Theis"},"url":"https:\/\/dev.improof.lu\/en\/articles\/author\/dylan-theis\/"}]}},"_links":{"self":[{"href":"https:\/\/dev.improof.lu\/en\/wp-json\/wp\/v2\/posts\/621","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.improof.lu\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dev.improof.lu\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dev.improof.lu\/en\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/dev.improof.lu\/en\/wp-json\/wp\/v2\/comments?post=621"}],"version-history":[{"count":6,"href":"https:\/\/dev.improof.lu\/en\/wp-json\/wp\/v2\/posts\/621\/revisions"}],"predecessor-version":[{"id":1800,"href":"https:\/\/dev.improof.lu\/en\/wp-json\/wp\/v2\/posts\/621\/revisions\/1800"}],"wp:attachment":[{"href":"https:\/\/dev.improof.lu\/en\/wp-json\/wp\/v2\/media?parent=621"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dev.improof.lu\/en\/wp-json\/wp\/v2\/categories?post=621"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dev.improof.lu\/en\/wp-json\/wp\/v2\/tags?post=621"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}