{"id":1113,"date":"2023-04-26T07:40:26","date_gmt":"2023-04-26T07:40:26","guid":{"rendered":"https:\/\/dev.improof.lu\/?p=1113"},"modified":"2024-01-31T15:21:06","modified_gmt":"2024-01-31T15:21:06","slug":"egalite-equite-education-formation","status":"publish","type":"post","link":"https:\/\/dev.improof.lu\/fr\/articles\/egalite-equite-education-formation\/","title":{"rendered":"\u00c9galit\u00e9 \u2013 \u00c9quit\u00e9 en \u00e9ducation et formation"},"content":{"rendered":"<p>N\u00e9anmoins, la r\u00e9alit\u00e9 que nous vivons aujourd\u2019hui encore plus que dans le pass\u00e9 nous montre que tel n\u2019est pas le cas (\u00e9galit\u00e9 femme-homme, logement, etc.). La raison pour cette situation d\u2019in\u00e9galit\u00e9 r\u00e9side dans la situation d\u2019origine. En effet, les individus ne vivent pas une m\u00eame situation socio-\u00e9conomique, socioculturelle, etc.<\/p>\n<p>C\u2019est \u00e0 cet instant que l\u2019\u00e9quit\u00e9 peut \u00eatre compl\u00e9mentaire \u00e0 l\u2019\u00e9galit\u00e9. En aucun cas l\u2019\u00e9quit\u00e9 est le contraire ou l\u2019alternative de l\u2019\u00e9galit\u00e9. En effet, quand l\u2019\u00e9galit\u00e9 est ressentie comme quelque chose de pas toujours \u00ab juste \u00bb \u00e0 cause de la situation d\u2019in\u00e9galit\u00e9 d\u00e9crite ci-avant, l\u2019\u00e9quit\u00e9 peut r\u00e9soudre cette sensation d\u2019in\u00e9galit\u00e9 car elle comprend une certaine part d\u2019injustice acceptable. Autrement dit les personnes qui pour une raison ou une autre sont d\u00e9favoris\u00e9es socialement ou \u00e9conomiquement devraient pouvoir b\u00e9n\u00e9ficier de certains droits qui leur permettraient de profiter des lois et r\u00e8gles mises en place dans une logique d\u2019\u00e9galit\u00e9.<\/p>\n<p>L\u2019\u00e9quit\u00e9, qui repr\u00e9sente un \u00e9tat d&#8217;esprit qui rel\u00e8ve du sens commun, permettra de corriger les in\u00e9galit\u00e9s et faire \u00e9voluer le concept d\u2019\u00e9galit\u00e9. Ainsi, comme le montre le dessin ci-dessous, l\u2019\u00e9quit\u00e9 est une posture consistant \u00e0 accorder \u00e0 chacun ce qui lui est d\u00fb.[1]<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/dev.improof.lu\/app\/uploads\/2023\/04\/Egalite_Equite.jpg\" \/><\/p>\n<p><span style=\"font-size: 8pt;\">Source : <a href=\"http:\/\/ekladata.com\/wy8X5Vne6b3NVAP2aPmFxuH4UC4.jpg\" target=\"_blank\" rel=\"noopener\">http:\/\/ekladata.com\/wy8X5Vne6b3NVAP2aPmFxuH4UC4.jpg<\/a><\/span><\/p>\n<p>Comment s\u2019articule la r\u00e9flexion pr\u00e9c\u00e9dente dans le monde de l\u2019\u00e9ducation et de la formation ? En partant d\u2019une situation d\u2019apprenants issus des milieux d\u00e9favoris\u00e9s, d\u2019une vari\u00e9t\u00e9 de contextes socio\u00e9conomiques, culturels, linguistiques, de genre etc., cette situation engendre un environnement injuste et in\u00e9gal.<\/p>\n<p>L\u2019\u00e9galit\u00e9 des chances en \u00e9ducation et formation a pris, aujourd\u2019hui plus que dans le pass\u00e9, une tournure plus id\u00e9ale que v\u00e9ridique. En effet, l\u2019\u00e9galit\u00e9 en \u00e9ducation et formation devrait permettre \u00e0 tout apprenant d\u2019avoir une chance d\u2019acqu\u00e9rir les comp\u00e9tences pour arriver \u00e0 une certification.<\/p>\n<p>Autrement dit, l\u2019\u00e9galit\u00e9 devrait rendre possible \u00ab \u2026 qu\u2019\u00e0 sa sortie du syst\u00e8me scolaire, [l\u2019apprenant] \u2026 ait d\u00e9velopp\u00e9 son potentiel et ait acquis un minimum commun de comp\u00e9tences et de connaissances pour lui permettre de prendre sa place dans la soci\u00e9t\u00e9 moderne [\u2026] ; que tous les groupes sociaux soient \u00e9quitablement repr\u00e9sent\u00e9s parmi les dipl\u00f4m\u00e9s \u00e0 tous les ordres d\u2019enseignement \u00bb.[2]<\/p>\n<p>Pour r\u00e9aliser ce parcours, il faut que cette personne vive une exp\u00e9rience \u00e9ducative qui tienne compte de son potentiel d\u2019apprentissage. Or, nous sommes simultan\u00e9ment en face d\u2019une multitude de capacit\u00e9s des individus et d\u2019un concept d\u2019\u00e9galit\u00e9 normative du syst\u00e8me d\u2019\u00e9ducation et de formation.\u00a0 Ces normes concernent des facteurs comme l\u2019acc\u00e8s \u00e0 la formation, les possibilit\u00e9s de parcours, les conditions de r\u00e9ussite, etc.<\/p>\n<p>On peut d\u00e9crire le syst\u00e8me d\u2019\u00e9ducation et de formation par analogie \u00e0 un petit enfant qui apprend \u00e0 marcher. Cet enfant a besoin d\u2019un certain nombre d\u2019essais avant qu\u2019il ne marche. Dans le syst\u00e8me scolaire ceci n\u2019est souvent pas le cas. M\u00eame si parfois on a la possibilit\u00e9 d\u2019avoir droit \u00e0 plusieurs tentatives, ces essais sont assortis de commentaires comme : cela pourrait \u00eatre mieux, tu t\u2019es tromp\u00e9, c\u2019est faux, etc.<\/p>\n<p>Et si apr\u00e8s cette exp\u00e9rience truff\u00e9e de retours n\u00e9gatifs on rate le \u00ab deuxi\u00e8me \u00bb essai, les critiques qui fusent se caract\u00e9risent par une connotation encore plus n\u00e9gative comme : tu n\u2019as pas r\u00e9vis\u00e9, tu ne suis pas ce qu\u2019on t\u2019explique, tu n\u2019es pas capable de faire les choses correctement. Tout ceci est le contraire d\u2019un environnement favorable aux apprentissages. Un doute s\u2019installe aupr\u00e8s de l\u2019apprenant concernant sa capacit\u00e9 d\u2019apprendre et la confiance en soi-m\u00eame prend un s\u00e9rieux coup.<\/p>\n<p>Les cons\u00e9quences sur l\u2019individu qui veut apprendre d\u00e9pendent de sa provenance socio-\u00e9conomique. Il faut d\u2019ailleurs noter que l\u2019origine de l\u2019apprenant conditionne les r\u00e9actions par rapport aux apprentissages. On le voit le plus souvent dans la notation des \u00e9l\u00e8ves peu importe s\u2019il s\u2019agit de l\u2019\u00e9valuation par points ou l\u2019\u00e9valuation des comp\u00e9tences. On parle de \u00ab biais sociaux de notation \u00bb. Duru-Bellat et Mingat[3] mentionnent en guise d\u2019exemple les 3 biais suivants :<\/p>\n<ul>\n<li>les filles obtiennent, en moyenne, des notes sup\u00e9rieures \u00e0 celles des gar\u00e7ons ;<\/li>\n<li>les \u00e9l\u00e8ves redoublants sont not\u00e9s plus s\u00e9v\u00e8rement que les \u00e9l\u00e8ves \u00ab \u00e0 l\u2019heure \u00bb. Il en est de m\u00eame des \u00e9l\u00e8ves \u00ab en retard \u00bb qui ne sont pas redoublants ;<\/li>\n<li>les enfants de cadres sup\u00e9rieurs sont mieux not\u00e9s en classe que les enfants des autres milieux.<\/li>\n<\/ul>\n<p>Dans un tel environnement partial, soit les apprenants d\u00e9veloppent diverses strat\u00e9gies qu\u2019on peut caract\u00e9riser comme d\u00e9crochage de l\u2019int\u00e9rieur ou d\u00e9sengag\u00e9 tout en restant pr\u00e9sent physiquement, soit ils vivent un d\u00e9classement ou un retard.<\/p>\n<p>Les r\u00e9flexions ci-dessus ne couvrent qu\u2019un aspect parmi d\u2019autres, quant aux \u00e9l\u00e9ments qui s\u2019\u00e9loignent des principes de l\u2019\u00e9galit\u00e9.<\/p>\n<p>On peut reprendre cette analyse concernant d\u2019autres \u00e9l\u00e9ments de l\u2019\u00e9galit\u00e9 comme l\u2019acc\u00e8s au parcours d\u2019\u00e9ducation et de formation, le redoublement ou encore l\u2019\u00e9chec. On constatera qu\u2019ici on se voit face aux m\u00eames d\u00e9viations de l\u2019\u00e9galit\u00e9.<\/p>\n<p>La question qu\u2019on doit se poser au vu de cette situation est la suivante : pouvons-nous toujours nous permettre de perdre un nombre significatif de jeunes et d\u2019adultes parce que nous sommes incapables de changer le syst\u00e8me actuel en un mod\u00e8le \u00e9quitable et juste ? Que pouvons-nous faire pour y arriver ?<\/p>\n<p>Il faut repenser le syst\u00e8me d\u2019\u00e9ducation et de formation vers un syst\u00e8me qui tienne compte des potentiels de chacun. Pour y arriver, il faudrait d\u00e9laisser ce syst\u00e8me, le r\u00e9initialiser et r\u00e9fl\u00e9chir \u00e0 la mise en place d\u2019un syst\u00e8me \u00e9quitable ou comme le dit Einstein : \u00ab Nous ne pouvons pas r\u00e9soudre nos probl\u00e8mes avec la m\u00eame pens\u00e9e que nous avions quand nous les avons cr\u00e9\u00e9s \u00bb.<\/p>\n<p>Ceci ne sera possible que si on r\u00e9ussit \u00e0 convaincre les pass\u00e9istes et les bricoleurs actuels de l\u2019\u00e9ducation et de la formation \u00e0 participer \u00e0 cette r\u00e9forme culturelle de l\u2019\u00e9ducation et de la formation. Il faut en effet passer d\u2019une conception mat\u00e9rialiste de l\u2019\u00e9ducation et de la formation qui \u00ab affirme le primat de la mati\u00e8re sur l&#8217;esprit \u00bb[4], c\u2019est-\u00e0-dire qui ne diff\u00e9rencie pas les apprenants, \u00e0 un enseignement humaniste qui con\u00e7oit les apprenants en tant que r\u00e9cipiendaires.<\/p>\n<p>Il s\u2019agira de ne plus transmettre les mati\u00e8res, mais d\u2019\u00e9tablir le lien entre la mati\u00e8re et l&#8217;apprenant, de lui faire d\u00e9couvrir quelque chose. Si on arrive \u00e0 adopter cette id\u00e9e comme point de d\u00e9part on pourra d\u00e9velopper un environnement d\u2019apprentissage \u00e9quitable.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00c9galit\u00e9 et \u00e9quit\u00e9\u00a0: parmi les deux, le mot qui est le plus connu et utilis\u00e9 est celui de l\u2019\u00e9galit\u00e9. Ce terme qui fut introduit par la R\u00e9volution fran\u00e7aise a mis du temps \u00e0 se g\u00e9n\u00e9raliser, comme par exemple le vote des femmes qui est venu plus tard. L\u2019\u00e9galit\u00e9 se d\u00e9finit par trois aspects : celui des conditions (revenus, logement etc.) celui des chances (chacun doit avoir la m\u00eame opportunit\u00e9 de r\u00e9ussir ind\u00e9pendant de son origine sociale), et celui des droits (tout le monde a les m\u00eames droits).<\/p>\n","protected":false},"author":16,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[2],"tags":[],"class_list":["post-1113","post","type-post","status-publish","format-standard","hentry","category-non-classifiee","topic-formation","format-text-fr"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u00c9galit\u00e9 \u2013 \u00c9quit\u00e9 en \u00e9ducation et formation - Improof<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dev.improof.lu\/fr\/articles\/egalite-equite-education-formation\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00c9galit\u00e9 \u2013 \u00c9quit\u00e9 en \u00e9ducation et formation\" \/>\n<meta property=\"og:description\" content=\"\u00c9galit\u00e9 et \u00e9quit\u00e9\u00a0: parmi les deux, le mot qui est le plus connu et utilis\u00e9 est celui de l\u2019\u00e9galit\u00e9. Ce terme qui fut introduit par la R\u00e9volution fran\u00e7aise a mis du temps \u00e0 se g\u00e9n\u00e9raliser, comme par exemple le vote des femmes qui est venu plus tard. L\u2019\u00e9galit\u00e9 se d\u00e9finit par trois aspects : celui des conditions (revenus, logement etc.) celui des chances (chacun doit avoir la m\u00eame opportunit\u00e9 de r\u00e9ussir ind\u00e9pendant de son origine sociale), et celui des droits (tout le monde a les m\u00eames droits).\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dev.improof.lu\/fr\/articles\/egalite-equite-education-formation\/\" \/>\n<meta property=\"og:site_name\" content=\"Improof\" \/>\n<meta property=\"article:published_time\" content=\"2023-04-26T07:40:26+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-01-31T15:21:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dev.improof.lu\/app\/uploads\/2023\/04\/Decrochage.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1280\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Jos Noesen\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"\u00c9galit\u00e9 \u2013 \u00c9quit\u00e9 en \u00e9ducation et formation\" \/>\n<meta name=\"twitter:description\" content=\"\u00c9galit\u00e9 et \u00e9quit\u00e9\u00a0: parmi les deux, le mot qui est le plus connu et utilis\u00e9 est celui de l\u2019\u00e9galit\u00e9. Ce terme qui fut introduit par la R\u00e9volution fran\u00e7aise a mis du temps \u00e0 se g\u00e9n\u00e9raliser, comme par exemple le vote des femmes qui est venu plus tard. L\u2019\u00e9galit\u00e9 se d\u00e9finit par trois aspects : celui des conditions (revenus, logement etc.) celui des chances (chacun doit avoir la m\u00eame opportunit\u00e9 de r\u00e9ussir ind\u00e9pendant de son origine sociale), et celui des droits (tout le monde a les m\u00eames droits).\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/dev.improof.lu\/app\/uploads\/2023\/04\/Decrochage.jpg\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jos Noesen\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/dev.improof.lu\/fr\/articles\/egalite-equite-education-formation\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dev.improof.lu\/fr\/articles\/egalite-equite-education-formation\/\"},\"author\":{\"name\":\"Jos Noesen\",\"@id\":\"https:\/\/dev.improof.lu\/fr\/#\/schema\/person\/1acca3a4fff1e7ca61c862102a896fb9\"},\"headline\":\"\u00c9galit\u00e9 \u2013 \u00c9quit\u00e9 en \u00e9ducation et formation\",\"datePublished\":\"2023-04-26T07:40:26+00:00\",\"dateModified\":\"2024-01-31T15:21:06+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dev.improof.lu\/fr\/articles\/egalite-equite-education-formation\/\"},\"wordCount\":1185,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dev.improof.lu\/fr\/#organization\"},\"image\":{\"@id\":\"https:\/\/dev.improof.lu\/fr\/articles\/egalite-equite-education-formation\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dev.improof.lu\/app\/uploads\/2023\/04\/Egalite_Equite.jpg\",\"articleSection\":[\"Non classifi\u00e9(e)\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dev.improof.lu\/fr\/articles\/egalite-equite-education-formation\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dev.improof.lu\/fr\/articles\/egalite-equite-education-formation\/\",\"url\":\"https:\/\/dev.improof.lu\/fr\/articles\/egalite-equite-education-formation\/\",\"name\":\"\u00c9galit\u00e9 \u2013 \u00c9quit\u00e9 en \u00e9ducation et formation - Improof\",\"isPartOf\":{\"@id\":\"https:\/\/dev.improof.lu\/fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dev.improof.lu\/fr\/articles\/egalite-equite-education-formation\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dev.improof.lu\/fr\/articles\/egalite-equite-education-formation\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dev.improof.lu\/app\/uploads\/2023\/04\/Egalite_Equite.jpg\",\"datePublished\":\"2023-04-26T07:40:26+00:00\",\"dateModified\":\"2024-01-31T15:21:06+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/dev.improof.lu\/fr\/articles\/egalite-equite-education-formation\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dev.improof.lu\/fr\/articles\/egalite-equite-education-formation\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dev.improof.lu\/fr\/articles\/egalite-equite-education-formation\/#primaryimage\",\"url\":\"https:\/\/dev.improof.lu\/app\/uploads\/2023\/04\/Egalite_Equite.jpg\",\"contentUrl\":\"https:\/\/dev.improof.lu\/app\/uploads\/2023\/04\/Egalite_Equite.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dev.improof.lu\/fr\/articles\/egalite-equite-education-formation\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/dev.improof.lu\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00c9galit\u00e9 \u2013 \u00c9quit\u00e9 en \u00e9ducation et formation\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dev.improof.lu\/fr\/#website\",\"url\":\"https:\/\/dev.improof.lu\/fr\/\",\"name\":\"Improof\",\"description\":\"Tagline goes here\",\"publisher\":{\"@id\":\"https:\/\/dev.improof.lu\/fr\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dev.improof.lu\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/dev.improof.lu\/fr\/#organization\",\"name\":\"Improof\",\"url\":\"https:\/\/dev.improof.lu\/fr\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dev.improof.lu\/fr\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dev.improof.lu\/app\/uploads\/2022\/10\/improof-logo-svg.png\",\"contentUrl\":\"https:\/\/dev.improof.lu\/app\/uploads\/2022\/10\/improof-logo-svg.png\",\"width\":652,\"height\":209,\"caption\":\"Improof\"},\"image\":{\"@id\":\"https:\/\/dev.improof.lu\/fr\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dev.improof.lu\/fr\/#\/schema\/person\/1acca3a4fff1e7ca61c862102a896fb9\",\"name\":\"Jos Noesen\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dev.improof.lu\/fr\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/f2b825eca9038bbe8020f8770ba1201e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/f2b825eca9038bbe8020f8770ba1201e?s=96&d=mm&r=g\",\"caption\":\"Jos Noesen\"},\"url\":\"https:\/\/dev.improof.lu\/fr\/articles\/author\/jos-noesen\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00c9galit\u00e9 \u2013 \u00c9quit\u00e9 en \u00e9ducation et formation - Improof","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dev.improof.lu\/fr\/articles\/egalite-equite-education-formation\/","og_locale":"fr_FR","og_type":"article","og_title":"\u00c9galit\u00e9 \u2013 \u00c9quit\u00e9 en \u00e9ducation et formation","og_description":"\u00c9galit\u00e9 et \u00e9quit\u00e9\u00a0: parmi les deux, le mot qui est le plus connu et utilis\u00e9 est celui de l\u2019\u00e9galit\u00e9. Ce terme qui fut introduit par la R\u00e9volution fran\u00e7aise a mis du temps \u00e0 se g\u00e9n\u00e9raliser, comme par exemple le vote des femmes qui est venu plus tard. L\u2019\u00e9galit\u00e9 se d\u00e9finit par trois aspects : celui des conditions (revenus, logement etc.) celui des chances (chacun doit avoir la m\u00eame opportunit\u00e9 de r\u00e9ussir ind\u00e9pendant de son origine sociale), et celui des droits (tout le monde a les m\u00eames droits).","og_url":"https:\/\/dev.improof.lu\/fr\/articles\/egalite-equite-education-formation\/","og_site_name":"Improof","article_published_time":"2023-04-26T07:40:26+00:00","article_modified_time":"2024-01-31T15:21:06+00:00","og_image":[{"width":1920,"height":1280,"url":"https:\/\/dev.improof.lu\/app\/uploads\/2023\/04\/Decrochage.jpg","type":"image\/jpeg"}],"author":"Jos Noesen","twitter_card":"summary_large_image","twitter_title":"\u00c9galit\u00e9 \u2013 \u00c9quit\u00e9 en \u00e9ducation et formation","twitter_description":"\u00c9galit\u00e9 et \u00e9quit\u00e9\u00a0: parmi les deux, le mot qui est le plus connu et utilis\u00e9 est celui de l\u2019\u00e9galit\u00e9. Ce terme qui fut introduit par la R\u00e9volution fran\u00e7aise a mis du temps \u00e0 se g\u00e9n\u00e9raliser, comme par exemple le vote des femmes qui est venu plus tard. L\u2019\u00e9galit\u00e9 se d\u00e9finit par trois aspects : celui des conditions (revenus, logement etc.) celui des chances (chacun doit avoir la m\u00eame opportunit\u00e9 de r\u00e9ussir ind\u00e9pendant de son origine sociale), et celui des droits (tout le monde a les m\u00eames droits).","twitter_image":"https:\/\/dev.improof.lu\/app\/uploads\/2023\/04\/Decrochage.jpg","twitter_misc":{"Written by":"Jos Noesen","Est. reading time":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/dev.improof.lu\/fr\/articles\/egalite-equite-education-formation\/#article","isPartOf":{"@id":"https:\/\/dev.improof.lu\/fr\/articles\/egalite-equite-education-formation\/"},"author":{"name":"Jos Noesen","@id":"https:\/\/dev.improof.lu\/fr\/#\/schema\/person\/1acca3a4fff1e7ca61c862102a896fb9"},"headline":"\u00c9galit\u00e9 \u2013 \u00c9quit\u00e9 en \u00e9ducation et formation","datePublished":"2023-04-26T07:40:26+00:00","dateModified":"2024-01-31T15:21:06+00:00","mainEntityOfPage":{"@id":"https:\/\/dev.improof.lu\/fr\/articles\/egalite-equite-education-formation\/"},"wordCount":1185,"commentCount":0,"publisher":{"@id":"https:\/\/dev.improof.lu\/fr\/#organization"},"image":{"@id":"https:\/\/dev.improof.lu\/fr\/articles\/egalite-equite-education-formation\/#primaryimage"},"thumbnailUrl":"https:\/\/dev.improof.lu\/app\/uploads\/2023\/04\/Egalite_Equite.jpg","articleSection":["Non classifi\u00e9(e)"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dev.improof.lu\/fr\/articles\/egalite-equite-education-formation\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/dev.improof.lu\/fr\/articles\/egalite-equite-education-formation\/","url":"https:\/\/dev.improof.lu\/fr\/articles\/egalite-equite-education-formation\/","name":"\u00c9galit\u00e9 \u2013 \u00c9quit\u00e9 en \u00e9ducation et formation - Improof","isPartOf":{"@id":"https:\/\/dev.improof.lu\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dev.improof.lu\/fr\/articles\/egalite-equite-education-formation\/#primaryimage"},"image":{"@id":"https:\/\/dev.improof.lu\/fr\/articles\/egalite-equite-education-formation\/#primaryimage"},"thumbnailUrl":"https:\/\/dev.improof.lu\/app\/uploads\/2023\/04\/Egalite_Equite.jpg","datePublished":"2023-04-26T07:40:26+00:00","dateModified":"2024-01-31T15:21:06+00:00","breadcrumb":{"@id":"https:\/\/dev.improof.lu\/fr\/articles\/egalite-equite-education-formation\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dev.improof.lu\/fr\/articles\/egalite-equite-education-formation\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dev.improof.lu\/fr\/articles\/egalite-equite-education-formation\/#primaryimage","url":"https:\/\/dev.improof.lu\/app\/uploads\/2023\/04\/Egalite_Equite.jpg","contentUrl":"https:\/\/dev.improof.lu\/app\/uploads\/2023\/04\/Egalite_Equite.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/dev.improof.lu\/fr\/articles\/egalite-equite-education-formation\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/dev.improof.lu\/fr\/"},{"@type":"ListItem","position":2,"name":"\u00c9galit\u00e9 \u2013 \u00c9quit\u00e9 en \u00e9ducation et formation"}]},{"@type":"WebSite","@id":"https:\/\/dev.improof.lu\/fr\/#website","url":"https:\/\/dev.improof.lu\/fr\/","name":"Improof","description":"Tagline goes here","publisher":{"@id":"https:\/\/dev.improof.lu\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dev.improof.lu\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/dev.improof.lu\/fr\/#organization","name":"Improof","url":"https:\/\/dev.improof.lu\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dev.improof.lu\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/dev.improof.lu\/app\/uploads\/2022\/10\/improof-logo-svg.png","contentUrl":"https:\/\/dev.improof.lu\/app\/uploads\/2022\/10\/improof-logo-svg.png","width":652,"height":209,"caption":"Improof"},"image":{"@id":"https:\/\/dev.improof.lu\/fr\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/dev.improof.lu\/fr\/#\/schema\/person\/1acca3a4fff1e7ca61c862102a896fb9","name":"Jos Noesen","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dev.improof.lu\/fr\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/f2b825eca9038bbe8020f8770ba1201e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f2b825eca9038bbe8020f8770ba1201e?s=96&d=mm&r=g","caption":"Jos Noesen"},"url":"https:\/\/dev.improof.lu\/fr\/articles\/author\/jos-noesen\/"}]}},"_links":{"self":[{"href":"https:\/\/dev.improof.lu\/fr\/wp-json\/wp\/v2\/posts\/1113","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.improof.lu\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dev.improof.lu\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dev.improof.lu\/fr\/wp-json\/wp\/v2\/users\/16"}],"replies":[{"embeddable":true,"href":"https:\/\/dev.improof.lu\/fr\/wp-json\/wp\/v2\/comments?post=1113"}],"version-history":[{"count":8,"href":"https:\/\/dev.improof.lu\/fr\/wp-json\/wp\/v2\/posts\/1113\/revisions"}],"predecessor-version":[{"id":1760,"href":"https:\/\/dev.improof.lu\/fr\/wp-json\/wp\/v2\/posts\/1113\/revisions\/1760"}],"wp:attachment":[{"href":"https:\/\/dev.improof.lu\/fr\/wp-json\/wp\/v2\/media?parent=1113"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dev.improof.lu\/fr\/wp-json\/wp\/v2\/categories?post=1113"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dev.improof.lu\/fr\/wp-json\/wp\/v2\/tags?post=1113"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}