{"id":1311,"date":"2023-09-20T07:52:34","date_gmt":"2023-09-20T07:52:34","guid":{"rendered":"https:\/\/dev.improof.lu\/?p=1311"},"modified":"2024-01-31T15:17:05","modified_gmt":"2024-01-31T15:17:05","slug":"classes-moyennes-1","status":"publish","type":"post","link":"https:\/\/dev.improof.lu\/fr\/articles\/classes-moyennes-1\/","title":{"rendered":"La classe moyenne \u2013 c\u2019est moi !"},"content":{"rendered":"<p>La classe moyenne. Voil\u00e0 une construction sociale \u00e0 laquelle tout le monde se sent appartenir, mais laquelle personne ne sait d\u00e9finir. Dans une \u00e9tude du CREDOC[1], des chercheurs ont not\u00e9 la tendance d\u2019une personne \u00ab \u00e0 d\u00e9clarer appartenir aux classes moyennes, et cela quel que soit son niveau de revenu \u00bb. Le r\u00e9flexe de se voir faire partie des classes moyennes y est expliqu\u00e9 \u00e0 la fois par \u00ab une certaine myopie [des m\u00e9nages] sur leur niveau de vie \u00bb que par \u00ab une certaine r\u00e9ticence \u00e0 s\u2019afficher en marge de la norme (la norme serait ici la moyenne) \u00bb. M\u00eame si des chiffres d\u00e9taill\u00e9s de cette \u00e9tude ne sont pas disponibles pour le Luxembourg, la situation n\u2019y doit pas trop diverger. D\u2019apr\u00e8s les plus r\u00e9centes donn\u00e9es de l\u2019OCDE, 83% des r\u00e9sidents au Luxembourg s\u2019auto-identifient comme faisant part de la classe moyenne.[2]<\/p>\n<h2>Wer bin ich \u2013 und wenn ja wie viele?[3]<\/h2>\n<p>Mais quelle est donc cette classe moyenne \u00e0 laquelle autant de gens s\u2019auto-identifient ?<\/p>\n<p>Est-ce cette classe moyenne pr\u00e9sent\u00e9e par John Rawls comme pilier de la justice sociale, avec son potentiel de coop\u00e9ration et de redistribution pour le bien de tous, la classe moyenne qui, d\u2019apr\u00e8s Hannah Arendt joue un r\u00f4le crucial dans le maintien de la sph\u00e8re publique et la pr\u00e9servation de la d\u00e9mocratie participative, la classe moyenne comme fondement de la soci\u00e9t\u00e9 civile, contribuant \u00e0 la pr\u00e9servation des droits individuels et \u00e0 la garantie de la propri\u00e9t\u00e9 d\u00e9finie par John Locke, ou encore la classe moyenne qui est selon Alexis de Tocqueville l&#8217;\u00e9pine dorsale de la soci\u00e9t\u00e9 d\u00e9mocratique, fournissant la stabilit\u00e9 et le bon sens n\u00e9cessaires \u00e0 son fonctionnement ?<\/p>\n<p>Ou est-ce que la classe moyenne est plut\u00f4t l&#8217;interm\u00e9diaire instable entre la bourgeoisie et le prol\u00e9tariat condamn\u00e9e \u00e0 dispara\u00eetre comme l\u2019a d\u00e9finie Karl Marx, la classe qui incarne le mode de vie bourgeois et les valeurs de l&#8217;individualisme selon Max Weber, ou encore la classe qui, selon Slavoj \u017di\u017eek est pi\u00e9g\u00e9e dans le cycle de la consommation, cherchant un bonheur illusoire dans l&#8217;accumulation de biens mat\u00e9riels ?[4]<\/p>\n<p>Notons ces diff\u00e9rences parfois fondamentales des d\u00e9finitions de classes moyennes selon les philosophes. Tandis que la stabilit\u00e9 consiste une caract\u00e9ristique fondamentale des classes moyennes d\u2019apr\u00e8s les premiers auteurs (l\u2019on note les expressions de \u00ab <strong>pilier<\/strong> \u00bb, de \u00ab <strong>maintien<\/strong> de la sph\u00e8re politique et la <strong>pr\u00e9servation<\/strong> \u00bb, de \u00ab <strong>fondement<\/strong> \u00bb et de \u00ab <strong>stabilit\u00e9<\/strong> \u00bb), l\u2019instabilit\u00e9 semble dominer les classes moyennes selon les deuxi\u00e8mes (qui d\u00e9finissent les classes moyennes d\u2019 \u00ab <strong>instable<\/strong> \u00bb, pris dans un \u00ab <strong>cycle<\/strong> \u00bb qui risque de se \u00ab <strong>perdre<\/strong> \u00bb).<\/p>\n<p>Vu ces appr\u00e9ciations parfois tr\u00e8s divergentes des classes moyennes, l\u2019on ne sait d\u00e9finir, une fois pour toutes, la classe moyenne d\u2019un point de vue philosophique. Comment peut-on alors d\u00e9finir d\u00e9lib\u00e9r\u00e9ment qui appartient \u00e0 cette fameuse classe moyenne qui est autant repr\u00e9sent\u00e9e dans le d\u00e9bat public ?<\/p>\n<p>Or, en sociologie, les classes sociales sont d\u00e9termin\u00e9es en fonction d\u2019une multitude de caract\u00e9ristiques, \u00e0 savoir des cat\u00e9gories socioprofessionnelles, du capital culturel, du capital social, des origines ou\/et encore du niveau de richesse des individus. Il existe donc un enchev\u00eatrement de crit\u00e8res d\u00e9finisseurs qui permet certes d\u2019\u00eatre plus pr\u00e9cis dans la d\u00e9finition de classe sociale, mais qui rend la d\u00e9finition d\u2019une grande classe moyenne quasiment impossible. Ce n\u2019est donc la sociologie qui permet de clore le d\u00e9bat sur les classes moyennes.<\/p>\n<p>Sans aucun doute, la d\u00e9finition de classe moyenne peut \u00eatre vue comme sujet complexe qui suscite de nombreux d\u00e9bats et interrogations. Il n\u2019existe d\u2019unanimit\u00e9 \u00e0 ce sujet, ni dans le d\u00e9bat politique, ni d\u2019ailleurs dans la sph\u00e8re scientifique, sociologique et philosophique. Au contraire, vu le nombre de d\u00e9finitions et d\u2019emplois du terme de \u00ab classe moyenne \u00bb, il est certes plus juste de parler <strong><em>des<\/em><\/strong> classes moyennes au pluriel, plut\u00f4t que de <em><strong>la<\/strong><\/em> classe moyenne au singulier.<\/p>\n<p>Malgr\u00e9 ce concept flou, l\u2019on ne cesse d\u2019entendre des discours de \u00ab classes moyennes \u00e0 la d\u00e9rive[5] \u00bb, de la \u00ab classe moyenne oubli\u00e9e[6] \u00bb, du \u00ab M\u00ebttelstandsbockel[7] \u00bb, de la \u00ab classe moyenne sous pression[8] \u00bb, de la \u00ab classe moyenne achev\u00e9e par la mondialisation[9] \u00bb ou encore, pendant chaque campagne \u00e9lectorale, de la classe moyenne qui m\u00e9rite des all\u00e9gements fiscaux. Mais, de qui parle-t-on ?<\/p>\n<h2>Des d\u00e9finitions philosophiques et sociologiques \u00e0 la d\u00e9finition \u00e9conomique<\/h2>\n<p>En se rapprochant de la question des classes moyennes d\u2019un point de vue \u00e9conomique, l\u2019on peut dresser une d\u00e9finition, parmi une multitude de d\u00e9finitions possibles, de la classe moyenne en se penchant sur le crit\u00e8re de \u00ab richesse \u00bb des m\u00e9nages. Toutefois, m\u00eame en se penchant uniquement sur le poids \u00e9conomique des individus pour d\u00e9terminer s\u2019ils appartiennent \u00e0 la classe moyenne ou pas, la d\u00e9finition des classes moyennes reste loin d\u2019\u00eatre simple.<\/p>\n<p>En effet, il existe deux principes scientifiques tr\u00e8s diff\u00e9rents pour d\u00e9terminer les classes moyennes en se penchant sur le niveau de la richesse des m\u00e9nages.<\/p>\n<p>Certains chercheurs d\u00e9finissent la classe moyenne comme \u00e9tant l\u2019ensemble de m\u00e9nages se situant dans certains d\u00e9ciles de richesse[10]. Selon cette d\u00e9finition, la classe moyenne est constitu\u00e9e d\u2019une part de x%, d\u00e9finie \u00e0 l\u2019avance, de la soci\u00e9t\u00e9 et elle reste constante tout au long des ann\u00e9es. L\u2019avantage de cette d\u00e9finition est que l\u2019on peut situer la classe moyenne au milieu de la distribution des richesses, sans d\u00e9finir ex ante les seuils de revenus pour appartenir aux diff\u00e9rentes classes. Dans Bigot et al. (2012)[11] par exemple, sont consid\u00e9r\u00e9s comme appartenant \u00e0 la classe moyenne tous les m\u00e9nages du quatri\u00e8me au huiti\u00e8me d\u00e9cile de la distribution. De cette mani\u00e8re, les auteurs d\u00e9finissent que la classe moyenne est constitu\u00e9e de 60% de la population qui se situe au juste milieu de la distribution.<\/p>\n<p>En revanche, une autre mani\u00e8re de d\u00e9finir la classe moyenne consiste \u00e0 consid\u00e9rer comme appartenant \u00e0 la classe moyenne tous les m\u00e9nages avec un niveau de vie qui d\u00e9vie d\u2019une certaine ampleur du niveau de vie m\u00e9dian de la population totale. Selon ce deuxi\u00e8me principe, le chercheur ne d\u00e9finit pas ex ante la taille de la classe moyenne, mais il d\u00e9finit les bornes de richesse sup\u00e9rieures et inf\u00e9rieures, bas\u00e9es sur la richesse m\u00e9diane, pour qu\u2019un individu ou un m\u00e9nage appartient \u00e0 la classe moyenne. Dans OECD (2019)[12] et Atkinson et al. (2011)[13], est d\u00e9fini comme appartenant \u00e0 la classe moyenne tout m\u00e9nage qui a un niveau de vie entre 75% et 200% du niveau de vie m\u00e9dian.<\/p>\n<p>L\u2019avantage de ce deuxi\u00e8me principe d\u00e9finisseur est que la part des m\u00e9nages qui appartient \u00e0 la classe moyenne d\u00e9pend de la distribution du niveau de vie : plus les m\u00e9nages se rassemblent au centre de la distribution, plus il y a de m\u00e9nages qui seront d\u00e9finis comme appartenant \u00e0 la classe moyenne, tandis qu\u2019une population fortement polaris\u00e9e n\u2019a qu\u2019une faible classe moyenne. En outre, avec ce deuxi\u00e8me crit\u00e8re, une analyse plus dynamique est possible pour analyser l\u2019\u00e9volution de la taille de la classe moyenne au fil des ann\u00e9es. Cette deuxi\u00e8me d\u00e9finition garantit aussi une certaine ressemblance pr\u00e9d\u00e9finie des m\u00e9nages de la classe moyenne en ce qui concerne la variable d\u2019int\u00e9r\u00eat, tandis que pour la premi\u00e8re d\u00e9finition des m\u00e9nages avec des niveaux de richesse tr\u00e8s diff\u00e9rents pourraient \u00eatre rassembl\u00e9 dans la classe moyenne[14].<\/p>\n<h2>La classe moyenne de niveau de vie<\/h2>\n<p>Comme pr\u00e9c\u00e9demment d\u00e9crit, il n\u2019est pas possible de parler d\u2019une seule classe moyenne puisque la d\u00e9finition de celle-ci est bas\u00e9e sur une multitude de variables socio\u00e9conomiques, qui ne peuvent \u00eatre toutes prises en compte. Toutefois, en se rapprochant de la question d\u2019un point de vue \u00e9conomique, il est possible de construire <em><strong>une<\/strong><\/em> d\u00e9finition \u00e9conomique de la classe moyenne \u00e0 partir du niveau de vie des m\u00e9nages[15]. En retenant la d\u00e9finition de OECD (2019) et de Atkinson et al. (2011), la classe moyenne de niveau de vie sera d\u00e9finie par la suite comme \u00e9tant l\u2019ensemble des m\u00e9nages avec un niveau de vie entre 75% et 200% du niveau de vie m\u00e9dian.<\/p>\n<p>Sur base de cette d\u00e9finition, avec quel niveau de vie appartient-on donc \u00e0 la classe moyenne au Luxembourg ? Or, en 2019, derni\u00e8re ann\u00e9e pour laquelle l\u2019on dispose du niveau de vie des m\u00e9nages, le revenu disponible \u00e9quivalent m\u00e9dian annuel s\u2019\u00e9l\u00e8ve \u00e0 41 192 euros[16] ; appartiennent alors \u00e0 la classe moyenne tous les m\u00e9nages qui ont un niveau de vie entre 30 894 euros et 82 384 euros en cette ann\u00e9e. En euros de septembre 2023, ces limites inf\u00e9rieures et sup\u00e9rieures pour appartenir \u00e0 la classe moyenne s\u2019\u00e9l\u00e8vent respectivement \u00e0 37 772 euros et 100 724 euros[17]. Concr\u00e8tement, un m\u00e9nage constitu\u00e9 d\u2019un couple avec un enfant est, selon la d\u00e9finition retenue, consid\u00e9r\u00e9 comme appartenant \u00e0 la classe moyenne tant que son revenu annuel net disponible se situe en septembre 2023 entre 67 989 et 181 304 euros. Un m\u00e9nage monoparental avec un enfant par contre se situe dans la classe moyenne si son revenu disponible se situe entre 49 103 et 130 942 euros.[18]<\/p>\n<p><em><strong>Tableau : La classe moyenne \u2013 c\u2019est qui ?<\/strong><\/em><\/p>\n<p><img decoding=\"async\" src=\"https:\/\/dev.improof.lu\/app\/uploads\/2023\/09\/Graf3.jpg\" \/><\/p>\n<p><span style=\"font-size: 8pt;\">Donn\u00e9es : Luxembourg Income Study (LIS) Database http:\/\/www.lisdatacenter.org (Juin 2023) ; graphique et calculs : Auteur<\/span><\/p>\n<p>Avec ces seuils et plafonds de classe moyenne d\u00e9finis, 61,4% des m\u00e9nages appartiennent \u00e0 la classe moyenne de niveau de vie en 2019. En revanche, la classe sup\u00e9rieure repr\u00e9sente 9,1% des m\u00e9nages au Luxembourg et la classe inf\u00e9rieure en repr\u00e9sente 29,5%.[19]<\/p>\n<p>Une fois d\u00e9finie, la classe moyenne peut \u00eatre compar\u00e9e \u00e0 la classe inf\u00e9rieure ainsi qu\u2019\u00e0 la classe sup\u00e9rieure pour mettre en perspective leur poids \u00e9conomique dans la soci\u00e9t\u00e9.<\/p>\n<p>Or, en 2019, la classe moyenne concentre 64,1% de l\u2019ensemble des revenus disponibles des m\u00e9nages r\u00e9sidents. Le fait que leur part dans l\u2019ensemble des revenus correspond \u00e0 peu pr\u00e8s \u00e0 leur part dans l\u2019ensemble de la population (64,1% contre 61,4%) indique que la classe moyenne concentre autant de revenus qu\u2019en situation de r\u00e9partition \u00e9gale de l\u2019ensemble de tous les revenus des r\u00e9sidents. Les classes inf\u00e9rieures par contre ne concentrent qu\u2019un peu moins de 15% des revenus disponibles alors qu\u2019ils repr\u00e9sentent une part deux fois aussi importante dans la population totale.[20] Les classes sup\u00e9rieures concentrent 21,0% des revenus, soit plus du double de leur poids dans la population.<\/p>\n<p>Ces concentrations de revenus sont expliqu\u00e9es d\u2019ailleurs par des niveaux de vie tr\u00e8s diff\u00e9rents entre les diff\u00e9rentes classes sociales. En effet, le niveau de vie annuel m\u00e9dian dans la classe inf\u00e9rieure s\u2019\u00e9levait \u00e0 23 776 euros en 2019 (29 069\u20ac en euros constants de septembre 2023), tandis qu\u2019il s\u2019\u00e9levait \u00e0 47 460 euros (58 026 euros de septembre 2023) en classe moyenne et 98 310 euros (120 196 euros de septembre 2023) en classe sup\u00e9rieure.<\/p>\n<h2>La classe moyenne est-elle en d\u00e9clin ?<\/h2>\n<p>Qu\u2019en est-il de l\u2019\u00e9volution de cette classe moyenne au Luxembourg ? Est-elle effectivement \u00e0 la d\u00e9rive comme l\u2019affirme le sociologue Louis Chauvel pour les classes moyennes occidentales et fran\u00e7aises ? Est-elle sous pression et en perte de vitesse comme le constate l\u2019OCDE ?<\/p>\n<p>Or, au Luxembourg, la part des m\u00e9nages pouvant \u00eatre consid\u00e9r\u00e9s comme appartenant \u00e0 la classe moyenne selon notre d\u00e9finition a significativement baiss\u00e9 entre 1985 et 2019. En 1985, plus de 70% des m\u00e9nages appartenaient \u00e0 la classe moyenne et avaient ainsi un niveau de vie entre 75% et 200% du niveau de vie m\u00e9dian de l\u2019\u00e9poque. Au fil des ann\u00e9es, cette part s\u2019est r\u00e9tr\u00e9cie continuellement avec une baisse importante entre 2016 et 2018 pour finalement atteindre 61,3% en 2019. Autrement dit, la part des m\u00e9nages appartenant \u00e0 la classe moyenne a baiss\u00e9 de 9,6 points en 34 ans, soit une baisse de 13,5% ! Cette baisse significative de la part des m\u00e9nages appartenant \u00e0 la classe moyenne s\u2019est faite au profit de mani\u00e8re quasi-\u00e9gale \u00e0 la classe inf\u00e9rieure et \u00e0 la classe sup\u00e9rieure qui ont vu leur part augmenter de respectivement 5,4 et 4,2 points de pourcentage.<\/p>\n<p><em><strong>Le d\u00e9clin de la classe moyenne (1985 \u2013 2019)<\/strong><\/em><\/p>\n<p><img decoding=\"async\" src=\"https:\/\/dev.improof.lu\/app\/uploads\/2023\/09\/Graf2.jpg\" \/><\/p>\n<p><span style=\"font-size: 8pt;\">Donn\u00e9es : Luxembourg Income Study (LIS) Database http:\/\/www.lisdatacenter.org (Juin 2023) ; graphique et calculs : Auteur<\/span><\/p>\n<p><span style=\"font-size: 8pt;\">Note : les barres repr\u00e9sentent des ruptures de s\u00e9rie<\/span><\/p>\n<p>Ce constat revient \u00e0 dire que m\u00eame si la classe moyenne reste majoritaire, de moins en moins de m\u00e9nages y appartiennent. En d\u2019autres mots, de moins en moins de m\u00e9nages se situent autour du milieu de la distribution du niveau de vie et on assiste \u00e0 une polarisation des m\u00e9nages ; presque 30% se situent dans la classe inf\u00e9rieure et pr\u00e8s de 10% sont dans la classe sup\u00e9rieure. On trouve ainsi quasiment 40% des m\u00e9nages dans des extr\u00e9mit\u00e9s, tandis qu\u2019en 1985 ils n\u2019\u00e9taient que moins de 30%.<\/p>\n<p><em><strong>L\u2019augmentation de la polarisation (1985 \u2013 2019)<\/strong><\/em><\/p>\n<p><img decoding=\"async\" src=\"https:\/\/dev.improof.lu\/app\/uploads\/2023\/09\/Graf.jpg\" \/><\/p>\n<p><span style=\"font-size: 8pt;\">Donn\u00e9es : Luxembourg Income Study (LIS) Database http:\/\/www.lisdatacenter.org (Juin 2023) ; graphique et calculs : Auteur<\/span><\/p>\n<p>En termes de poids \u00e9conomique, le d\u00e9clin est encore plus important pour la classe moyenne. En 1985, la classe moyenne concentrait encore 77,1% de l\u2019ensemble des revenus disponibles. Au fil des ann\u00e9es, cette proportion a baiss\u00e9 et ne s\u2019\u00e9l\u00e8ve plus qu\u2019\u00e0 64,1% en 2019. Avec 16,9%, la baisse du poids \u00e9conomique d\u00e9passe donc la baisse du poids dans la population, ce qui veut dire que la classe moyenne est d\u00e9class\u00e9e et devient comparativement plus pauvre. Le m\u00eame constat d\u2019un appauvrissement relatif peut \u00eatre constat\u00e9 chez la classe inf\u00e9rieure dans laquelle la hausse du poids \u00e9conomique n\u2019a pas pu suivre la hausse du poids dans la population (+18,7% contre +22,4%). En revanche, le poids \u00e9conomique a augment\u00e9 plus que proportionnellement dans la classe sup\u00e9rieure (x2 contre x1,8).<\/p>\n<p style=\"text-align: center;\">***<\/p>\n<p>Cette baisse consid\u00e9rable du poids de la classe moyenne ne peut \u00eatre banalis\u00e9, ni d\u2019ailleurs \u00eatre consid\u00e9r\u00e9 comme un <strong><em>non-event<\/em><\/strong> car \u00ab une classe moyenne forte et prosp\u00e8re est essentielle \u00e0 la r\u00e9ussite de l\u2019\u00e9conomie et \u00e0 la coh\u00e9sion de la soci\u00e9t\u00e9 \u00bb et \u00ab les soci\u00e9t\u00e9s qui reposent sur une classe moyenne forte [\u2026] jouissent [\u2026] d\u2019une plus grande stabilit\u00e9 politique et d\u2019une meilleure gouvernance \u00bb.[21]<\/p>\n<p>La pr\u00e9servation, voire la consolidation des classes moyennes est donc d\u2019une immense importance pour garantir la stabilit\u00e9 \u00e9conomique et politique d\u2019une soci\u00e9t\u00e9 ; d\u2019autant plus que les d\u00e9fis soci\u00e9taux auxquels nous serons confront\u00e9s en raison de la transition \u00e9cologique et le changement climatique risquent de demander des sacrifices aux m\u00e9nages. Le d\u00e9clin des classes moyennes est \u00e0 prendre au s\u00e9rieux, les <a href=\"https:\/\/dev.improof.lu\/fr\/articles\/classes-moyennes-2\/\" target=\"_blank\" rel=\"noopener\"><span style=\"text-decoration: underline;\">causes du d\u00e9clin<\/span><\/a> \u00e0 combattre et la tendance \u00e0 renverser !<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La classe moyenne. Voil\u00e0 une construction sociale \u00e0 laquelle tout le monde se sent appartenir, mais laquelle personne ne sait d\u00e9finir. Dans une \u00e9tude du CREDOC, des chercheurs ont not\u00e9 la tendance d\u2019une personne \u00ab \u00e0 d\u00e9clarer appartenir aux classes moyennes, et cela quel que soit son niveau de revenu \u00bb.<\/p>\n","protected":false},"author":8,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[2],"tags":[],"class_list":["post-1311","post","type-post","status-publish","format-standard","hentry","category-non-classifiee","topic-inegalites","format-text-fr"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>La classe moyenne \u2013 c\u2019est moi ! - Improof<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dev.improof.lu\/fr\/articles\/classes-moyennes-1\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La classe moyenne \u2013 c\u2019est moi !\" \/>\n<meta property=\"og:description\" content=\"La classe moyenne. Voil\u00e0 une construction sociale \u00e0 laquelle tout le monde se sent appartenir, mais laquelle personne ne sait d\u00e9finir. Dans une \u00e9tude du CREDOC, des chercheurs ont not\u00e9 la tendance d\u2019une personne \u00ab \u00e0 d\u00e9clarer appartenir aux classes moyennes, et cela quel que soit son niveau de revenu \u00bb.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dev.improof.lu\/fr\/articles\/classes-moyennes-1\/\" \/>\n<meta property=\"og:site_name\" content=\"Improof\" \/>\n<meta property=\"article:published_time\" content=\"2023-09-20T07:52:34+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-01-31T15:17:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dev.improof.lu\/app\/uploads\/2023\/09\/Work.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1281\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Dylan Theis\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"La classe moyenne \u2013 c\u2019est moi !\" \/>\n<meta name=\"twitter:description\" content=\"La classe moyenne. Voil\u00e0 une construction sociale \u00e0 laquelle tout le monde se sent appartenir, mais laquelle personne ne sait d\u00e9finir. Dans une \u00e9tude du CREDOC, des chercheurs ont not\u00e9 la tendance d\u2019une personne \u00ab \u00e0 d\u00e9clarer appartenir aux classes moyennes, et cela quel que soit son niveau de revenu \u00bb.\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/dev.improof.lu\/app\/uploads\/2023\/09\/Work.jpg\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Dylan Theis\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"12 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/dev.improof.lu\/fr\/articles\/classes-moyennes-1\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dev.improof.lu\/fr\/articles\/classes-moyennes-1\/\"},\"author\":{\"name\":\"Dylan Theis\",\"@id\":\"https:\/\/dev.improof.lu\/fr\/#\/schema\/person\/7aaf2286464ae00d2447ba7811787c41\"},\"headline\":\"La classe moyenne \u2013 c\u2019est moi !\",\"datePublished\":\"2023-09-20T07:52:34+00:00\",\"dateModified\":\"2024-01-31T15:17:05+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dev.improof.lu\/fr\/articles\/classes-moyennes-1\/\"},\"wordCount\":2501,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dev.improof.lu\/fr\/#organization\"},\"image\":{\"@id\":\"https:\/\/dev.improof.lu\/fr\/articles\/classes-moyennes-1\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dev.improof.lu\/app\/uploads\/2023\/09\/Graf3.jpg\",\"articleSection\":[\"Non classifi\u00e9(e)\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dev.improof.lu\/fr\/articles\/classes-moyennes-1\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dev.improof.lu\/fr\/articles\/classes-moyennes-1\/\",\"url\":\"https:\/\/dev.improof.lu\/fr\/articles\/classes-moyennes-1\/\",\"name\":\"La classe moyenne \u2013 c\u2019est moi ! - Improof\",\"isPartOf\":{\"@id\":\"https:\/\/dev.improof.lu\/fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dev.improof.lu\/fr\/articles\/classes-moyennes-1\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dev.improof.lu\/fr\/articles\/classes-moyennes-1\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dev.improof.lu\/app\/uploads\/2023\/09\/Graf3.jpg\",\"datePublished\":\"2023-09-20T07:52:34+00:00\",\"dateModified\":\"2024-01-31T15:17:05+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/dev.improof.lu\/fr\/articles\/classes-moyennes-1\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dev.improof.lu\/fr\/articles\/classes-moyennes-1\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dev.improof.lu\/fr\/articles\/classes-moyennes-1\/#primaryimage\",\"url\":\"https:\/\/dev.improof.lu\/app\/uploads\/2023\/09\/Graf3.jpg\",\"contentUrl\":\"https:\/\/dev.improof.lu\/app\/uploads\/2023\/09\/Graf3.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dev.improof.lu\/fr\/articles\/classes-moyennes-1\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/dev.improof.lu\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La classe moyenne \u2013 c\u2019est moi !\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dev.improof.lu\/fr\/#website\",\"url\":\"https:\/\/dev.improof.lu\/fr\/\",\"name\":\"Improof\",\"description\":\"Tagline goes here\",\"publisher\":{\"@id\":\"https:\/\/dev.improof.lu\/fr\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dev.improof.lu\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/dev.improof.lu\/fr\/#organization\",\"name\":\"Improof\",\"url\":\"https:\/\/dev.improof.lu\/fr\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dev.improof.lu\/fr\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dev.improof.lu\/app\/uploads\/2022\/10\/improof-logo-svg.png\",\"contentUrl\":\"https:\/\/dev.improof.lu\/app\/uploads\/2022\/10\/improof-logo-svg.png\",\"width\":652,\"height\":209,\"caption\":\"Improof\"},\"image\":{\"@id\":\"https:\/\/dev.improof.lu\/fr\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dev.improof.lu\/fr\/#\/schema\/person\/7aaf2286464ae00d2447ba7811787c41\",\"name\":\"Dylan Theis\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dev.improof.lu\/fr\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/1991007fbb4e5a769ee7f0a6a6cc3d0c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/1991007fbb4e5a769ee7f0a6a6cc3d0c?s=96&d=mm&r=g\",\"caption\":\"Dylan Theis\"},\"url\":\"https:\/\/dev.improof.lu\/fr\/articles\/author\/dylan-theis\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La classe moyenne \u2013 c\u2019est moi ! - Improof","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dev.improof.lu\/fr\/articles\/classes-moyennes-1\/","og_locale":"fr_FR","og_type":"article","og_title":"La classe moyenne \u2013 c\u2019est moi !","og_description":"La classe moyenne. Voil\u00e0 une construction sociale \u00e0 laquelle tout le monde se sent appartenir, mais laquelle personne ne sait d\u00e9finir. Dans une \u00e9tude du CREDOC, des chercheurs ont not\u00e9 la tendance d\u2019une personne \u00ab \u00e0 d\u00e9clarer appartenir aux classes moyennes, et cela quel que soit son niveau de revenu \u00bb.","og_url":"https:\/\/dev.improof.lu\/fr\/articles\/classes-moyennes-1\/","og_site_name":"Improof","article_published_time":"2023-09-20T07:52:34+00:00","article_modified_time":"2024-01-31T15:17:05+00:00","og_image":[{"width":1920,"height":1281,"url":"https:\/\/dev.improof.lu\/app\/uploads\/2023\/09\/Work.jpg","type":"image\/jpeg"}],"author":"Dylan Theis","twitter_card":"summary_large_image","twitter_title":"La classe moyenne \u2013 c\u2019est moi !","twitter_description":"La classe moyenne. Voil\u00e0 une construction sociale \u00e0 laquelle tout le monde se sent appartenir, mais laquelle personne ne sait d\u00e9finir. Dans une \u00e9tude du CREDOC, des chercheurs ont not\u00e9 la tendance d\u2019une personne \u00ab \u00e0 d\u00e9clarer appartenir aux classes moyennes, et cela quel que soit son niveau de revenu \u00bb.","twitter_image":"https:\/\/dev.improof.lu\/app\/uploads\/2023\/09\/Work.jpg","twitter_misc":{"Written by":"Dylan Theis","Est. reading time":"12 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/dev.improof.lu\/fr\/articles\/classes-moyennes-1\/#article","isPartOf":{"@id":"https:\/\/dev.improof.lu\/fr\/articles\/classes-moyennes-1\/"},"author":{"name":"Dylan Theis","@id":"https:\/\/dev.improof.lu\/fr\/#\/schema\/person\/7aaf2286464ae00d2447ba7811787c41"},"headline":"La classe moyenne \u2013 c\u2019est moi !","datePublished":"2023-09-20T07:52:34+00:00","dateModified":"2024-01-31T15:17:05+00:00","mainEntityOfPage":{"@id":"https:\/\/dev.improof.lu\/fr\/articles\/classes-moyennes-1\/"},"wordCount":2501,"commentCount":0,"publisher":{"@id":"https:\/\/dev.improof.lu\/fr\/#organization"},"image":{"@id":"https:\/\/dev.improof.lu\/fr\/articles\/classes-moyennes-1\/#primaryimage"},"thumbnailUrl":"https:\/\/dev.improof.lu\/app\/uploads\/2023\/09\/Graf3.jpg","articleSection":["Non classifi\u00e9(e)"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dev.improof.lu\/fr\/articles\/classes-moyennes-1\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/dev.improof.lu\/fr\/articles\/classes-moyennes-1\/","url":"https:\/\/dev.improof.lu\/fr\/articles\/classes-moyennes-1\/","name":"La classe moyenne \u2013 c\u2019est moi ! - Improof","isPartOf":{"@id":"https:\/\/dev.improof.lu\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dev.improof.lu\/fr\/articles\/classes-moyennes-1\/#primaryimage"},"image":{"@id":"https:\/\/dev.improof.lu\/fr\/articles\/classes-moyennes-1\/#primaryimage"},"thumbnailUrl":"https:\/\/dev.improof.lu\/app\/uploads\/2023\/09\/Graf3.jpg","datePublished":"2023-09-20T07:52:34+00:00","dateModified":"2024-01-31T15:17:05+00:00","breadcrumb":{"@id":"https:\/\/dev.improof.lu\/fr\/articles\/classes-moyennes-1\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dev.improof.lu\/fr\/articles\/classes-moyennes-1\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dev.improof.lu\/fr\/articles\/classes-moyennes-1\/#primaryimage","url":"https:\/\/dev.improof.lu\/app\/uploads\/2023\/09\/Graf3.jpg","contentUrl":"https:\/\/dev.improof.lu\/app\/uploads\/2023\/09\/Graf3.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/dev.improof.lu\/fr\/articles\/classes-moyennes-1\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/dev.improof.lu\/fr\/"},{"@type":"ListItem","position":2,"name":"La classe moyenne \u2013 c\u2019est moi !"}]},{"@type":"WebSite","@id":"https:\/\/dev.improof.lu\/fr\/#website","url":"https:\/\/dev.improof.lu\/fr\/","name":"Improof","description":"Tagline goes here","publisher":{"@id":"https:\/\/dev.improof.lu\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dev.improof.lu\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/dev.improof.lu\/fr\/#organization","name":"Improof","url":"https:\/\/dev.improof.lu\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dev.improof.lu\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/dev.improof.lu\/app\/uploads\/2022\/10\/improof-logo-svg.png","contentUrl":"https:\/\/dev.improof.lu\/app\/uploads\/2022\/10\/improof-logo-svg.png","width":652,"height":209,"caption":"Improof"},"image":{"@id":"https:\/\/dev.improof.lu\/fr\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/dev.improof.lu\/fr\/#\/schema\/person\/7aaf2286464ae00d2447ba7811787c41","name":"Dylan Theis","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dev.improof.lu\/fr\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/1991007fbb4e5a769ee7f0a6a6cc3d0c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1991007fbb4e5a769ee7f0a6a6cc3d0c?s=96&d=mm&r=g","caption":"Dylan Theis"},"url":"https:\/\/dev.improof.lu\/fr\/articles\/author\/dylan-theis\/"}]}},"_links":{"self":[{"href":"https:\/\/dev.improof.lu\/fr\/wp-json\/wp\/v2\/posts\/1311","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.improof.lu\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dev.improof.lu\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dev.improof.lu\/fr\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/dev.improof.lu\/fr\/wp-json\/wp\/v2\/comments?post=1311"}],"version-history":[{"count":20,"href":"https:\/\/dev.improof.lu\/fr\/wp-json\/wp\/v2\/posts\/1311\/revisions"}],"predecessor-version":[{"id":1730,"href":"https:\/\/dev.improof.lu\/fr\/wp-json\/wp\/v2\/posts\/1311\/revisions\/1730"}],"wp:attachment":[{"href":"https:\/\/dev.improof.lu\/fr\/wp-json\/wp\/v2\/media?parent=1311"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dev.improof.lu\/fr\/wp-json\/wp\/v2\/categories?post=1311"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dev.improof.lu\/fr\/wp-json\/wp\/v2\/tags?post=1311"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}