{"id":2021,"date":"2024-06-11T08:24:30","date_gmt":"2024-06-11T08:24:30","guid":{"rendered":"https:\/\/dev.improof.lu\/?p=2021"},"modified":"2024-06-11T08:23:18","modified_gmt":"2024-06-11T08:23:18","slug":"regles-ue-dette","status":"publish","type":"post","link":"https:\/\/dev.improof.lu\/fr\/articles\/regles-ue-dette\/","title":{"rendered":"R\u00e8gles de l\u2019UE en mati\u00e8re de dette : une vague de coupes budg\u00e9taires d\u00e9ferle sur la zone euro"},"content":{"rendered":"<p>Apr\u00e8s des ann\u00e9es de d\u00e9bat, la Commission, le Conseil et le Parlement se sont mis d&#8217;accord sur une r\u00e9forme des r\u00e8gles dites budg\u00e9taires \u00e0 la derni\u00e8re minute avant les \u00e9lections europ\u00e9ennes. Celles-ci d\u00e9terminent le montant de la dette que les \u00c9tats membres sont autoris\u00e9s \u00e0 contracter et, par cons\u00e9quent, la mesure dans laquelle ils doivent r\u00e9duire leurs d\u00e9penses ou augmenter leurs imp\u00f4ts. En raison des r\u00e8gles actuellement en vigueur, on peut s\u2019attendre d\u2019ici 2028 \u00e0 une s\u00e9rie de plans de consolidation d\u2019une valeur de plusieurs milliards, qui ralentiront tr\u00e8s probablement l\u2019\u00e9conomie, l\u2019\u00c9tat-providence et la protection du climat.<\/p>\n<h2>Des r\u00e8gles d\u2019un autre temps<\/h2>\n<p>Les limites fix\u00e9es pour le niveau maximum de la dette nationale et de la nouvelle dette caract\u00e9risent la zone euro depuis sa cr\u00e9ation. Chaque pays souhaitant rejoindre l\u2019euro devait au moins r\u00e9duire son d\u00e9ficit \u00e0 moins de 3 % de sa production \u00e9conomique (produit int\u00e9rieur brut). Si le taux d\u2019endettement national \u00e9tait sup\u00e9rieur \u00e0 la moyenne de l\u2019UE de l\u2019\u00e9poque, soit 60 % du produit int\u00e9rieur brut, il devait au moins s\u2019approcher de cette valeur. En 1997, elles ont \u00e9t\u00e9 adopt\u00e9es dans le droit permanent europ\u00e9en sous le titre \u00ab Pacte de stabilit\u00e9 et de croissance \u00bb.<\/p>\n<p>Si les r\u00e8gles ont chang\u00e9 plusieurs fois depuis, les valeurs sont rest\u00e9es telles quelles, m\u00eame si leur r\u00e9f\u00e9rence a consid\u00e9rablement chang\u00e9 : les taux d\u2019int\u00e9r\u00eat \u00e0 long terme et les d\u00e9ficits structurels sont nettement inf\u00e9rieurs ; le taux d\u2019endettement national a augment\u00e9, mais beaucoup moins rapidement que dans d\u2019autres grandes \u00e9conomies comme les \u00c9tats-Unis, la Chine ou le Japon.<\/p>\n<p>Avant m\u00eame le d\u00e9clenchement de la pand\u00e9mie, la Commission a lanc\u00e9 une nouvelle r\u00e9forme pour corriger les erreurs de la derni\u00e8re intensification de la crise financi\u00e8re et \u00e9conomique, qui avait conduit \u00e0 des bouleversements sociaux et \u00e0 un effondrement sans pr\u00e9c\u00e9dent des investissements publics dans certains pays. Afin d\u2019amortir le ralentissement \u00e9conomique provoqu\u00e9 par la pand\u00e9mie, les r\u00e8gles ont \u00e9t\u00e9 suspendues. Les mesures de lutte contre la pand\u00e9mie ont fait monter en fl\u00e8che les d\u00e9ficits et les taux d\u2019endettement publics et, avec eux, la pression en faveur de r\u00e9formes.<\/p>\n<p>Les syndicats europ\u00e9ens, les ONG et certains \u00e9conomistes ont mis en garde contre les cons\u00e9quences d&#8217;un assouplissement insuffisant des exigences, voire du r\u00e9tablissement des anciennes r\u00e8gles : les r\u00e9ductions des retraites, les suppressions d&#8217;emplois, les r\u00e9ductions des services de sant\u00e9, les augmentations massives d&#8217;imp\u00f4ts, l&#8217;effondrement des investissements, y compris dans la protection du climat, etc., que la population grecque a d\u00fb subir au d\u00e9but des ann\u00e9es 2010, pourraient conduire \u00e0 un nouvel effondrement \u00e9conomique, un ch\u00f4mage de masse et une mis\u00e8re sociale ; et avec tout \u00e7a \u00e0 un taux d&#8217;endettement national encore plus \u00e9lev\u00e9.<\/p>\n<h2>Plans budg\u00e9taires et probl\u00e8mes \u00e0 moyen terme<\/h2>\n<p>Les avertissements ont eu un certain effet : dans les r\u00e8gles budg\u00e9taires qui ont \u00e9t\u00e9 adopt\u00e9es, les exigences r\u00e9cemment irr\u00e9alistes et radicales en mati\u00e8re de r\u00e9duction de la dette ont \u00e9t\u00e9 supprim\u00e9es. \u00c0 moyen terme, cela pourrait suffire \u00e0 stabiliser le taux d\u2019endettement national ou \u00e0 le rapprocher des 60 % du produit int\u00e9rieur brut. Cela profiterait particuli\u00e8rement aux g\u00e9n\u00e9rations futures, car cela permettrait d\u2019\u00e9viter des retards majeurs dans les investissements publics dans la protection du climat ou des r\u00e9ductions dans les plans d\u2019expansion de l\u2019\u00e9ducation et de la garde d\u2019enfants.<\/p>\n<p>Au lieu d&#8217;objectifs budg\u00e9taires concrets recalcul\u00e9s chaque ann\u00e9e, et donc par cons\u00e9quent fluctuants, ce sont d\u00e9sormais les plans budg\u00e9taires et structurels, valables en g\u00e9n\u00e9ral pour quatre ans, qui devraient devenir d\u00e9cisifs. Ils se concentrent sur des limites maximales pour la croissance annuelle des d\u00e9penses publiques, dont le respect est ensuite surveill\u00e9 en permanence. Si un ensemble de r\u00e9formes et d\u2019investissements est mis en place, les \u00c9tats membres disposeront de trois ann\u00e9es suppl\u00e9mentaires pour atteindre leurs objectifs budg\u00e9taires.<\/p>\n<p><strong>Mais il y a \u00e0 pr\u00e9sent trois probl\u00e8mes principaux :<\/strong><\/p>\n<p>1. En p\u00e9riode de crise, le secteur public a besoin de plus de latitude pour pouvoir prendre des contre-mesures. Les r\u00e8gles budg\u00e9taires ne pr\u00e9voient que le m\u00e9canisme pr\u00e9alable \u00e0 leur suspension, mais rien pour agir conform\u00e9ment aux r\u00e8gles dans le contexte de la r\u00e9cession \u00e9conomique actuelle, par exemple contre la hausse du ch\u00f4mage.<\/p>\n<p>2. La Commission europ\u00e9enne dispose d\u2019une trop grande marge de man\u0153uvre lorsqu\u2019il s\u2019agit d\u2019\u00e9valuer les programmes de r\u00e9forme et d\u2019investissement. Il existe un risque qu&#8217;elle exige \u00e0 nouveau des r\u00e9ductions des retraites, des restrictions du droit du travail ou quelque chose de similaire afin d&#8217;approuver un d\u00e9lai plus long et donc une trajectoire de r\u00e9duction plus douce. Les \u00c9tats membres n\u2019auraient alors plus que le choix proverbial entre la peste et le chol\u00e9ra. Cependant, il est \u00e9galement possible que des exigences raisonnables soient impos\u00e9es, telles qu&#8217;un plus grand d\u00e9veloppement de l&#8217;accueil des enfants, davantage de possibilit\u00e9s de formation et de perfectionnement, une acc\u00e9l\u00e9ration de la protection du climat, etc. Le r\u00e9sultat des \u00e9lections europ\u00e9ennes et la composition de la nouvelle Commission joueront ici un r\u00f4le important.<\/p>\n<p>3. Le nouveau r\u00e8glement donne \u00e0 la Commission une grande libert\u00e9 pour choisir la m\u00e9thode avec laquelle elle \u00e9value si le taux d&#8217;endettement national diminue suffisamment rapidement. La m\u00e9thode \u00e0 pr\u00e9sent choisie conduit \u00e0 d&#8217;autres probl\u00e8mes.<\/p>\n<h2>Qu\u2019est-ce que l\u2019avenir nous r\u00e9serve\u00a0?<\/h2>\n<p>Ce n&#8217;est qu&#8217;apr\u00e8s l\u2019accord du trilogue que <a href=\"https:\/\/economy-finance.ec.europa.eu\/publications\/debt-sustainability-monitor-2023_en\" target=\"_blank\" rel=\"noopener\"><span style=\"text-decoration: underline;\"><em>la Commission a fait savoir publiquement<\/em><\/span><\/a> comment ce que l\u2019on appelle l\u2019analyse de la fiabilit\u00e9 de la dette sera effectu\u00e9e. Le r\u00e9sultat donne \u00e0 r\u00e9fl\u00e9chir : la Commission europ\u00e9enne ne publiera les chiffres exacts, et ce, par mesure de pr\u00e9caution, que peu de temps apr\u00e8s les \u00e9lections europ\u00e9ennes ; sur la base de ses nouvelles pr\u00e9visions, l\u2019Institut Bruegel a calcul\u00e9 de premi\u00e8res estimations (version pr\u00e9liminaire <a href=\"https:\/\/www.jvi.org\/fileadmin\/jvi_files\/News\/2024\/24WR02_Feb21\/2024-02-21_Greening_EU_fiscal_rules.pdf\" target=\"_blank\" rel=\"noopener\"><span style=\"text-decoration: underline;\"><em>ici<\/em><\/span><\/a>) :<\/p>\n<p>La zone euro est menac\u00e9e de nouvelles r\u00e9ductions successives des d\u00e9penses jusqu&#8217;en 2028, qui atteindront finalement plus de 360 \u200b\u200bmilliards d&#8217;euros (environ 2,1 % de la production \u00e9conomique), avec moins de ressources disponibles chaque ann\u00e9e, si on les mesure comme un \u00e9cart par rapport \u00e0 un sc\u00e9nario sans consolidation. Sans amortissement par des hausses d\u2019imp\u00f4ts, cela ne sera pas possible sans des <a href=\"https:\/\/www.awblog.at\/Allgemein\/weniger-staatsausgaben-abbau-des-sozialstaats-und-vertiefung-v\" target=\"_blank\" rel=\"noopener\"><span style=\"text-decoration: underline;\"><em>r\u00e9ductions significatives dans les domaines de l\u2019\u00e9ducation, de la s\u00e9curit\u00e9 sociale<\/em><\/span><\/a> et de la <a href=\"https:\/\/www.awblog.at\/Europa\/mehr-klimainvestitionen\" target=\"_blank\" rel=\"noopener\"><span style=\"text-decoration: underline;\"><em>protection du climat<\/em><\/span><\/a>.<\/p>\n<p>L&#8217;Italie est particuli\u00e8rement touch\u00e9e\u00a0: le gouvernement devrait donc consolider au moins 100 milliards d&#8217;euros au cours des quatre prochaines ann\u00e9es, et ce, avec des cons\u00e9quences \u00e9conomiques et sociales dramatiques qui mettraient m\u00eame en danger la r\u00e9duction de la dette.<\/p>\n<h2>Des hypoth\u00e8ses absurdes viennent aggraver les choses<\/h2>\n<p>Si l\u2019on regarde derri\u00e8re les coulisses de la m\u00e9thode, l\u2019absurdit\u00e9 de l\u2019exercice devient \u00e9vidente : il ne suffit donc pas de r\u00e9duire le taux d\u2019endettement national ; il faut \u00e9galement veiller \u00e0 ce que le taux continue de baisser dans les dix ans qui suivront la fin du plan, m\u00eame si les r\u00e8gles budg\u00e9taires sont \u00e0 nouveau enfreintes \u00e0 l&#8217;avenir. Concr\u00e8tement, la Commission s&#8217;attend \u00e0 ce que l&#8217;augmentation \u00e0 long terme des d\u00e9penses publiques li\u00e9es \u00e0 la d\u00e9mographie ne soit pas compens\u00e9e dans les prochains plans budg\u00e9taires et structurels, mais qu&#8217;elle soit financ\u00e9e exclusivement par une dette plus \u00e9lev\u00e9e, et ce m\u00eame si les r\u00e8gles budg\u00e9taires excluent pr\u00e9cis\u00e9ment ce cas de figure. Et pour \u00e9viter cette augmentation de la dette, la consolidation doit \u00eatre encore plus stricte dans le plan actuel.<\/p>\n<p>Il serait plus \u00e9vident de supposer que les r\u00e8gles auxquelles chacun devrait adh\u00e9rer sont effectivement respect\u00e9es aujourd\u2019hui et \u00e0 l\u2019avenir. Le simple fait de passer \u00e0 cette derni\u00e8re hypoth\u00e8se apporterait des milliards d\u2019euros de flexibilit\u00e9 budg\u00e9taire. Si l\u2019on applique les objectifs de Bruegel ci-dessus, il appara\u00eet clairement que chaque pays doit davantage consolider ses finances publiques que la marge de s\u00e9curit\u00e9 requise par les 3 pour cent n\u00e9goci\u00e9s par le Conseil et le Parlement (plus pr\u00e9cis\u00e9ment 1,5 pour cent du produit int\u00e9rieur brut). Dans les pays o\u00f9 l\u2019augmentation des co\u00fbts du vieillissement est particuli\u00e8rement \u00e9lev\u00e9e, comme l\u2019Espagne ou le Portugal, les objectifs budg\u00e9taires \u00e0 moyen terme sont d\u00e9sormais implicitement encore plus stricts qu\u2019avec les anciennes r\u00e8gles. Cela est particuli\u00e8rement dangereux pour le financement de l\u2019\u00c9tat-providence en Europe car, par exemple, une augmentation sous-estim\u00e9e du nombre de personnes employ\u00e9es conduit \u00e0 se concentrer davantage sur la r\u00e9duction des d\u00e9penses en mati\u00e8re de retraite, de sant\u00e9 et de soins. La situation est similaire avec des taux d\u2019int\u00e9r\u00eat surestim\u00e9s.<\/p>\n<h2>Trop peu de marge pour des investissements futurs et un progr\u00e8s social<\/h2>\n<p>La vague de consolidation imminente pourrait retarder de plusieurs ann\u00e9es la sortie de la production et de la consommation bas\u00e9es sur les \u00e9nergies fossiles ou ralentir la poursuite du progr\u00e8s social, et ce m\u00eame si les soci\u00e9t\u00e9s europ\u00e9ennes ont d\u00e9j\u00e0 connu <a href=\"https:\/\/www.awblog.at\/Arbeit\/ak-wohlstandsbericht-2023\" target=\"_blank\" rel=\"noopener\"><span style=\"text-decoration: underline;\"><em>cinq ann\u00e9es de r\u00e9gression<\/em><\/span><\/a> apr\u00e8s la pand\u00e9mie et la crise inflationniste. D\u2019autant plus qu\u2019apr\u00e8s l\u2019expiration <a href=\"https:\/\/www.awblog.at\/Europa\/was-kann-der-eu-krisenfonds-rrf\" target=\"_blank\" rel=\"noopener\"><span style=\"text-decoration: underline;\"><em>des fonds suppl\u00e9mentaires de l\u2019UE destin\u00e9s \u00e0 stabiliser<\/em><\/span><\/a> les investissements en 2026, m\u00eame sans r\u00e8gles, la question de savoir comment maintenir le niveau actuel reste ouverte. \u00c9tant donn\u00e9 que la r\u00e8gle des d\u00e9penses s\u2019applique \u00e9galement \u00e0 la croissance des investissements publics au lieu de les exclure, comme l\u2019exigerait <a href=\"https:\/\/library.fes.de\/pdf-files\/wiso\/12078.pdf\" target=\"_blank\" rel=\"noopener\"><span style=\"text-decoration: underline;\"><em>la r\u00e8gle d\u2019or de l\u2019investissement<\/em><\/span><\/a>, souvent r\u00e9clam\u00e9e, le risque que les projets d\u2019investissement soient \u00e9tir\u00e9s, report\u00e9s, voire annul\u00e9s, est particuli\u00e8rement \u00e9lev\u00e9.<\/p>\n<p>Mais, dans la phase finale des n\u00e9gociations sur les r\u00e8gles budg\u00e9taires, sous la pression du Parlement europ\u00e9en, il y a eu une tout de m\u00eame am\u00e9lioration dans la mesure o\u00f9 les investissements cofinanc\u00e9s ne sont pas limit\u00e9s par la r\u00e8gle des d\u00e9penses. L&#8217;ampleur de cette exception d\u00e9pend notamment des prochaines \u00e9lections au Parlement europ\u00e9en, car elle ne rec\u00e8le qu&#8217;un potentiel d&#8217;am\u00e9lioration politique significatif \u00e0 moyen terme : d&#8217;une part, dans la conception du cadre financier de l&#8217;UE pour 2028-2034 et, d&#8217;autre part, dans la question de savoir si <a href=\"https:\/\/wiiw.ac.at\/rrf-2-0-ein-permanenter-eu-investitionsfonds-im-kontext-von-energiekrise-klimawandel-und-eu-fiskalregeln-dlp-6413.pdf\" target=\"_blank\" rel=\"noopener\"><span style=\"text-decoration: underline;\"><em>les fonds suppl\u00e9mentaires de l&#8217;UE<\/em><\/span><\/a> seront \u00e0 nouveau utilis\u00e9s. La question de savoir si ce potentiel sera exploit\u00e9 d\u00e9terminera en grande partie si l\u2019UE sera en mesure de r\u00e9pondre aux besoins \u00e9lev\u00e9s et urgents en investissements publics pour atteindre ses objectifs climatiques au cours de la prochaine d\u00e9cennie.<\/p>\n<p>Et qu\u2019en est-il de la dimension sociale de la r\u00e9forme ? Les objectifs sociaux seront davantage pris en compte \u00e0 l&#8217;avenir dans le cadre de la r\u00e9vision du budget de la Commission europ\u00e9enne. D\u2019un autre c\u00f4t\u00e9, nous sommes confront\u00e9s \u00e0 une vague de consolidation. M\u00eame si ces mesures seront assouplies et prolong\u00e9es au fil du temps par rapport aux anciennes r\u00e8gles, les r\u00e9ductions des d\u00e9penses sociales restent in\u00e9vitables : les d\u00e9penses sociales, d\u2019\u00e9ducation et de sant\u00e9 constituent les postes budg\u00e9taires les plus importants dans tous les \u00c9tats membres, de sorte que la consolidation leur co\u00fbte presque in\u00e9vitablement un lourd tribut, du moins si elle n\u2019est pas \u00e9galement appliqu\u00e9e du c\u00f4t\u00e9 des recettes.<\/p>\n<h2>Conclusions<\/h2>\n<p>La r\u00e9forme des r\u00e8gles budg\u00e9taires a \u00e9t\u00e9 une occasion manqu\u00e9e d\u2019ancrer une politique \u00e9conomique \u00e9quilibr\u00e9e et ax\u00e9e sur la prosp\u00e9rit\u00e9 au niveau europ\u00e9en. Elle reste unilat\u00e9ralement ax\u00e9e sur les restrictions impos\u00e9es aux politiques budg\u00e9taires des \u00c9tats membres, m\u00eame si, compte tenu de la diversit\u00e9 des d\u00e9fis, des efforts auraient d\u00fb \u00eatre faits pour rendre l&#8217;Europe mieux capable d&#8217;agir.<\/p>\n<p>Cela a abouti \u00e0 une obligation de consolidation moindre ; mais ce n&#8217;est que dans la pratique que l&#8217;on se rendra compte de l&#8217;ampleur r\u00e9elle de la marge de man\u0153uvre budg\u00e9taire relativement plus importante, car des questions essentielles telles que la mani\u00e8re dont la Commission traitera les plans d&#8217;investissement et de r\u00e9forme sont encore en suspens. Il serait tr\u00e8s probl\u00e9matique de combiner des mesures de r\u00e9forme au d\u00e9triment des salari\u00e9s, comme cela a \u00e9t\u00e9 le cas en Gr\u00e8ce ou au Portugal dans le cadre des n\u00e9gociations dites de la Tro\u00efka.<\/p>\n<p>Des fonds europ\u00e9ens suppl\u00e9mentaires sont \u00e0 nouveau n\u00e9cessaires, car sans soutien, la vague de consolidation se fera au d\u00e9triment d&#8217;autres objectifs importants, tels que l&#8217;\u00e9galisation sociale et la protection du climat.<\/p>\n<p><strong>Cet article a d\u2019abord \u00e9t\u00e9 publi\u00e9 par <a href=\"https:\/\/www.awblog.at\/Europa\/EU-Schuldenregeln-Kuerzungswelle\" target=\"_blank\" rel=\"noopener\"><span style=\"text-decoration: underline;\"><em>A&amp;W Blog<\/em><\/span><\/a><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Apr\u00e8s des ann\u00e9es de d\u00e9bat, la Commission, le Conseil et le Parlement se sont mis d&#8217;accord sur une r\u00e9forme des r\u00e8gles dites budg\u00e9taires \u00e0 la derni\u00e8re minute avant les \u00e9lections europ\u00e9ennes. Celles-ci d\u00e9terminent le montant de la dette que les \u00c9tats membres sont autoris\u00e9s \u00e0 contracter et, par cons\u00e9quent, la mesure dans laquelle ils doivent r\u00e9duire leurs d\u00e9penses ou augmenter leurs imp\u00f4ts. En raison des r\u00e8gles actuellement en vigueur, on peut s\u2019attendre d\u2019ici 2028 \u00e0 une s\u00e9rie de plans de consolidation d\u2019une valeur de plusieurs milliards, qui ralentiront tr\u00e8s probablement l\u2019\u00e9conomie, l\u2019\u00c9tat-providence et la protection du climat.<\/p>\n","protected":false},"author":11,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[2],"tags":[],"class_list":["post-2021","post","type-post","status-publish","format-standard","hentry","category-non-classifiee","topic-politique-budgetaire","format-text-fr"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>R\u00e8gles de l\u2019UE en mati\u00e8re de dette : une vague de coupes budg\u00e9taires d\u00e9ferle sur la zone euro - Improof<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dev.improof.lu\/fr\/articles\/regles-ue-dette\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"R\u00e8gles de l\u2019UE en mati\u00e8re de dette : une vague de coupes budg\u00e9taires d\u00e9ferle sur la zone euro\" \/>\n<meta property=\"og:description\" content=\"Apr\u00e8s des ann\u00e9es de d\u00e9bat, la Commission, le Conseil et le Parlement se sont mis d&#039;accord sur une r\u00e9forme des r\u00e8gles dites budg\u00e9taires \u00e0 la derni\u00e8re minute avant les \u00e9lections europ\u00e9ennes. Celles-ci d\u00e9terminent le montant de la dette que les \u00c9tats membres sont autoris\u00e9s \u00e0 contracter et, par cons\u00e9quent, la mesure dans laquelle ils doivent r\u00e9duire leurs d\u00e9penses ou augmenter leurs imp\u00f4ts. En raison des r\u00e8gles actuellement en vigueur, on peut s\u2019attendre d\u2019ici 2028 \u00e0 une s\u00e9rie de plans de consolidation d\u2019une valeur de plusieurs milliards, qui ralentiront tr\u00e8s probablement l\u2019\u00e9conomie, l\u2019\u00c9tat-providence et la protection du climat.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dev.improof.lu\/fr\/articles\/regles-ue-dette\/\" \/>\n<meta property=\"og:site_name\" content=\"Improof\" \/>\n<meta property=\"article:published_time\" content=\"2024-06-11T08:24:30+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-06-11T08:23:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dev.improof.lu\/app\/uploads\/2024\/06\/bild2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1076\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Nermin Plavsic\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"R\u00e8gles de l\u2019UE en mati\u00e8re de dette : une vague de coupes budg\u00e9taires d\u00e9ferle sur la zone euro\" \/>\n<meta name=\"twitter:description\" content=\"Apr\u00e8s des ann\u00e9es de d\u00e9bat, la Commission, le Conseil et le Parlement se sont mis d&#039;accord sur une r\u00e9forme des r\u00e8gles dites budg\u00e9taires \u00e0 la derni\u00e8re minute avant les \u00e9lections europ\u00e9ennes. Celles-ci d\u00e9terminent le montant de la dette que les \u00c9tats membres sont autoris\u00e9s \u00e0 contracter et, par cons\u00e9quent, la mesure dans laquelle ils doivent r\u00e9duire leurs d\u00e9penses ou augmenter leurs imp\u00f4ts. En raison des r\u00e8gles actuellement en vigueur, on peut s\u2019attendre d\u2019ici 2028 \u00e0 une s\u00e9rie de plans de consolidation d\u2019une valeur de plusieurs milliards, qui ralentiront tr\u00e8s probablement l\u2019\u00e9conomie, l\u2019\u00c9tat-providence et la protection du climat.\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/dev.improof.lu\/app\/uploads\/2024\/06\/bild2.jpg\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Nermin Plavsic\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"11 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/dev.improof.lu\/fr\/articles\/regles-ue-dette\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dev.improof.lu\/fr\/articles\/regles-ue-dette\/\"},\"author\":{\"name\":\"Nermin Plavsic\",\"@id\":\"https:\/\/dev.improof.lu\/fr\/#\/schema\/person\/8b7e0720f9ab34bd8b12af9dbf2592a6\"},\"headline\":\"R\u00e8gles de l\u2019UE en mati\u00e8re de dette : une vague de coupes budg\u00e9taires d\u00e9ferle sur la zone euro\",\"datePublished\":\"2024-06-11T08:24:30+00:00\",\"dateModified\":\"2024-06-11T08:23:18+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dev.improof.lu\/fr\/articles\/regles-ue-dette\/\"},\"wordCount\":2262,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dev.improof.lu\/fr\/#organization\"},\"articleSection\":[\"Non classifi\u00e9(e)\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dev.improof.lu\/fr\/articles\/regles-ue-dette\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dev.improof.lu\/fr\/articles\/regles-ue-dette\/\",\"url\":\"https:\/\/dev.improof.lu\/fr\/articles\/regles-ue-dette\/\",\"name\":\"R\u00e8gles de l\u2019UE en mati\u00e8re de dette : une vague de coupes budg\u00e9taires d\u00e9ferle sur la zone euro - Improof\",\"isPartOf\":{\"@id\":\"https:\/\/dev.improof.lu\/fr\/#website\"},\"datePublished\":\"2024-06-11T08:24:30+00:00\",\"dateModified\":\"2024-06-11T08:23:18+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/dev.improof.lu\/fr\/articles\/regles-ue-dette\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dev.improof.lu\/fr\/articles\/regles-ue-dette\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dev.improof.lu\/fr\/articles\/regles-ue-dette\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/dev.improof.lu\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"R\u00e8gles de l\u2019UE en mati\u00e8re de dette : une vague de coupes budg\u00e9taires d\u00e9ferle sur la zone euro\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dev.improof.lu\/fr\/#website\",\"url\":\"https:\/\/dev.improof.lu\/fr\/\",\"name\":\"Improof\",\"description\":\"Tagline goes here\",\"publisher\":{\"@id\":\"https:\/\/dev.improof.lu\/fr\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dev.improof.lu\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/dev.improof.lu\/fr\/#organization\",\"name\":\"Improof\",\"url\":\"https:\/\/dev.improof.lu\/fr\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dev.improof.lu\/fr\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dev.improof.lu\/app\/uploads\/2022\/10\/improof-logo-svg.png\",\"contentUrl\":\"https:\/\/dev.improof.lu\/app\/uploads\/2022\/10\/improof-logo-svg.png\",\"width\":652,\"height\":209,\"caption\":\"Improof\"},\"image\":{\"@id\":\"https:\/\/dev.improof.lu\/fr\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dev.improof.lu\/fr\/#\/schema\/person\/8b7e0720f9ab34bd8b12af9dbf2592a6\",\"name\":\"Nermin Plavsic\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dev.improof.lu\/fr\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/1b010c13286dbffe130fb77dd68cc999?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/1b010c13286dbffe130fb77dd68cc999?s=96&d=mm&r=g\",\"caption\":\"Nermin Plavsic\"},\"url\":\"https:\/\/dev.improof.lu\/fr\/articles\/author\/nermin-plavsic\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"R\u00e8gles de l\u2019UE en mati\u00e8re de dette : une vague de coupes budg\u00e9taires d\u00e9ferle sur la zone euro - Improof","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dev.improof.lu\/fr\/articles\/regles-ue-dette\/","og_locale":"fr_FR","og_type":"article","og_title":"R\u00e8gles de l\u2019UE en mati\u00e8re de dette : une vague de coupes budg\u00e9taires d\u00e9ferle sur la zone euro","og_description":"Apr\u00e8s des ann\u00e9es de d\u00e9bat, la Commission, le Conseil et le Parlement se sont mis d'accord sur une r\u00e9forme des r\u00e8gles dites budg\u00e9taires \u00e0 la derni\u00e8re minute avant les \u00e9lections europ\u00e9ennes. Celles-ci d\u00e9terminent le montant de la dette que les \u00c9tats membres sont autoris\u00e9s \u00e0 contracter et, par cons\u00e9quent, la mesure dans laquelle ils doivent r\u00e9duire leurs d\u00e9penses ou augmenter leurs imp\u00f4ts. En raison des r\u00e8gles actuellement en vigueur, on peut s\u2019attendre d\u2019ici 2028 \u00e0 une s\u00e9rie de plans de consolidation d\u2019une valeur de plusieurs milliards, qui ralentiront tr\u00e8s probablement l\u2019\u00e9conomie, l\u2019\u00c9tat-providence et la protection du climat.","og_url":"https:\/\/dev.improof.lu\/fr\/articles\/regles-ue-dette\/","og_site_name":"Improof","article_published_time":"2024-06-11T08:24:30+00:00","article_modified_time":"2024-06-11T08:23:18+00:00","og_image":[{"width":1920,"height":1076,"url":"https:\/\/dev.improof.lu\/app\/uploads\/2024\/06\/bild2.jpg","type":"image\/jpeg"}],"author":"Nermin Plavsic","twitter_card":"summary_large_image","twitter_title":"R\u00e8gles de l\u2019UE en mati\u00e8re de dette : une vague de coupes budg\u00e9taires d\u00e9ferle sur la zone euro","twitter_description":"Apr\u00e8s des ann\u00e9es de d\u00e9bat, la Commission, le Conseil et le Parlement se sont mis d'accord sur une r\u00e9forme des r\u00e8gles dites budg\u00e9taires \u00e0 la derni\u00e8re minute avant les \u00e9lections europ\u00e9ennes. Celles-ci d\u00e9terminent le montant de la dette que les \u00c9tats membres sont autoris\u00e9s \u00e0 contracter et, par cons\u00e9quent, la mesure dans laquelle ils doivent r\u00e9duire leurs d\u00e9penses ou augmenter leurs imp\u00f4ts. En raison des r\u00e8gles actuellement en vigueur, on peut s\u2019attendre d\u2019ici 2028 \u00e0 une s\u00e9rie de plans de consolidation d\u2019une valeur de plusieurs milliards, qui ralentiront tr\u00e8s probablement l\u2019\u00e9conomie, l\u2019\u00c9tat-providence et la protection du climat.","twitter_image":"https:\/\/dev.improof.lu\/app\/uploads\/2024\/06\/bild2.jpg","twitter_misc":{"Written by":"Nermin Plavsic","Est. reading time":"11 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/dev.improof.lu\/fr\/articles\/regles-ue-dette\/#article","isPartOf":{"@id":"https:\/\/dev.improof.lu\/fr\/articles\/regles-ue-dette\/"},"author":{"name":"Nermin Plavsic","@id":"https:\/\/dev.improof.lu\/fr\/#\/schema\/person\/8b7e0720f9ab34bd8b12af9dbf2592a6"},"headline":"R\u00e8gles de l\u2019UE en mati\u00e8re de dette : une vague de coupes budg\u00e9taires d\u00e9ferle sur la zone euro","datePublished":"2024-06-11T08:24:30+00:00","dateModified":"2024-06-11T08:23:18+00:00","mainEntityOfPage":{"@id":"https:\/\/dev.improof.lu\/fr\/articles\/regles-ue-dette\/"},"wordCount":2262,"commentCount":0,"publisher":{"@id":"https:\/\/dev.improof.lu\/fr\/#organization"},"articleSection":["Non classifi\u00e9(e)"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dev.improof.lu\/fr\/articles\/regles-ue-dette\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/dev.improof.lu\/fr\/articles\/regles-ue-dette\/","url":"https:\/\/dev.improof.lu\/fr\/articles\/regles-ue-dette\/","name":"R\u00e8gles de l\u2019UE en mati\u00e8re de dette : une vague de coupes budg\u00e9taires d\u00e9ferle sur la zone euro - Improof","isPartOf":{"@id":"https:\/\/dev.improof.lu\/fr\/#website"},"datePublished":"2024-06-11T08:24:30+00:00","dateModified":"2024-06-11T08:23:18+00:00","breadcrumb":{"@id":"https:\/\/dev.improof.lu\/fr\/articles\/regles-ue-dette\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dev.improof.lu\/fr\/articles\/regles-ue-dette\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/dev.improof.lu\/fr\/articles\/regles-ue-dette\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/dev.improof.lu\/fr\/"},{"@type":"ListItem","position":2,"name":"R\u00e8gles de l\u2019UE en mati\u00e8re de dette : une vague de coupes budg\u00e9taires d\u00e9ferle sur la zone euro"}]},{"@type":"WebSite","@id":"https:\/\/dev.improof.lu\/fr\/#website","url":"https:\/\/dev.improof.lu\/fr\/","name":"Improof","description":"Tagline goes here","publisher":{"@id":"https:\/\/dev.improof.lu\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dev.improof.lu\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/dev.improof.lu\/fr\/#organization","name":"Improof","url":"https:\/\/dev.improof.lu\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dev.improof.lu\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/dev.improof.lu\/app\/uploads\/2022\/10\/improof-logo-svg.png","contentUrl":"https:\/\/dev.improof.lu\/app\/uploads\/2022\/10\/improof-logo-svg.png","width":652,"height":209,"caption":"Improof"},"image":{"@id":"https:\/\/dev.improof.lu\/fr\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/dev.improof.lu\/fr\/#\/schema\/person\/8b7e0720f9ab34bd8b12af9dbf2592a6","name":"Nermin Plavsic","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dev.improof.lu\/fr\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/1b010c13286dbffe130fb77dd68cc999?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1b010c13286dbffe130fb77dd68cc999?s=96&d=mm&r=g","caption":"Nermin Plavsic"},"url":"https:\/\/dev.improof.lu\/fr\/articles\/author\/nermin-plavsic\/"}]}},"_links":{"self":[{"href":"https:\/\/dev.improof.lu\/fr\/wp-json\/wp\/v2\/posts\/2021","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.improof.lu\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dev.improof.lu\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dev.improof.lu\/fr\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/dev.improof.lu\/fr\/wp-json\/wp\/v2\/comments?post=2021"}],"version-history":[{"count":5,"href":"https:\/\/dev.improof.lu\/fr\/wp-json\/wp\/v2\/posts\/2021\/revisions"}],"predecessor-version":[{"id":2026,"href":"https:\/\/dev.improof.lu\/fr\/wp-json\/wp\/v2\/posts\/2021\/revisions\/2026"}],"wp:attachment":[{"href":"https:\/\/dev.improof.lu\/fr\/wp-json\/wp\/v2\/media?parent=2021"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dev.improof.lu\/fr\/wp-json\/wp\/v2\/categories?post=2021"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dev.improof.lu\/fr\/wp-json\/wp\/v2\/tags?post=2021"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}